{"id":10024,"date":"2024-08-30T15:00:09","date_gmt":"2024-08-30T13:00:09","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=10024"},"modified":"2024-08-30T15:00:09","modified_gmt":"2024-08-30T13:00:09","slug":"byd-tesla-motor-hidrogeno","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/byd-tesla-motor-hidrogeno\/10024\/","title":{"rendered":"Ni BYD ni Tesla, pero tampoco un motor de hidr\u00f3geno: esta marca acaba de revolucionar el transporte con su prototipo"},"content":{"rendered":"<p>Producto de la norma establecida por la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/union-europea-reactores-nucleares\/3201\/\">Uni\u00f3n Europea<\/a> que dice tajantemente que estar\u00e1 prohibido comerciar coches contaminantes a partir del 2035, los fabricantes est\u00e1n en la b\u00fasqueda de un motor que cumpla con este requisito. Aqu\u00ed te traemos uno que seguramente revolucionara la industria automotriz.<\/p>\n<h2>Este motor usa un combustible no contaminante: no ha sido fabricado por Tesla ni BYD<\/h2>\n<p>Estamos acostumbrados a que estas dos emblem\u00e1ticas marcas de veh\u00edculos sean las que nos sorprendan con sus innovaciones, sobre todo en coches h\u00edbridos que usan la electricidad como combustible. Sin embargo, <strong>Xiaomi ha decidido no quedarse atr\u00e1s<\/strong> y tambi\u00e9n ha presentado su motor.<\/p>\n<p>El nombre de esta m\u00e1quina es m\u00e1s que curioso: V8. Que es igual al de los motores de combusti\u00f3n interna, aunque nada tiene que ver con estos. El V8 de Xiaomi es el\u00e9ctrico y que, seg\u00fan el fabricante, ser\u00e1 m\u00e1s potente que sus competidores y tiene una mayor eficiencia por lo que es una mejora para el SU7.<\/p>\n<h2>Las caracter\u00edsticas de esta m\u00e1quina desarrollada por Xiaomi<\/h2>\n<p>Esta maquinaria <strong>impresiona por su potencia de 578 CV<\/strong> lo que le permite desarrollar un par m\u00e1ximo motriz de 635 Nm. Se puede combinar con la m\u00e1quina delantera para que act\u00fae como una de mayor potencia que dejar\u00eda al Tesla Model S Plaid o al Porsche Taycan Turbo GT muy atr\u00e1s en t\u00e9rminos de prestaciones.<\/p>\n<p>Con respecto a su aceleraci\u00f3n, no tenemos cifras oficiales, pero informaci\u00f3n filtrada dice que puede llegar de 0 a 100 kil\u00f3metros por hora en unos dos segundos. Su velocidad crucero m\u00e1xima es de v\u00e9rtigo puesto que alcanza los 300 kil\u00f3metros por hora en carretera recta lo que es impresionante.<\/p>\n<p><strong>Entre las claves para estos atributos est\u00e1 su capacidad de revoluciones<\/strong>, ya que llega a las 27.000 rpm lo que es un n\u00famero incre\u00edble. Esto si tomamos en cuenta que el Porsche Taycan Turbo \u201capenas\u201d llega a las 16.000 rpm y el Tesla Model S Paid alcanza las 21.000 rpm.<\/p>\n<p>Una de las curiosidades de este motor es que est\u00e1 constituido de muy pocas piezas, lo cual sumado al material de que est\u00e1 hecho, es muy ligero por lo que el coche que lo lleva tambi\u00e9n tendr\u00e1 una carrocer\u00eda liviana. Adicionalmente, tiene un tama\u00f1o muy compacto por lo que el espacio que lo aloja es muy bajo.<\/p>\n<p>Por otro lado, el V8 tiene 155 solicitudes de patentes por ser de un dise\u00f1o propio y diferente, tanto por la m\u00e1quina en s\u00ed como por los sistemas asociados. De estas patentes han sido aceptadas 60. Se espera que antes de finalizar este a\u00f1o, sean aprobadas las 95 restantes.<\/p>\n<h2>Rendimiento y autonom\u00eda de esa maravilla tecnol\u00f3gica<\/h2>\n<p>Lo anterior no es lo \u00fanico por lo que el V8 ha causado sensaci\u00f3n entre los expertos. Ya que este motor posee una <strong>gran eficiencia del 98,11 %<\/strong>, es decir, que las p\u00e9rdidas se ubican en menos del 2 %. Tambi\u00e9n posee una alta densidad energ\u00e9tica que se ubica en 10,14 kW\/kg que lo hace muy rendidor.<\/p>\n<p>Incorpora una bater\u00eda LFP cuya arquitectura utilizada es del tipo CTB, o cell\u2013to\u2013body. Un tipo de elemento que integra las celdas en el chasis del coche. Esta bater\u00eda viene en dos versiones de capacidades: 73,6 y 101 kWh. Esta \u00faltima, brindar\u00e1 una autonom\u00eda m\u00e1xima de 800 kil\u00f3metros de acuerdo al ciclo CLTC.<\/p>\n<p>Se espera el lanzamiento de la nueva versi\u00f3n del SU7, equipada con este motor V8, sea efectiva para principios o mediados del 2025. Su valor estimado depender\u00e1 de su versi\u00f3n comenzando con los 27.500 euros. El modelo de mayor potencia costar\u00e1 alrededor de los 38.500 euros.<\/p>\n<p>En resumen, este motor V8 ha causado gran revuelo en la comunidad de los <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/byd-coches-electricos-7-millones\/9518\/\">coches<\/a>. M\u00e1s aun cuando su dise\u00f1ador es Xiaomi y no los tradicionales fabricantes como Tesla o BYD. Sus prestaciones lo hacen una de las mejores m\u00e1quinas el\u00e9ctricas hasta los momentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Producto de la norma establecida por la Uni\u00f3n Europea que dice tajantemente que estar\u00e1 prohibido comerciar coches contaminantes a partir &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Ni BYD ni Tesla, pero tampoco un motor de hidr\u00f3geno: esta marca acaba de revolucionar el transporte con su prototipo\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/byd-tesla-motor-hidrogeno\/10024\/#more-10024\" aria-label=\"Leer m\u00e1s sobre Ni BYD ni Tesla, pero tampoco un motor de hidr\u00f3geno: esta marca acaba de revolucionar el transporte con su prototipo\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":10025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=10024"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/10025"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=10024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=10024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=10024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}