{"id":10179,"date":"2024-09-03T17:00:32","date_gmt":"2024-09-03T15:00:32","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=10179"},"modified":"2024-09-03T17:00:32","modified_gmt":"2024-09-03T15:00:32","slug":"hidrogeno-podria-desaparecer","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-podria-desaparecer\/10179\/","title":{"rendered":"El hidr\u00f3geno, a punto de desaparecer en todo el planeta: hemos producido demasiado, y solo nos quedar\u00e1 este color"},"content":{"rendered":"<p>Los proyectos de hidr\u00f3geno verde han prosperado por toda Europa en los \u00faltimos a\u00f1os gracias al apoyo de gobiernos y empresas que ven en este gas noble la alternativa m\u00e1s prometedora a los combustibles f\u00f3siles. No obstante, un reciente informe sugiere que habr\u00eda que moderar nuestras expectativas en este sector, ya que predicen un futuro incierto para esta industria en la que <strong>ya se han invertido miles de millones de euros<\/strong>.<\/p>\n<h2>El hidr\u00f3geno verde afronta un futuro incierto: \u00bfHemos invertido demasiado en estos proyectos?<\/h2>\n<p>Europa es una de las regiones que m\u00e1s promueven el futuro mercado del hidr\u00f3geno verde como alternativa libre de emisiones tanto para sectores industriales, como para los coches, el transporte pesado y la industria naval. Si bien es cierto que se trata de una fuente renovable con grandes beneficios para la descarbonizaci\u00f3n, algunos expertos advierten que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-emisiones-ciclo-de-vida\/9949\/\">existe contaminaci\u00f3n en el ciclo de vida del H2<\/a>.<\/p>\n<p>Mientras la Uni\u00f3n Europea destina miles de millones de euros en el desarrollo de instalaciones de producci\u00f3n y transporte de hidr\u00f3geno y derivados como el amoniaco, compa\u00f1\u00edas de gran importancia como Toyota y Coca-Cola firman acuerdos para llevar el combustible al transporte pesado de mercanc\u00edas.<\/p>\n<p>Aun as\u00ed, un documento presentado recientemente por la OBS Bussiness School pone sobre la mesa un nuevo cuestionamiento m\u00e1s all\u00e1 de si el hidr\u00f3geno emite contaminaci\u00f3n o no. El estudio se enfoca en la rentabilidad de este nuevo combustible, afirmando que<strong> sus costos de producci\u00f3n resultan prohibitivos en comparaci\u00f3n con el petr\u00f3leo<\/strong> y sus derivados y podr\u00eda ser la base de un nuevo monopolio chino.<\/p>\n<h2>Los expertos predicen un proceso de \u00abselecci\u00f3n natural\u00bb para los proyectos de hidr\u00f3geno verde<\/h2>\n<p>Para producir hidr\u00f3geno sin recurrir a m\u00e9todos tradicionales como el reformado de gas natural, que genera emisiones de CO2, se requieren electrolizadores de gran escala que todav\u00eda resultan muy caros de producir en Europa. Por estas razones es que el documento de la OBS advierte que la producci\u00f3n y comercializaci\u00f3n de este combustible a gran escala implica <strong>una fuerte dependencia de la financiaci\u00f3n estatal<\/strong>.<\/p>\n<p>Esta dependencia se traduce en d\u00e9cadas de inversiones para que el H2 sea un producto de mercado rentable para la industria automotriz y las energ\u00edas renovables. Pero las ayudas estatales no pueden ser infinitos, por lo que el reporte advierte de un proceso de \u00abselecci\u00f3n natural\u00bb que dejar\u00e1 a muchos de los proyectos actuales en el camino.<\/p>\n<p>Seg\u00fan los datos aportados por el documento de la OBS, s\u00f3lo aquellos proyectos de hidr\u00f3geno verde que <strong>demuestren perspectivas s\u00f3lidas a largo plazo y una inversi\u00f3n sostenida<\/strong> por parte de privados y p\u00fablicos ser\u00e1n los que lleguen a concretarse en el futuro pr\u00f3ximo.<\/p>\n<h2>Las regulaciones a las importaciones chinas pueden echar por tierra los proyectos europeos<\/h2>\n<p>Los electrolizadores de escala industrial son el elemento clave para separar las mol\u00e9culas de hidr\u00f3geno del agua sin emitir ning\u00fan tipo de contaminaci\u00f3n. Fabricar estos componentes en territorio europeo tiene <strong>un costo hasta cuatro veces m\u00e1s elevado que importarlos desde China<\/strong>.<\/p>\n<p>El problema en este sentido es que la UE ha impuesto altos aranceles a las importaciones chinas para ayudar a la industria nacional a competir en este mercado, lo que supone un obst\u00e1culo importante para el H2 y requerir\u00eda la revisi\u00f3n de estas regulaciones si queremos que el combustible del futuro pueda reemplazar al petr\u00f3leo con un precio competitivo.<\/p>\n<h2>\u00bfCu\u00e1les ser\u00e1n las empresas que sobrevivan a la \u00abselecci\u00f3n natural\u00bb del hidr\u00f3geno?<\/h2>\n<p>Aunque el reporte de la OBS pueda parecer un tanto pesimista frente a las grandes promesas que se han hecho en torno al hidr\u00f3geno verde, lo cierto es que no desmiente los beneficios de este combustible. En realidad, nos revela que la estrategia m\u00e1s acertada ser\u00e1 la diversificaci\u00f3n. Este ha sido el enfoque que Toyota ha defendido durante a\u00f1os, y que ha impulsado el desarrollo de su <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-hibrido-toyota-hidrogeno\/9935\/\">motor h\u00edbrido que funciona con todos los combustibles<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los proyectos de hidr\u00f3geno verde han prosperado por toda Europa en los \u00faltimos a\u00f1os gracias al apoyo de gobiernos y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El hidr\u00f3geno, a punto de desaparecer en todo el planeta: hemos producido demasiado, y solo nos quedar\u00e1 este color\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-podria-desaparecer\/10179\/#more-10179\" aria-label=\"Leer m\u00e1s sobre El hidr\u00f3geno, a punto de desaparecer en todo el planeta: hemos producido demasiado, y solo nos quedar\u00e1 este color\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":10180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=10179"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/10180"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=10179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=10179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=10179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}