{"id":10641,"date":"2024-09-22T16:30:19","date_gmt":"2024-09-22T14:30:19","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=10641"},"modified":"2024-09-22T16:30:19","modified_gmt":"2024-09-22T14:30:19","slug":"paneles-solares-aeroleaf","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/paneles-solares-aeroleaf\/10641\/","title":{"rendered":"Adi\u00f3s a los paneles solares, el futuro es este \u00e1rbol artificial: as\u00ed produces 36 MWh con el viento en tu jard\u00edn"},"content":{"rendered":"<p>Un \u00e1rbol artificial de unos 11 metros de altura es con lo que se est\u00e1 aprovechando el viento para tratar de producir m\u00e1s energ\u00eda que la generada por el sol mediante finos y alargados<strong> paneles solares<\/strong>, sin duda, se trata de una re\u00f1ida pelea entre las dos fuentes \u00bfA qui\u00e9n le apuestas?<\/p>\n<h2>Un \u00e1rbol artificial que con el viento produce energ\u00eda e\u00f3lica<\/h2>\n<p>Ahora las hojas de los \u00e1rboles no solo se mecen con el viento, sino que tambi\u00e9n son capaces de generar energ\u00eda verde, pues funcionan como micro o <strong>mini turbinas<\/strong> con un movimiento giratorio alrededor de un eje vertical.<\/p>\n<p>Claro, no se trata de los \u00e1rboles que ya conocemos, sino \u00e1rboles artificiales o \u00abWindTree\u00bb, dise\u00f1ados por una startup francesa como respuesta a las deficiencias que presentan los aerogeneradores tradicionales y los paneles solares.<\/p>\n<p>Estos dispositivos con innovadores dise\u00f1os <strong>son capaces de generar 18 MWh<\/strong> con el poco viento que hay normalmente en los jardines (8 m\/s) y hasta 36 MWh en lugares con vientos de 12 m\/s de velocidad, lo que significa una excelente noticia en materia de reducci\u00f3n del calentamiento global.<\/p>\n<p>Sin embargo, es necesario advertir que todav\u00eda hay mucho camino por recorrer, puesto que los mismos representantes de la empresa fabricante reconocen que este novedoso dise\u00f1o contempla tanto ventajas como desventajas.<\/p>\n<h2>Ventajas y eficiencia de los \u00c1rboles de Viento<\/h2>\n<p>Asumiendo que una de las desventajas de los aerogeneradores existentes pudiera ser la ausencia de viento o la baja velocidad de las r\u00e1fagas, <strong>el Wind Tree no presenta ese problema<\/strong> porque opera con eficiencia aun con poco viento.<\/p>\n<p>Con un tama\u00f1o entre 5 y 11 metros y hojas de silueta geom\u00e9trica pueden incorporarse a los ambientes urbanos sin muchas dificultades, e incluso con algunos bancos alrededor puede constituir un paisaje urban\u00edsticamente integrado.<\/p>\n<p>A estas ventajas se les puede sumar el hecho de que, al no tener las paletas t\u00edpicas de los aerogeneradores sino miniturbinas, los incidentes con las aves se ven reducidos, aparte de que no producen elevados niveles de ruido.<\/p>\n<p>En resumen, los \u00e1rboles que generan energ\u00eda e\u00f3lica presentan las siguientes ventajas:<\/p>\n<ul>\n<li>Novedoso y compacto dise\u00f1o.<\/li>\n<li>Es bastante silencioso.<\/li>\n<li>Se integra al ambiente urbano.<\/li>\n<li>Representa poco riesgo para las aves.<\/li>\n<\/ul>\n<p>Sin embargo, no todo es perfecto, y en el caso de los \u00e1rboles de viento no es la excepci\u00f3n, puesto que en comparaci\u00f3n con otros dise\u00f1os este es mucho m\u00e1s costoso.<\/p>\n<p>Por ejemplo, el \u00abAeroleaf\u00bb <strong>puede tener un precio de 795\u20ac<\/strong>, pero adquirir un \u00abWindTree\u00bb completo requiere pagar 52.000\u20ac, aunque el modelo de 12 hojas de la versi\u00f3n hibrida (turbinas e\u00f3licas &#8211; paneles solares) tiene un precio menor de 24.500\u20ac<\/p>\n<p>Por consiguiente, como \u00fanica desventaja de estos \u00e1rboles generadores de energ\u00eda limpia puede se\u00f1alarse su alto coste.<\/p>\n<h2>\u00bfCu\u00e1l es la mejor decisi\u00f3n: paneles solares o \u00e1rboles artificiales?<\/h2>\n<p>El asunto de los elevados costes no es de poca importancia, aun cuando se trata de buscar soluci\u00f3n al vital y delicado problema del calentamiento global, porque sin duda esto reducir\u00e1 los niveles de compra de los consumidores.<\/p>\n<p>Sin embargo, todo apunta a creer que en el futuro la eficiencia energ\u00e9tica de estos \u00e1rboles artificiales <strong>se mantendr\u00e1 o incluso aumentar\u00e1<\/strong>, mientras que los precios de esta tecnolog\u00eda tender\u00e1n a disminuir por el uso de nuevos materiales o una mayor demanda.<\/p>\n<p>Por consiguiente, ciertamente a la vuelta de algunos a\u00f1os nos estaremos despidiendo de los paneles solares, y en cada jard\u00edn o plaza de la ciudad avistaremos la figura un tanto peculiar de este tipo de \u00e1rbol.<\/p>\n<p>En conclusi\u00f3n, la visi\u00f3n futurista es la de este <strong>\u00e1rbol artificial<\/strong> en el jard\u00edn de cada casa a pocos pasos de los \u00e1rboles naturales, ayudando a mantener un paisaje est\u00e9tico integrado y generando la energ\u00eda el\u00e9ctrica que requieren las personas que viven all\u00ed \u00bfcompartes esta visi\u00f3n?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un \u00e1rbol artificial de unos 11 metros de altura es con lo que se est\u00e1 aprovechando el viento para tratar &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Adi\u00f3s a los paneles solares, el futuro es este \u00e1rbol artificial: as\u00ed produces 36 MWh con el viento en tu jard\u00edn\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/paneles-solares-aeroleaf\/10641\/#more-10641\" aria-label=\"Leer m\u00e1s sobre Adi\u00f3s a los paneles solares, el futuro es este \u00e1rbol artificial: as\u00ed produces 36 MWh con el viento en tu jard\u00edn\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":10909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=10641"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/10641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/10909"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=10641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=10641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=10641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}