{"id":12512,"date":"2024-10-28T17:30:19","date_gmt":"2024-10-28T16:30:19","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=12512"},"modified":"2024-10-28T17:30:19","modified_gmt":"2024-10-28T16:30:19","slug":"japon-amoniaco-fukushima-limpiar","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/japon-amoniaco-fukushima-limpiar\/12512\/","title":{"rendered":"Jap\u00f3n va a lanzar una megabomba de amon\u00edaco: as\u00ed van a aniquilar la zona m\u00e1s peligrosa"},"content":{"rendered":"<p>El carb\u00f3n es una de las fuentes de energ\u00eda m\u00e1s contaminantes que existen, raz\u00f3n por la cual se ha ido abandonando a\u00f1o tras a\u00f1o en todo el mundo. Jap\u00f3n no tiene la posibilidad de, por ejemplo, <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/paneles-solares-refugio-animales\/5731\/\">instalar granjas solares como las que tenemos en Espa\u00f1a<\/a>. Sin embargo, parece que han encontrado una interesante soluci\u00f3n en la combusti\u00f3n de carb\u00f3n y amoniaco.<\/p>\n<h2>De qu\u00e9 se trata la combusti\u00f3n de carb\u00f3n y amoniaco<\/h2>\n<p>Importar energ\u00eda representa un gran costo para cada territorio. Es por esto que la base de la econom\u00eda de cada pa\u00eds depende en gran medida de los recursos energ\u00e9ticos locales. <strong>Para Jap\u00f3n, la principal fuente de electricidad siempre ha sido el carb\u00f3n<\/strong>, y las caracter\u00edsticas y dimensiones de su territorio suponen un gran impedimento para el uso de energ\u00edas alternativas.<\/p>\n<p>El gran inconveniente es que la combusti\u00f3n de carb\u00f3n genera una incre\u00edble cantidad de gases nocivos para el ambiente, adem\u00e1s de que su extracci\u00f3n requiere de trabajos de miner\u00eda igualmente destructivos para el ecosistema. Finalmente, el carb\u00f3n es un recurso no renovable, por lo que es importante encontrar una fuente alternativa antes de que \u00e9ste se agote.<\/p>\n<p>La empresa Jera, l\u00edder en la producci\u00f3n de electricidad en el pa\u00eds, parece haber dado con una soluci\u00f3n para dejar todos estos problemas en el pasado de manera sencilla y relativamente econ\u00f3mica. Se trata de <strong>la combinaci\u00f3n de carb\u00f3n y amoniaco para reducir el impacto negativo en el medio ambiente<\/strong> al quemar carb\u00f3n para producir electricidad.<\/p>\n<h2>\u00bfAmoniaco como combustible?<\/h2>\n<p>Puede que no hayas escuchado mucho sobre el amoniaco como combustible, y es porque en occidente no es muy com\u00fan ya que tenemos gran abundancia de otro tipo de recursos. En Jap\u00f3n, en cambio, hay un fuerte sector productivo dedicado al amoniaco para diferentes usos, y, en los \u00faltimos a\u00f1os, han estado desarrollando <strong>investigaciones en su potencial como combustible<\/strong>.<\/p>\n<p>El potencial de la combusti\u00f3n de amoniaco y carb\u00f3n reside principalmente en las propiedades del amoniaco como fuente de hidr\u00f3geno limpio para impulsar motores y centrales el\u00e9ctricas. Esta sustancia est\u00e1 compuesta por un \u00e1tomo de nitr\u00f3geno y dos de hidr\u00f3geno, por lo que se puede generar una reacci\u00f3n qu\u00edmica sencilla para separar el hidr\u00f3geno y usarlo tanto como combustible como para motores el\u00e9ctricos.<\/p>\n<p>El objetivo de Jera es empezar por reemplazar un 20% del uso de carb\u00f3n para la producci\u00f3n de energ\u00eda por amoniaco, con miras a alcanzar un 50% para 2035 y un<strong> funcionamiento completo por combusti\u00f3n de amoniaco en todas las centrales el\u00e9ctricas para 2050<\/strong>.<\/p>\n<p>Para obtener el amoniaco necesario para la combusti\u00f3n de carb\u00f3n y amoniaco, Jera planea obtenerlo del mar, donde los cuerpos org\u00e1nicos en descomposici\u00f3n liberan esta sustancia en grandes cantidades. Se trata del llamado \u00abamoniaco azul\u00bb.<\/p>\n<h2>Los desaf\u00edos de la combusti\u00f3n de carb\u00f3n y amoniaco<\/h2>\n<p>La combusti\u00f3n de carbono y amoniaco <strong>todav\u00eda se encuentra en una fase experimental<\/strong>, aunque el pa\u00eds asi\u00e1tico ve un gran potencial en este combustible tanto para la industria energ\u00e9tica como para combustible para nav\u00edos y veh\u00edculos impulsados por hidr\u00f3geno. El mayor obst\u00e1culo es el manejo seguro de una sustancia que es altamente t\u00f3xica para todos los seres vivos.<\/p>\n<p>Tambi\u00e9n ser\u00e1 necesario establecer una nueva l\u00ednea de suministro para obtener amoniaco azul y el desarrollo de amoniaco verde que permita obtener la sustancia de manera segura para el medio ambiente. Sin embargo, las perspectivas son altamente positivas y se espera que para 2050 sea una alternativa de uso masivo para todo el mundo.<\/p>\n<h2>El amoniaco como combustible del futuro<\/h2>\n<p>Ya est\u00e1n en marcha las gestiones para el uso de combusti\u00f3n de carb\u00f3n y amoniaco para proveer de electricidad a la ciudad de Hekian, que <strong>cuenta con unos 70000 habitantes<\/strong>. Solamente queda esperar a ver c\u00f3mo esta innovaci\u00f3n se complementa con otros desarrollos de gran importancia para <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-en-polvo\/5861\/\">el uso de hidr\u00f3geno limpio para generar energ\u00eda<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El carb\u00f3n es una de las fuentes de energ\u00eda m\u00e1s contaminantes que existen, raz\u00f3n por la cual se ha ido &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Jap\u00f3n va a lanzar una megabomba de amon\u00edaco: as\u00ed van a aniquilar la zona m\u00e1s peligrosa\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/japon-amoniaco-fukushima-limpiar\/12512\/#more-12512\" aria-label=\"Leer m\u00e1s sobre Jap\u00f3n va a lanzar una megabomba de amon\u00edaco: as\u00ed van a aniquilar la zona m\u00e1s peligrosa\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":12514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-12512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/12512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=12512"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/12512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/12514"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=12512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=12512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=12512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}