{"id":14403,"date":"2024-12-14T15:00:36","date_gmt":"2024-12-14T14:00:36","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=14403"},"modified":"2024-12-14T15:00:36","modified_gmt":"2024-12-14T14:00:36","slug":"china-panel-solar-oscuro-sin-luz","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/china-panel-solar-oscuro-sin-luz\/14403\/","title":{"rendered":"China pone el mundo al rev\u00e9s con el primer panel solar oscuro: el secreto para que funcione sin luz"},"content":{"rendered":"<p>China se ha convertido en una fuente constante de innovaciones en el \u00e1rea de las energ\u00edas limpias, y su liderazgo en este aspecto no tiene rivales. Hace poco hizo p\u00fablico un nuevo invento, se trata del primer panel solar oscuro, y puso el mundo al rev\u00e9s cuando revel\u00f3 cu\u00e1l es su secreto para que pueda funcionar sin luz.<\/p>\n<h2>Un panel solar que funciona con o sin luz<\/h2>\n<p>La generaci\u00f3n de energ\u00edas limpias se considera un \u00e1rea esencial para el desarrollo de cualquier pa\u00eds, e igualmente importante para tratar de mejorar las condiciones del medio ambiente, y detener el cambio clim\u00e1tico. En este sentido, China est\u00e1 decidida a tomar el liderazgo para hacerse con la mejor fuente energ\u00e9tica.<\/p>\n<p>Y recientemente, la Academia de Ciencias de ese pa\u00eds inform\u00f3 acerca de la creaci\u00f3n de una nueva celda <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/epanel-solar-agua-electricidad\/6311\/\">hidrovoltaica<\/a> herm\u00e9tica (HHC). Con este invento <strong>se puede producir energ\u00eda sin necesidad de tener luz solar<\/strong>, porque lo hace a trav\u00e9s del vapor de agua que se genera en su interior, debido al calor ambiental.<\/p>\n<h2>China busca producir energ\u00edas limpias a partir de diversas fuentes<\/h2>\n<p>El desarrollo de las investigaciones para <strong>encontrar la forma de dejar la dependencia del petr\u00f3leo<\/strong> ha permitido encontrar la utilidad de diversas fuentes como el sol o el viento. Y desde la Academia China de Ciencias public\u00f3 un art\u00edculo sobre el desarrollo de un nuevo artefacto para generar energ\u00eda el\u00e9ctrica.<\/p>\n<p>Se refiere a una celda hidrovoltaica herm\u00e9tica (HHC), que se diferencia de otras porque no necesita recibir agua de forma constante, sino que trabaja con un volumen reducido de agua que es suficiente para producir vapor con el calor ambiental. Otra de sus ventajas es que se adapta a diferentes tipos de entornos.<\/p>\n<p>Esto lo hace gracias a que est\u00e1 totalmente sellado, y en su interior contiene una l\u00e1mina negra de carbono, papel tis\u00fa y un peque\u00f1o volumen de agua. El calor ambiental va a provocar su evaporaci\u00f3n, que va a circular a trav\u00e9s del papel, que crea un flujo capilar constante, y esto a su vez produce un efecto hidrovoltaico.<\/p>\n<p>Este fen\u00f3meno, que es causado por la interacci\u00f3n del agua con una superficie s\u00f3lida, va a hacer que se produzca energ\u00eda el\u00e9ctrica con muy poca p\u00e9rdida de agua. Y aunque no es necesaria la luz solar, si esta incide sobre la celda y le da m\u00e1s calor, aumenta la evaporaci\u00f3n y, por lo tanto, la generaci\u00f3n energ\u00e9tica.<\/p>\n<p>Este invento demostr\u00f3 su eficiencia al ser probado porque tuvo la capacidad de <strong>producir electricidad de forma ininterrumpida durante 160 horas<\/strong>. Con esta celda, los investigadores de China abren una nueva puerta a la producci\u00f3n de energ\u00eda limpia de una forma sencilla, y que se adapta a diferentes clases de ambientes.<\/p>\n<h2>La celda hidrovoltaica herm\u00e9tica es una fuente de energ\u00eda vers\u00e1til<\/h2>\n<p>Uno de los m\u00e1s recientes inventos realizados en China, la celda hidrovoltaica herm\u00e9tica, constituye un adelanto para producir energ\u00eda el\u00e9ctrica de una forma limpia. Y aunque hay muchos aparatos que cumplen con esta funci\u00f3n, este cuenta con una serie de ventajas, como por ejemplo el uso de poca cantidad de agua.<\/p>\n<p>Otra es que <strong>puede funcionar en ambientes con condiciones muy adversas<\/strong>, como lugares con gran humedad, secos, a temperaturas extremas, con poca luz o con mucho viento. Adem\u00e1s, sus partes son de uso com\u00fan, por lo que puede ser empleado en lugares remotos o donde los recursos son muy escasos.<\/p>\n<p>Concluyendo, los investigadores de China han sacado a la luz un nuevo invento, la celda hidrovoltaica herm\u00e9tica, que genera <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/panel-solar-placa-termoelectrica\/14211\/\">electricidad<\/a> limpia por medio de las interacciones del agua con superficies s\u00f3lidas. Sus ventajas son, entre otras, que usa poca agua, funciona sin luz solar y aprovecha el calor ambiental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>China se ha convertido en una fuente constante de innovaciones en el \u00e1rea de las energ\u00edas limpias, y su liderazgo &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"China pone el mundo al rev\u00e9s con el primer panel solar oscuro: el secreto para que funcione sin luz\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/china-panel-solar-oscuro-sin-luz\/14403\/#more-14403\" aria-label=\"Leer m\u00e1s sobre China pone el mundo al rev\u00e9s con el primer panel solar oscuro: el secreto para que funcione sin luz\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":14404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=14403"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/14404"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=14403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=14403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=14403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}