{"id":14417,"date":"2024-12-10T14:30:54","date_gmt":"2024-12-10T13:30:54","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=14417"},"modified":"2024-12-10T14:30:54","modified_gmt":"2024-12-10T13:30:54","slug":"region-espanola-oro-grande-europa","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/region-espanola-oro-grande-europa\/14417\/","title":{"rendered":"Esta regi\u00f3n espa\u00f1ola, \u00abbendecida\u00bb con oro: 30 000 kilos en la mina m\u00e1s grande de Europa"},"content":{"rendered":"<p>Espa\u00f1a es un pa\u00eds bendecido por la gran cantidad y variedad de recursos naturales que posee, entre ellos est\u00e1 el oro que pr\u00e1cticamente aflora a los pies de quien lo busca. Te traemos una regi\u00f3n espa\u00f1ola que posee enormes reservas del noble metal y que su potencial mina ser\u00eda la m\u00e1s grande de Europa. Ve\u00e1mosla m\u00e1s de cerca.<\/p>\n<h2>El oro: un mineral que no solo sirve para decorar y adornar sino para la fabricaci\u00f3n de materiales conductores<\/h2>\n<p>En el municipio de Tapia de Casariego, que pertenece a la comunidad aut\u00f3noma de Asturias en las orillas del mar Cant\u00e1brico, se han hecho exploraciones que han dado como resultado que en su subsuelo hay una <strong>reserva de oro es de 30.000 kilos<\/strong>, siendo la m\u00e1s grande de Europa.<\/p>\n<p>Este es un mineral que no solo tiene usos decorativos por su gran belleza y ductilidad, tambi\u00e9n posee propiedades que lo hacen un excelente <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/panel-solar-placa-termoelectrica\/14211\/\">conductor<\/a> el\u00e9ctrico. De hecho, es superior en este sentido a la gran mayor\u00eda de los metales. Lo mejor es que este atributo no es afectado por la temperatura como otros materiales.<\/p>\n<h2>Un descubrimiento que tiene m\u00e1s de 100 a\u00f1os pero que a\u00fan no se ha podido explotar<\/h2>\n<p>Desde hace, aproximadamente, unos 100 a\u00f1os que se realizan sondeos y exploraciones subterr\u00e1neas en la zona de Tapia de Casariego, por muchas empresas mineras con buenos resultados y con el fin de <strong>explotar esta mina y su enorme yacimiento de oro<\/strong> que est\u00e1 alrededor de 30.000 kilogramos.<\/p>\n<p>El caso es que estos trabajos han sido poco menos que in\u00fatiles, pues la extracci\u00f3n de este mineral causar\u00eda un grave da\u00f1o al medio ambiente de la regi\u00f3n que probablemente ser\u00eda irremediable. Por otra parte, est\u00e1 el temor de los habitantes de c\u00f3mo este deterioro afectar\u00eda su calidad de vida, que ahora se considera buena.<\/p>\n<p>Igualmente est\u00e1 el tema de la expropiaci\u00f3n de casas y terrenos. Es por ello que se ha creado el movimiento llamado \u201cOro NO\u201d que agrupa a vecinos, ganaderos, pescadores y dem\u00e1s para oponerse a este proyecto. De hecho, ya llevan varias d\u00e9cadas venciendo, en el plano jur\u00eddico, a las multinacionales.<\/p>\n<p>La m\u00e1s reciente batalla legal fue en el 2010 cuando una empresa llamada Astur Gold present\u00f3 una propuesta para la explotaci\u00f3n. Pero en el a\u00f1o 2014 la misma fue vetada por el Principado de Asturias. <strong>Luego todo qued\u00f3 hasta ah\u00ed<\/strong> cuando en el 2017, dicho veto fue confirmado por el Tribunal Superior del Principado.<\/p>\n<h2>Se presenta una nueva propuesta que dice ser m\u00e1s ecol\u00f3gica y sostenible<\/h2>\n<p>Este nuevo proyecto es presentado por la empresa Exploraciones Mineras del Cant\u00e1brico (EMC). El mismo a\u00fan est\u00e1 en la etapa de estudio y mejoras. Tiene un presupuesto asignado de 100 millones de euros con el objetivo de extraer un <strong>mill\u00f3n de onzas de oro que son unos 30.000 kilos<\/strong>, en un t\u00e9rmino de tres a\u00f1os.<\/p>\n<p>Tanto conceptualmente como en la pr\u00e1ctica, este proyecto es muy diferente al del 2010. Como ejemplo de esta afirmaci\u00f3n se tiene que no se usar\u00e1 cianuro y las aguas residuales ser\u00e1n filtradas y potabilizadas en una planta de tratamiento para hacerlas un 99 % puras antes de verterlas en el r\u00edo.<\/p>\n<p>Asimismo, cuentan con el apoyo de la industria fabricante de conductores el\u00e9ctricos, la que recibir\u00e1 parte de este material para sus factor\u00edas. Los directivos de EMC reiteran que este proyecto no pretende perjudicar a nadie, puesto que est\u00e1 adaptado para ser lo m\u00e1s sostenible posible.<\/p>\n<p>Como conclusi\u00f3n, la localidad de Tapia de Casariego posee alrededor de 30.000 kilos de oro bajo sus pies lo que pudiera ser una bendici\u00f3n o una maldici\u00f3n seg\u00fan se mire. El problema es que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-energia-mundo-nucleares\/10467\/\">Espa\u00f1a<\/a> no ha dado luz verde para su explotaci\u00f3n por los da\u00f1os medioambientales que pudiera involucrar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espa\u00f1a es un pa\u00eds bendecido por la gran cantidad y variedad de recursos naturales que posee, entre ellos est\u00e1 el &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Esta regi\u00f3n espa\u00f1ola, \u00abbendecida\u00bb con oro: 30 000 kilos en la mina m\u00e1s grande de Europa\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/region-espanola-oro-grande-europa\/14417\/#more-14417\" aria-label=\"Leer m\u00e1s sobre Esta regi\u00f3n espa\u00f1ola, \u00abbendecida\u00bb con oro: 30 000 kilos en la mina m\u00e1s grande de Europa\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":14435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=14417"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/14435"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=14417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=14417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=14417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}