{"id":14771,"date":"2024-12-18T14:30:10","date_gmt":"2024-12-18T13:30:10","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=14771"},"modified":"2024-12-18T14:30:10","modified_gmt":"2024-12-18T13:30:10","slug":"espana-central-energetica-unesco","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/espana-central-energetica-unesco\/14771\/","title":{"rendered":"Espa\u00f1a encuentra una central energ\u00e9tica de los Romanos: 1200 millones de euros y una mina de oro"},"content":{"rendered":"<p>La actual crisis energ\u00e9tica a nivel global, agravada por la guerra entre Ucrania y Rusia que pone en peligro el suministro de combustibles f\u00f3siles, ha hecho que Espa\u00f1a busque otras fuentes que sean limpias. Como esta central energ\u00e9tica en terrenos de la antigua Roma con una mina de oro y 1.200 millones de euros.<\/p>\n<h2>La construcci\u00f3n de una central energ\u00e9tica hidroel\u00e9ctrica en un sitio que es Patrimonio Mundial por la Unesco<\/h2>\n<p>La empresa Capital Energy, una compa\u00f1\u00eda especializada en estudios de ingenier\u00eda, construcci\u00f3n y gesti\u00f3n de instalaciones para la generaci\u00f3n de energ\u00eda el\u00e9ctrica de una forma sostenible, ha anunciado que est\u00e1 en la fase de planificaci\u00f3n y obtenci\u00f3n de permisos para la construcci\u00f3n de una central energ\u00e9tica.<\/p>\n<p><strong>Se ubicar\u00e1 en las localidades de Castrillo y Encinedo en la comarca leonesa de Cabrera<\/strong>, comunidad de Castilla y Le\u00f3n. Esta infraestructura se construir\u00e1 cerca de las minas de oro a cielo abierto de la antigua Roma conocidas como Las M\u00e9dulas y a 200 metros de sus canales de agua que tienen m\u00e1s de 600 kil\u00f3metros.<\/p>\n<h2>Una planta de generaci\u00f3n de electricidad que ser\u00e1 de \u00faltima tecnolog\u00eda reversible y soterrada<\/h2>\n<p><strong>Esta central hidroel\u00e9ctrica ser\u00e1 del tipo reversible<\/strong>, la cual ser\u00e1 abastecida por el cercano r\u00edo Cabrera. La forma de operaci\u00f3n de esta clase de planta es muy sencilla, por lo menos en su forma conceptual, ya que consiste en dejar caer agua desde una gran altura hasta unas aletas de turbinas ubicadas a fondo de la ca\u00edda.<\/p>\n<p>Las cuales, al moverse a suficiente velocidad angular, convierten la energ\u00eda mec\u00e1nica generando energ\u00eda el\u00e9ctrica que ser\u00eda transmitida por las redes de alta tensi\u00f3n. A fin de captar el agua necesaria, esta se tomar\u00e1 del r\u00edo Cabrera construyendo una presa directamente encima de su cauce para forzar su embalse.<\/p>\n<p>Para esto el agua ser\u00eda impulsada, artificialmente, hasta la cima de la monta\u00f1a de Marrubio para depositarla en <strong>un embalse que se construir\u00eda all\u00ed a una altura de 900 metros<\/strong> y se dejar\u00eda caer desde esta altitud. Por lo que ser\u00eda necesario perforar la monta\u00f1a, as\u00ed que tambi\u00e9n ser\u00e1 una planta hidroel\u00e9ctrica del tipo soterrada.<\/p>\n<p>En este proyecto se invertir\u00e1n alrededor de 1.200 millones de euros para generar una potencia el\u00e9ctrica equivalente a la que suministrar\u00edan dos centrales nucleares de regular tama\u00f1o a pleno funcionamiento. Por otra parte, es el tercer proyecto m\u00e1s grande de Europa para la explotaci\u00f3n de recursos hidroel\u00e9ctricos.<\/p>\n<p>La construcci\u00f3n de esta central dar\u00e1 muchos beneficios para el desarrollo econ\u00f3mico de las localidades de Encinedo y Castrillo (al igual que este <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-megaproyecto-energia-agua\/14598\/\">megaproyecto que est\u00e1 en desarrollo<\/a> en Espa\u00f1a). Esto sin contar con que se generar\u00edan 40 puestos fijos de mano de obra calificada <strong>necesarios para su operaci\u00f3n y mantenimiento<\/strong>.<\/p>\n<h2>Un gran proyecto que tambi\u00e9n tiene detractores por las posibles afectaciones al ambiente y al patrimonio cultural<\/h2>\n<p>Los alcaldes de ambas municipalidades ya han dado su aprobaci\u00f3n para esta central, aunque pol\u00edticamente son contrarios pero convergen en su deseo de un gran desarrollo regional, se han topado <strong>con las cr\u00edticas de algunos sectores<\/strong>. Como los ecologistas que ven la obra como una amenaza.<\/p>\n<p>Para los ecosistemas marinos y terrestres, as\u00ed como para la fauna y flora aut\u00f3ctona. Por otra parte, otros movimientos conservacionistas del patrimonio objetan su ubicaci\u00f3n por la cercan\u00eda al yacimiento arqueol\u00f3gico de las minas y sus cauces de agua, los que fueron declarados Patrimonio Mundial por la Unesco.<\/p>\n<p>Concluyendo, Espa\u00f1a est\u00e1 en v\u00edas de construcci\u00f3n de una gran central hidroel\u00e9ctrica que se podr\u00eda decir que es de la Antigua Roma por su ubicaci\u00f3n (as\u00ed como esta instalaci\u00f3n que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-shock-energia-rapida\/12877\/\">generar\u00e1 electricidad en forma tan r\u00e1pida<\/a> que tiene a Espa\u00f1a en shock) con una inversi\u00f3n de 1.200 millones de euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actual crisis energ\u00e9tica a nivel global, agravada por la guerra entre Ucrania y Rusia que pone en peligro el &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a encuentra una central energ\u00e9tica de los Romanos: 1200 millones de euros y una mina de oro\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-central-energetica-unesco\/14771\/#more-14771\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a encuentra una central energ\u00e9tica de los Romanos: 1200 millones de euros y una mina de oro\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":14869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=14771"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/14771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/14869"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=14771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=14771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=14771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}