{"id":15154,"date":"2024-12-25T15:30:27","date_gmt":"2024-12-25T14:30:27","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=15154"},"modified":"2024-12-25T15:30:27","modified_gmt":"2024-12-25T14:30:27","slug":"supervolcan-perforarlo-energia","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/supervolcan-perforarlo-energia\/15154\/","title":{"rendered":"Este supervolc\u00e1n puede ser el fin de la humanidad: quieren perforarlo y extraer esto del fondo"},"content":{"rendered":"<p>Aunque los seres humanos han aprovechado la naturaleza, y en muchos casos han abusado de ella al tratar de moldearla para su satisfacci\u00f3n, su poder sigue siendo indomable. Y ese es el caso de este supervolc\u00e1n, que puede ser el fin de la humanidad, pero igual hay quien quiere perforarlo para poder extraer esto del fondo.<\/p>\n<h2>La belleza de un Parque Nacional oculta un peligro<\/h2>\n<p>El Parque Nacional de Yellowstone es uno de esos lugares excepcionales en los que la naturaleza se conserva en su estado m\u00e1s puro y salvaje. Su aspecto es \u00fanico, gracias a sus formaciones geol\u00f3gicas que permiten la emisi\u00f3n de aguas termales, cuya composici\u00f3n mineral le brinda un colorido especial a toda esa zona.<\/p>\n<p>El coraz\u00f3n de ese lugar es su supervolc\u00e1n, que es reconocido por ser el m\u00e1s grande del planeta, esto lo convierte tambi\u00e9n en un peligro, pues <strong>en el caso de hacer erupci\u00f3n, ser\u00eda el fin de la humanidad<\/strong>. Por eso se ha propuesto la idea de perforarlo para extraer del fondo su calor y usarlo como fuente de energ\u00eda.<\/p>\n<h2>El poder de la naturaleza como fuente de energ\u00eda<\/h2>\n<p>Los requerimientos de energ\u00eda son inevitables en cualquier lugar en el que vivan los seres humanos, lo diferente en estos tiempos es <strong>el deseo de renunciar a los derivados del petr\u00f3leo<\/strong> y sustituirlos por fuentes limpias. En este aspecto, la naturaleza ofrece muchas opciones, incluyendo la geot\u00e9rmica de un supervolc\u00e1n.<\/p>\n<p>Es un hecho conocido que, en el Parque Nacional de Yellowstone de Estados Unidos, est\u00e1 uno de los mayores peligros naturales para la vida del planeta. Porque se sabe que, si su volc\u00e1n hace erupci\u00f3n, arrasar\u00eda con ese pa\u00eds, y el planeta sufrir\u00eda los rigores de un invierno causado por la cantidad de rocas y lava que expulsar\u00eda.<\/p>\n<p>Ante ese riesgo, un grupo de cient\u00edficos de la NASA propuso hace algunos a\u00f1os que se podr\u00eda calmar el supervolc\u00e1n al perforarlo, realizando varios pozos de unos 10 km de profundidad a su alrededor para bombear agua a alta presi\u00f3n (y tambi\u00e9n para <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/se-hunde-el-volcan-mas-grande-del-mundo-los-cientificos-debaten-la-manera-de-evitar-los-inminentes-estragos\/12365\/\">evitar que se hunda<\/a> como ya advertimos). As\u00ed se podr\u00eda enfriar la cuenca.<\/p>\n<p>Con esta tecnolog\u00eda se lograr\u00eda reducir la actividad volc\u00e1nica, y aportar\u00eda una ganancia adicional, pues ese calor liberado del fondo permitir\u00eda extraer energ\u00eda geot\u00e9rmica. Esta, a su vez, se puede usar para obtener agua caliente, como calefacci\u00f3n y para generar electricidad, que adem\u00e1s ser\u00eda muy econ\u00f3mica.<\/p>\n<p>Sin embargo, esto puede quedar solo en la mera posibilidad te\u00f3rica, pues el supervolc\u00e1n est\u00e1 en una zona protegida, que incluso es considerada sagrada. Y, aunque una central geot\u00e9rmica no da\u00f1e su estructura rocosa, cambiar\u00eda el paisaje, y <strong>no se puede da\u00f1ar esa regi\u00f3n donde la naturaleza luce su m\u00e1ximo esplendor.<\/strong><\/p>\n<h2><strong>\u00a0<\/strong>El supervolc\u00e1n de Yellowstone est\u00e1 protegido<\/h2>\n<p>La idea de obtener energ\u00eda geot\u00e9rmica en el Parque Nacional de Yellowstone parece muy l\u00f3gica, sin embargo, la experiencia de otros pa\u00edses indica que se pueden producir da\u00f1os irreparables al medio ambiente. Un ejemplo de ello es Nueva Zelanda, que pose\u00eda la mayor cantidad de g\u00e9iseres de todo el mundo.<\/p>\n<p>A mediados del siglo pasado ten\u00eda m\u00e1s de 220, pero construyeron una central de energ\u00eda geot\u00e9rmica que los arras\u00f3, y solo quedaron 55 activos, seg\u00fan los expertos, el error fue la falta de cuidado y no mantener las perforaciones alejadas de los g\u00e9iseres. <strong>Por eso Yellowstone permanecer\u00e1 protegido de la explotaci\u00f3n.<\/strong><\/p>\n<p>En conclusi\u00f3n, si el supervolc\u00e1n de Yellowstone hace erupci\u00f3n, podr\u00eda ser el fin de la humanidad (como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/volcan-islas-energia-geotermica\/12025\/\">este que arras\u00f3<\/a> una de las islas de Espa\u00f1a). Propusieron perforarlo y extraer su calor del fondo para enfriarlo y obtener energ\u00eda geot\u00e9rmica. Pero eso quedar\u00e1 como una teor\u00eda, porque da\u00f1ar\u00eda la naturaleza en toda esa regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque los seres humanos han aprovechado la naturaleza, y en muchos casos han abusado de ella al tratar de moldearla &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este supervolc\u00e1n puede ser el fin de la humanidad: quieren perforarlo y extraer esto del fondo\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/supervolcan-perforarlo-energia\/15154\/#more-15154\" aria-label=\"Leer m\u00e1s sobre Este supervolc\u00e1n puede ser el fin de la humanidad: quieren perforarlo y extraer esto del fondo\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":15182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-15154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/15154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=15154"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/15154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/15182"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=15154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=15154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=15154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}