{"id":15562,"date":"2025-01-03T16:30:32","date_gmt":"2025-01-03T15:30:32","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=15562"},"modified":"2025-01-03T16:30:32","modified_gmt":"2025-01-03T15:30:32","slug":"construccion-aluminio-transparente-2","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/construccion-aluminio-transparente-2\/15562\/","title":{"rendered":"Este material de construcci\u00f3n invisible por primera vez en la historia: es el aislante perfecto este invierno"},"content":{"rendered":"<p>\u00bfHab\u00edas pensando alguna vez que con aluminio llegar\u00edan a crear un material de <strong>construcci\u00f3n<\/strong> transparente extremadamente resistente y de alta capacidad aislante? Es tan futurista este compuesto que su uso fue predicho en la saga de la pel\u00edcula Star Trek.<\/p>\n<h2>Si el aluminio no es transparente ni buen aislante \u00bfpor qu\u00e9 el nuevo material de construcci\u00f3n lo es?<\/h2>\n<p>Generalmente los objetos heredan las propiedades de las materias primas con las que son fabricados, por lo que es sorprendente que se haya creado un material de construcci\u00f3n con aluminio que resulte transparente y buen aislante, sabiendo que este metal se caracteriza por ser:<\/p>\n<ul>\n<li>D\u00factil<\/li>\n<li>Maleable<\/li>\n<li>Lustroso<\/li>\n<li>Conductor el\u00e9ctrico<\/li>\n<li>Conductor t\u00e9rmico<\/li>\n<\/ul>\n<p>Cuando tenemos un objeto hecho en aluminio en nuestras manos, por ejemplo, un tubo de poco grosor, podemos doblarlo, calentarlo hasta que se derrita, as\u00ed como utilizarla para conducir electricidad o calor.<\/p>\n<p>Entonces, c\u00f3mo es que puede fabricarse un <strong>compuesto cuyas propiedades son muy diferentes a su material original<\/strong>, siendo el resultado en este caso un \u00abaluminio transparente\u00bb parecido al vidrio y con capacidad aislante.<\/p>\n<h2>El nuevo material de aluminio transparente est\u00e1 de pel\u00edcula<\/h2>\n<p>En realidad no se trata de una sustancia met\u00e1lica derivada del aluminio sino de una cer\u00e1mica constituida por partes iguales de este metal con el ox\u00edgeno y el hidr\u00f3geno y cuya f\u00f3rmula es AlON, siendo <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/construccion-aluminio-transparente\/8413\/\">fabricado de esta manera<\/a>.<\/p>\n<p>Esta cer\u00e1mica recibe el nombre de oxinitruro de aluminio desde 1980 cuando fue creado, justo en la \u00e9poca de Star Trek IV: The Voyage Home, siendo precisamente en una <strong>escena de esta pel\u00edcula cuando se menciona por primera vez este compuesto<\/strong>. Este compuesto es bastante popular debido a sus aplicaciones, pues se utiliza en diversos procesos con las siguientes ventajas:<\/p>\n<ul>\n<li>Novedosa tecnolog\u00eda<\/li>\n<li>Amplias aplicaciones<\/li>\n<li>Reducci\u00f3n de costes<\/li>\n<li>Ahorro de tiempo<\/li>\n<li>Amigabilidad con el ambiente<\/li>\n<\/ul>\n<h3>Un material de pel\u00edcula usado para transportar ballenas<\/h3>\n<p>Curiosamente en la pel\u00edcula Star Trek IV se menciona este material cuando no era muy conocido; espec\u00edficamente, cuando el personaje de Scotty encara la tarea de trasladar dos ballenas desde la tierra.<\/p>\n<p>Es la escena cuando se necesita llevar dos enormes ballenas en una destartalada nave klingon y se requiere de un material adecuado, por ello se propone enviar la f\u00f3rmula al siglo XX.<\/p>\n<p>El <strong>nombre comercial de este novedoso aluminio transparente es ALON<\/strong>, siendo la compa\u00f1\u00eda Surmet Corporation quien lo fabrica y comercializa. Para su fabricaci\u00f3n se utiliza el proceso de sinterizaci\u00f3n, aplicando el siguiente procedimiento:<\/p>\n<ol>\n<li>Mezcla de los ingredientes<\/li>\n<li>Vertido en un molde<\/li>\n<li>Compactaci\u00f3n a alta presi\u00f3n<\/li>\n<li>Cocci\u00f3n a alta temperatura<\/li>\n<li>Molienda del cuerpo transl\u00facido producido<\/li>\n<li>Pulido del material<\/li>\n<\/ol>\n<h2>Este nuevo vidrio demuestra una resistencia a prueba de balas<\/h2>\n<p>La resistencia de este elemento de construcci\u00f3n es tal que durante las pruebas realizadas con un panel de 1,6 pulgadas de espesor recibi\u00f3 disparos de un rifle calibre 50 sin que se produjera rompimiento o penetraci\u00f3n, superando a un vidrio blindado de 3,7&#8243;.<\/p>\n<p>Igualmente supera a otros materiales en cuanto a la transparencia, pues mediante pruebas de propiedades \u00f3pticas se pudo <strong>comprobar la absorci\u00f3n de IR por parte de la mayor\u00eda de vidrios<\/strong>, mientras que ALON es completamente transparente.<\/p>\n<p>Este material tiene la ventaja frente al vidrio de una resistencia mayor a los ara\u00f1azos, aunque tambi\u00e9n una importante desventaja y es lo que impide que sea utilizado con frecuencia como sustituto del vidrio blindado.<\/p>\n<p>La desventaja es su precio, pues quintuplica el coste del laminado tradicional, aunque es posible que en el futuro una mayor demanda incida en una reducci\u00f3n de costes, lo que conllevar\u00eda a reemplazar el Gorilla Glaz de los tel\u00e9fonos inteligentes.<\/p>\n<p>En definitiva, si baja lo suficiente el coste de este material<span data-sheets-root=\"1\"> de <strong>construcci\u00f3n<\/strong> invisible y de alta resistencia incluso podr\u00eda utilizarse con m\u00e1s frecuencia en \u00e9poca de invierno, pudiendo ser m\u00e1s eficiente que este <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/aislante-termico-asequible\/13154\/\">nuevo aislante t\u00e9cnico<\/a>.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHab\u00edas pensando alguna vez que con aluminio llegar\u00edan a crear un material de construcci\u00f3n transparente extremadamente resistente y de alta &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este material de construcci\u00f3n invisible por primera vez en la historia: es el aislante perfecto este invierno\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/construccion-aluminio-transparente-2\/15562\/#more-15562\" aria-label=\"Leer m\u00e1s sobre Este material de construcci\u00f3n invisible por primera vez en la historia: es el aislante perfecto este invierno\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":15602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-15562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/15562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=15562"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/15562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/15602"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=15562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=15562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=15562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}