{"id":16478,"date":"2025-01-23T17:00:33","date_gmt":"2025-01-23T16:00:33","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=16478"},"modified":"2025-01-23T17:00:33","modified_gmt":"2025-01-23T16:00:33","slug":"nasa-planeta-desintegrando","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/nasa-planeta-desintegrando\/16478\/","title":{"rendered":"La NASA, en vilo con este planeta: se est\u00e1 desintegrando a velocidad r\u00e9cord"},"content":{"rendered":"<p>La <strong>NASA<\/strong> a trav\u00e9s de un sat\u00e9lite de sondeo de exoplanetas ha descubierto un planeta que se desintegra a tan incre\u00edble velocidad que muy pronto dejar\u00e1 de existir \u00bfQuieres saber m\u00e1s acerca de este cuerpo celeste que est\u00e1 desapareciendo?<\/p>\n<h2>Cu\u00e1l es ese planeta que la NASA ha descubierto durante su proceso de desintegraci\u00f3n<\/h2>\n<p>Gracias a un trabajo combinado entre astr\u00f3nomos del MIT y de la Universidad de Pensilvania fue descubierto un planeta que ha sido bautizado con el nombre de BD+05 4868 Ab y que se mantiene orbitando alrededor de su estrella BD+05 4868 A.<\/p>\n<p>Dicho cuerpo celeste se localiza aproximadamente a 141 a\u00f1os luz,\u00a0 siendo as\u00ed el exoplaneta en desintegraci\u00f3n m\u00e1s cercano; buscando ambos equipos de investigadores conocer m\u00e1s acerca del <strong>Telescopio Espacial James Webb (JWST) en BD+05 4868<\/strong> dotado de tecnolog\u00eda infrarrojo y que se compara con <a href=\"https:\/\/www.ecoticias.com\/tecnologia-verde\/169317_e-elt-telescopio-terrestre-grande-mundo\">el telescopio m\u00e1s grande del mundo<\/a>.<\/p>\n<p>El evento astron\u00f3mico ha sido estudiado por la NASA mediante el sat\u00e9lite de sondeo de exoplanetas (TESS, siglas en ingl\u00e9s) y lo m\u00e1s interesante del hallazgo es la velocidad con que se lleva a cabo la desintegraci\u00f3n de este cuerpo sideral.<\/p>\n<p>Es algo que <strong>nunca se ha visto por la distancia a la que sucede la descomposici\u00f3n de las estrellas<\/strong>, y cuando apenas se percibe es porque el astro ha desaparecido en su totalidad.<\/p>\n<h2>Qu\u00e9 se observa en un cuerpo celeste que est\u00e1 desapareciendo<\/h2>\n<p>De acuerdo con Nick Tusay, quien dirigi\u00f3 la investigaci\u00f3n, la visi\u00f3n de este exoplaneta en proceso de desintegraci\u00f3n permite conocer m\u00e1s acerca de la composici\u00f3n de estos cuerpos celestes y de esta forma obtener respuestas a interrogantes sobre el origen de las estrellas.<\/p>\n<p>Otro de los miembros del equipo de investigaci\u00f3n hizo referencia a la oportunidad que brinda la <strong>observaci\u00f3n de planetas en proceso de desintegraci\u00f3n mediante espectr\u00f3grafos<\/strong> porque permite ver el interior de los mismos, algo que no es posible incluso con la Tierra y otros planetas cercanos.<\/p>\n<p>Uno de los aspectos m\u00e1s impresionantes del planeta que se desintegra son las colas de polvo que se desprenden y que alcanzan casi una decena de millones de kil\u00f3metros cubriendo la mitad de la \u00f3rbita planetaria durante treinta horas y media.<\/p>\n<p>Espec\u00edficamente, la cola de este cuerpo celeste presenta las siguientes caracter\u00edsticas:<\/p>\n<ul>\n<li>De amplia prominencia<\/li>\n<li><strong>Son gigantescas por tener una longitud de unos 9 millones de kil\u00f3metros<\/strong><\/li>\n<li>Rodean m\u00e1s de la mitad de la \u00f3rbita del planeta alrededor de la estrella cada 30 horas y media.<\/li>\n<li>Es densa y grande<\/li>\n<li>Al cruzar la cara de su estrella bloquea el 1% de su luz<\/li>\n<li>Afecta la se\u00f1al de tr\u00e1nsito durante 15 horas<\/li>\n<\/ul>\n<h2>Hasta donde lleva la visi\u00f3n de un planeta reduci\u00e9ndose a polvo c\u00f3smico<\/h2>\n<p>La magnitud de las dimensiones y densidad de esta cola es tan impresionante que al cruzar la faz de la estrella produce un bloqueo de la luz en un 1% y el tr\u00e1nsito de las se\u00f1ales luminosas se ven interrumpidas por un periodo de 15 horas.<\/p>\n<p>El equipo de investigadores considera una verdadera suerte poder apreciar la descomposici\u00f3n del cuerpo planetario, sirviendo los datos obtenidos para emprender nuevas <strong>investigaciones en torno a sistemas en proceso de desintegraci\u00f3n<\/strong>.<\/p>\n<p>Una de las razones por la que es tan dif\u00edcil observar este tipo de fen\u00f3meno astron\u00f3mico es que la velocidad a la que se evapora el cuerpo celeste es simplemente catacl\u00edsmica.<\/p>\n<p>A esta alt\u00edsima velocidad de desaparici\u00f3n es toda una suerte presenciar las \u00faltimas horas del planeta moribundo, y mucho m\u00e1s fortuna es tener la oportunidad de recoger datos que sirvan como <strong>punto de referencia para futuros estudios de desintegraci\u00f3n de estos sistemas<\/strong>.<\/p>\n<p>Estos planetas pr\u00e1cticamente riegan sus contenidos por el espacio cuando se encuentran en este proceso, haciendo imprescindibles los medios tecnol\u00f3gicos disponibles para estudiar su composici\u00f3n, as\u00ed como la de los planetas que orbitan otras estrellas es algo clave para la astronom\u00eda.<\/p>\n<p>En conclusi\u00f3n, la observaci\u00f3n que lleva a cabo l<span data-sheets-root=\"1\">a <strong>NASA<\/strong> del planeta BD+05 4868 Ab que est\u00e1 desintegr\u00e1ndose a velocidad r\u00e9cord es un indicador de los muchos eventos que pueden estudiarse para comprender el origen del universo, siendo este uno de los estudios que se suman a los <a href=\"https:\/\/www.ecoticias.com\/cambio-climatico\/nasa-cambio-climatico\">realizados por la agencia espacial estadounidense<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NASA a trav\u00e9s de un sat\u00e9lite de sondeo de exoplanetas ha descubierto un planeta que se desintegra a tan &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La NASA, en vilo con este planeta: se est\u00e1 desintegrando a velocidad r\u00e9cord\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/nasa-planeta-desintegrando\/16478\/#more-16478\" aria-label=\"Leer m\u00e1s sobre La NASA, en vilo con este planeta: se est\u00e1 desintegrando a velocidad r\u00e9cord\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":16481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-16478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/16478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=16478"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/16478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/16481"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=16478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=16478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=16478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}