{"id":16597,"date":"2025-02-01T16:00:15","date_gmt":"2025-02-01T15:00:15","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=16597"},"modified":"2025-02-01T16:00:15","modified_gmt":"2025-02-01T15:00:15","slug":"estados-unidos-crescent-dunes","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/estados-unidos-crescent-dunes\/16597\/","title":{"rendered":"Estados Unidos perdi\u00f3 1000 millones en el desierto: El resultado parece un OVNI"},"content":{"rendered":"<p>Desde que comenz\u00f3 la tendencia para la conservaci\u00f3n del ambiente a trav\u00e9s de la sustituci\u00f3n de energ\u00edas contaminantes por otras verdes, los pa\u00edses han emprendido proyectos algunos de los cuales han resultado en un fracaso. Como ejemplo, te traemos este d\u00f3nde los Estados Unidos perdieron 1.000 millones de d\u00f3lares.<\/p>\n<h2>Un ambicioso proyecto de los Estados Unidos para la generaci\u00f3n de energ\u00eda el\u00e9ctrica barata<\/h2>\n<p>Entre los a\u00f1os 2011 y 2013, Estados Unidos construy\u00f3 una planta de energ\u00eda solar que se ubic\u00f3 en la localidad de Tonopah, que se encuentra entre Reno y Las Vegas, a un costo de 1.000 millones de d\u00f3lares, estos fueron financiados por m\u00faltiples inversores interesados entre los que est\u00e1n Citigroup, Warren Buffet, etc.<\/p>\n<p>Actuando el gobierno de EUA como garante de los pr\u00e9stamos. Producir\u00eda <strong>500.000 MWh de electricidad muy barata<\/strong> que ser\u00edan comprados por la el\u00e9ctrica de Nevada llamada NV Energy. Ser\u00eda suministrada las 24 horas del dio\u00a0 esto por la tecnolog\u00eda de almacenamiento de sales fundidas que daba un respaldo de 12 horas.<\/p>\n<h2>Una instalaci\u00f3n multimillonaria de energ\u00eda renovable en quiebra<\/h2>\n<p>El nombre de este gran complejo energ\u00e9tico en los Estados Unidos es Crescent Dunes el que alberga m\u00e1s de 10.000 espejos los que reflejan la luz del sol hacia una torre que se encuentra en el centro y que mide 200 metros. Almacenar\u00eda <strong>1,1 GWh de electricidad utilizando sales fundidas<\/strong>, lo que la hac\u00eda la segunda en el mundo.<\/p>\n<p>Que se basa en esta tecnolog\u00eda. Esta planta termosolar dar\u00eda un servicio seguro y flexible a unas 100.000 personas en el estado de Nevada. La enorme construcci\u00f3n vista desde el aire se asemeja a un gran OVNI (<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-fotovoltaico-desierto-energia\/8948\/\">como este<\/a> que fue conquistado por Espa\u00f1a) y su capacidad era de 110 MW de potencia el\u00e9ctrica.<\/p>\n<p>La central era operada por el mismo promotor del proyecto que es la empresa <strong>con sede en California, Solar Reserve.<\/strong> El caso fue que el sistema tuvo muchos problemas t\u00e9cnicos y log\u00edsticos que retrasaron la entrega de la energ\u00eda prometida, por lo que NV Energy cansada de espera, demand\u00f3 a Solar Reserve.<\/p>\n<p>Por incumplimiento y, adem\u00e1s, cancel\u00f3 el contrato de la compra de electricidad por lo que Crescent Dunes perdi\u00f3 a su \u00fanico cliente. Despu\u00e9s los sueldos de los trabajadores y los costos asociados a la operaci\u00f3n y mantenimiento hicieron que la planta fuera econ\u00f3micamente inviable y, finalmente, la central fue cerrada.<\/p>\n<p>Todos los inversores se separaron del proyecto y tambi\u00e9n demandaron a la promotora por haber hecho una mala administraci\u00f3n del capital y los EUA debieron pagarles el dinero perdido ya que era garante de los fondos. La situaci\u00f3n se hizo m\u00e1s grave cuando, un a\u00f1o m\u00e1s tarde, <strong>Crescent Dunes quebr\u00f3 oficialmente.<\/strong><\/p>\n<p>Es de destacar que despu\u00e9s que los Estados Unidos tomaron las instalaciones por la v\u00eda de la expropiaci\u00f3n, Solar Reserve dijo que la compa\u00f1\u00eda espa\u00f1ola ACS Cobra quien era la encargada del \u00e1rea de ingenier\u00eda, era la culpable por dise\u00f1ar un <strong>sistema de almacenamiento que era obsoleto y ten\u00eda muchos defectos<\/strong>.<\/p>\n<h2>Los problemas principales que condujeron al fracaso de Crescent Dunes<\/h2>\n<p>Los Estados Unidos est\u00e1n claros en que uno de los problemas es el costo del MWh que genera esta instalaci\u00f3n, que es de <strong>135 d\u00f3lares mientras que el de una granja fotovoltaica no supera los 30 d\u00f3lares<\/strong>. Esto sin contar con los inconvenientes de dise\u00f1o que tiene el almacenamiento de energ\u00eda con el dep\u00f3sito de sales.<\/p>\n<p>En conclusi\u00f3n, los Estados Unidos han echado por la borda 1.000 millones de d\u00f3lares por el fracaso de la planta termosolar de Crescent Dunes (aunque ya tiene planes de absorber la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/estados-unidos-paneles-solares\/14642\/\">energ\u00eda del sol<\/a>). El motivo de fracaso fue por errores en el dise\u00f1o de su sistema de almacenamiento y por altos costos de cada MWh generado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que comenz\u00f3 la tendencia para la conservaci\u00f3n del ambiente a trav\u00e9s de la sustituci\u00f3n de energ\u00edas contaminantes por otras &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Estados Unidos perdi\u00f3 1000 millones en el desierto: El resultado parece un OVNI\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/estados-unidos-crescent-dunes\/16597\/#more-16597\" aria-label=\"Leer m\u00e1s sobre Estados Unidos perdi\u00f3 1000 millones en el desierto: El resultado parece un OVNI\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":16598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-16597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/16597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=16597"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/16597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/16598"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=16597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=16597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=16597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}