{"id":17758,"date":"2025-02-26T15:00:34","date_gmt":"2025-02-26T14:00:34","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=17758"},"modified":"2025-02-26T15:00:34","modified_gmt":"2025-02-26T14:00:34","slug":"volar-carga-dirigible-sostenible","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/volar-carga-dirigible-sostenible\/17758\/","title":{"rendered":"La \u2039\u2039Ballena Voladora\u203a\u203a, la cosa m\u00e1s grande que ver\u00e1s volar: 200 metros y 60 toneladas de carga"},"content":{"rendered":"<p>La tecnolog\u00eda de la movilidad sostenible no solo est\u00e1 referida al transporte terrestre, sino que en el a\u00e9reo tambi\u00e9n hay muchas aplicaciones sobre todo con aparatos no convencionales para volar. Aqu\u00ed te traemos un ejemplo de la Ballena Voladora, un gigantesco aparato que mide 200 metros y puede cargar con 60 toneladas.<\/p>\n<h2>Naves no convencionales y ecol\u00f3gicas en la aviaci\u00f3n moderna<\/h2>\n<p>En los tiempos modernos los aparatos voladores no son sostenibles, en el caso de los aviones por requerir extensas pistas para su aterrizaje y despegue y, del lado de los helic\u00f3pteros por necesitar de \u00e1reas despejadas. En ambos casos atentan contra el medio ambiente por la deforestaci\u00f3n y alteraci\u00f3n que causan en los h\u00e1bitats.<\/p>\n<p>Pero hay un transporte que <strong>r\u00e1pidamente se ha popularizado y es el dirigible<\/strong>. Est\u00e1 claro que no nos referimos a los inseguros ingenios que vieron volar nuestros abuelos por los cielos en la primera mitad del siglo pasado. Ahora son muy seguros y su medio de propulsi\u00f3n y fabricaci\u00f3n es libre de emisiones de CO2.<\/p>\n<h2>La Ballena Voladora: el m\u00e1s grande dirigible que ver\u00e1s volar<\/h2>\n<p>La Ballena Voladora, cuyo nombre oficial es dirigible LCA60T, consiste en una aeronave que tendr\u00e1 una longitud de 200 metros, la cual tiene la capacidad de <strong>despegar y aterrizar verticalmente<\/strong>. Su tecnolog\u00eda de elevaci\u00f3n es con el uso de helio y tiene una capacidad de carga impresionante: 60 toneladas.<\/p>\n<p>Esta nave a\u00e9rea ha sido dise\u00f1ada con un criterio de alta sostenibilidad (como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/primer-avion-fotovoltaico-historia\/11867\/\">este avi\u00f3n fotovoltaico<\/a> que tiene en vilo al mundo). Por otra parte, es muy eficiente para volar y no provoca impacto ambiental. Para su construcci\u00f3n, la empresa finlandesa Exel Composites ha firmado un acuerdo con Flying Whales.<\/p>\n<p>Es un fabricante y operador canadiense de este tipo de aeronaves. Seg\u00fan este acuerdo, la empresa de Finlandia ser\u00e1 la proveedora del equivalente a 75 kil\u00f3metros de tubos hechos con resina epoxi y fibra de carbono aeron\u00e1utica los cuales estar\u00e1n enrollados utilizando <strong>la t\u00e9cnica de tracci\u00f3n pull \u2013 winding.<\/strong><\/p>\n<p>Sin embargo, el contrato exige que Exel sea sometida a un riguroso proceso de calificaci\u00f3n, as\u00ed como a diferentes pruebas a sus productos a fin de garantizar que cumplan con los m\u00e1s altos est\u00e1ndares aeron\u00e1uticos vigentes. Si todo sale bien, se estima que las entregas del material inicien durante el tercer trimestre del 2025.<\/p>\n<p>En referencia al sistema de propulsi\u00f3n Flying Whales ha seleccionado a Evolito Limited, compa\u00f1\u00eda especializada en el dise\u00f1o y desarrollo de motores el\u00e9ctricos de tecnolog\u00eda de flujo axial, quien suministrar\u00e1 32 motores modelo D250 que es del tipo el\u00e9ctrico el cual ha sido escogido por su gran potencia.<\/p>\n<p>Que llega a los 240 kW. As\u00ed como su densidad energ\u00e9tica y de empuje par \u2013 motor, que es de 18,5 kW \/ kg para volar de manera muy silenciosa. Asimismo, cuenta con una <strong>eficiente configuraci\u00f3n de controladores de estas m\u00e1quinas<\/strong> e incluye un sistema de bater\u00edas muy compactas y de alta capacidad.<\/p>\n<h2>Los usos que se le dar\u00e1n a la Ballena Voladora<\/h2>\n<p>Una de sus principales caracter\u00edsticas es que tiene la capacidad de volar <strong>bajo casi cualquier condici\u00f3n clim\u00e1tica siendo muy estable<\/strong>. Por lo que puede ser usado para transportar componentes de grandes turbinas e\u00f3licas para los parques de generadores en ubicaciones remotas y \u00e1reas rurales aisladas.<\/p>\n<p>Asimismo, permitir\u00e1 el acceso a herramientas, equipo y materiales para la construcci\u00f3n de parques e\u00f3licos y solares en zonas de dif\u00edcil acceso por tierra por falta de v\u00edas y donde no se desee abrir caminos que pudieran impactar a la fauna local. Igualmente, dar\u00e1 un servicio que es sostenible y sin gasto de combustible.<\/p>\n<p>Como conclusi\u00f3n, la Ballena Voladora ser\u00e1 la aeronave m\u00e1s grande del mundo. Este dirigible tendr\u00e1 200 metros de longitud y podr\u00e1 llevar cargas de hasta 60 toneladas (ser\u00e1 m\u00e1s grande que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/superavion-espana-qantas\/14023\/\">este superavi\u00f3n de Espa\u00f1a<\/a> aunque sin los problemas que present\u00f3 este por lo que hallaron dentro posterior a volar).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnolog\u00eda de la movilidad sostenible no solo est\u00e1 referida al transporte terrestre, sino que en el a\u00e9reo tambi\u00e9n hay &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La \u2039\u2039Ballena Voladora\u203a\u203a, la cosa m\u00e1s grande que ver\u00e1s volar: 200 metros y 60 toneladas de carga\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/volar-carga-dirigible-sostenible\/17758\/#more-17758\" aria-label=\"Leer m\u00e1s sobre La \u2039\u2039Ballena Voladora\u203a\u203a, la cosa m\u00e1s grande que ver\u00e1s volar: 200 metros y 60 toneladas de carga\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":17759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-17758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/17758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=17758"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/17758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/17759"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=17758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=17758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=17758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}