{"id":19365,"date":"2025-04-07T17:00:26","date_gmt":"2025-04-07T15:00:26","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=19365"},"modified":"2025-04-07T17:00:26","modified_gmt":"2025-04-07T15:00:26","slug":"poblacion-china-arboles-censo","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/poblacion-china-arboles-censo\/19365\/","title":{"rendered":"La revelaci\u00f3n m\u00e1s impactante del siglo: La poblaci\u00f3n China supera lo 140 000 millones"},"content":{"rendered":"<p>A veces se podr\u00eda tener la sensaci\u00f3n de que todo en China es cuantioso, pues no solo es su extensi\u00f3n territorial sino adem\u00e1s su abultada <strong>poblaci\u00f3n<\/strong> que a\u00fan con un crecimiento demogr\u00e1fico leve puede llevar a este pa\u00eds a tener miles de millones de personas circulando por sus apretujadas ciudades.<\/p>\n<h2>Una poblaci\u00f3n en China que crece continuamente y puede llegar el momento que se desborde<\/h2>\n<p>Cuando hablamos de <a href=\"https:\/\/www.ecoticias.com\/naturaleza\/57162_noticias-informacion-medio-ambiente-medioambiente-medioambiental-ambiental-ecologia-energias-renovables\">poblaci\u00f3n humana y su crecimiento<\/a>, sin duda, pa\u00edses como China son referencia obligada, puesto que a\u00fan bajo la influencia de una peque\u00f1a tasa de nacimiento la realidad es que anualmente se suman a los millones de individuos que haya en ese momento un n\u00famero importante de nuevos habitantes.<\/p>\n<p>Tal vez los chinos se hayan dado cuenta que con una poblaci\u00f3n humana tan cuantiosa, aun <strong>aplicando una severa planificaci\u00f3n que limite el n\u00famero de hijos<\/strong>, el incremento demogr\u00e1fico anual ser\u00e1 siempre bastante significativo, lo que se traduce a tener un elevado n\u00famero de habitantes.<\/p>\n<p>Pero m\u00e1s evidente puede ser el crecimiento poblacional de otras especies en China, pues se trata de un pa\u00eds tan inmenso que no solo la cantidad de personas crece sino adem\u00e1s todo aquello con una tasa reproductiva, como es el caso de los \u00e1rboles que se encuentran diseminados por todo el pa\u00eds asi\u00e1tico y cuya cantidad es dif\u00edcil de determinar.<\/p>\n<h2>Hasta hace poco no se sab\u00eda cu\u00e1ntos eran y ahora que se calcul\u00f3 la cifra es demasiado escandalosa<\/h2>\n<p>Es de suponer que<strong> la tarea de calcular la cantidad de \u00e1rboles en China es m\u00e1s ardua<\/strong> que realizar un censo poblacional en cualquier comarca porque esta debe ser muy variable en cuanto a tipo y tasa de reproducci\u00f3n, sin embargo, los cient\u00edficos han tenido un extraordinario logro al conseguir un m\u00e9todo con tecnolog\u00eda de punta para hacerlo.<\/p>\n<p>La metodolog\u00eda que han empleado los expertos chinos se basa en el software LiDAR360 que est\u00e1 provisto de inteligencia artificial, y la han utilizado luego de una recolecci\u00f3n de datos que se inici\u00f3 en 2015 para el c\u00e1lculo de la densidad forestal de una extensa \u00e1rea de 1400 Km2, cuyo resultado luego han extrapolado al total territorial de China.<\/p>\n<p>A trav\u00e9s de esta tecnolog\u00eda con apoyo de drones y basada en la detecci\u00f3n lum\u00ednica y el c\u00e1lculo de distancia a trav\u00e9s de l\u00e1ser se pudo establecer que <strong>la cantidad total de \u00e1rboles en el gigantesco pa\u00eds es de 142,6 mil millones<\/strong>, lo que se traduce a aproximadamente 100 ejemplares por cada residente.<\/p>\n<h2>\u00bfHay un dron en tu jard\u00edn? No te preocupes porque son los chinos que est\u00e1n podando tus plantas<\/h2>\n<p>La cantidad de \u00e1rboles en la naci\u00f3n asi\u00e1tica puede ser mayor que la calculada puesto que en 2019 se realiz\u00f3 el conocido Inventario Nacional de Recursos Forestales y en esa oportunidad la cifra obtenida fue de 1050 \u00e1rboles por unidad de hect\u00e1rea, mientras que en el nuevo estudio los cient\u00edficos chinos determinaron un promedio de 1052 \u00e1rboles por hect\u00e1rea.<\/p>\n<p>No es la primera vez que se utiliza esta tecnolog\u00eda con el fin de cuantificar la masa de \u00e1rboles, pues ya cient\u00edficos de universidades inglesas han empleado esta tecnolog\u00eda con el prop\u00f3sito de obtener este tipo de informaci\u00f3n para la <strong>realizaci\u00f3n de mapas y el dise\u00f1o de estrategias contra el cambio clim\u00e1tico<\/strong>, adem\u00e1s de otras tareas.<\/p>\n<p>Evidencia de una de las tareas efectuadas con esta informaci\u00f3n fue la llevada a cabo en la Cuenca de China donde se crearon mapas 3D y se podaron \u00e1rboles de gran altura en entornos urbanos de acuerdo a la identificaci\u00f3n de excesos en el crecimiento de su follaje. La poda se realiz\u00f3 con precisi\u00f3n milim\u00e9trica utilizando drones provistos de:<\/p>\n<ul>\n<li>Cuchillas altamente precisas<\/li>\n<li>Tecnolog\u00eda LiDAR<\/li>\n<li>C\u00e1maras con lente especializado.<\/li>\n<\/ul>\n<p><span data-sheets-root=\"1\">En conclusi\u00f3n, la tecnolog\u00eda empleada por los cient\u00edficos de China ha permitido obtener un dato extraordinario como lo es la <strong>poblaci\u00f3n<\/strong> de \u00e1rboles en esta gigantesca naci\u00f3n asi\u00e1tica, permitiendo adem\u00e1s esta innovaci\u00f3n mejorar la <\/span>eficiencia y seguridad en la <a href=\"https:\/\/www.ecoticias.com\/vida-saludable\/197823_importancia-espacios-verdes-salud-urbanitas\">gesti\u00f3n de espacios verdes urbanos<\/a> y trazar estrategias para el cambio clim\u00e1tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A veces se podr\u00eda tener la sensaci\u00f3n de que todo en China es cuantioso, pues no solo es su extensi\u00f3n &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La revelaci\u00f3n m\u00e1s impactante del siglo: La poblaci\u00f3n China supera lo 140 000 millones\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/poblacion-china-arboles-censo\/19365\/#more-19365\" aria-label=\"Leer m\u00e1s sobre La revelaci\u00f3n m\u00e1s impactante del siglo: La poblaci\u00f3n China supera lo 140 000 millones\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":19374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-19365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/19365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=19365"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/19365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/19374"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=19365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=19365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=19365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}