{"id":1952,"date":"2024-01-28T17:10:50","date_gmt":"2024-01-28T16:10:50","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=1952"},"modified":"2024-01-28T17:10:50","modified_gmt":"2024-01-28T16:10:50","slug":"hogar-bioclimatico-claves","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/hogar-bioclimatico-claves\/1952\/","title":{"rendered":"Estas son las claves para tener un hogar bioclim\u00e1tico perfecto, y no te costar\u00e1 m\u00e1s que una casa tradicional"},"content":{"rendered":"<p>Un <strong>hogar bioclim\u00e1tico<\/strong> es posible y no te costar\u00e1 m\u00e1s que una casa convencional. Siempre est\u00e1 orientada al sur en el hemisferio norte. La <a href=\"https:\/\/ecoticias.com\/hoyeco\/arabia-saudita-lujoso-proyecto\/1529\/\" target=\"_blank\" rel=\"noopener\">construcci\u00f3n<\/a> sostenible es una manera \u00f3ptima de satisfacer las necesidades actuales de la vivienda sin poner en tela de juicio la capacidad de generaciones futuras. A este ideal apunta el <strong>hogar bioclim\u00e1tico<\/strong>, un tipo de construcci\u00f3n que cada vez est\u00e1 tomando m\u00e1s importancia. Es una casa realizada con madera y hasta paja. Aprovecha al m\u00e1ximo los recursos de su entorno para bajar y hasta suprimir el consumo de energ\u00eda, reduciendo su impacto sobre el medio ambiente.<\/p>\n<p>Resulta fundamentalmente que la fachada siempre se encuentra orientada al sur, brindando una exposici\u00f3n solar m\u00e1xima. Para los que residen al sur del ecuador es al rev\u00e9s. La <a href=\"https:\/\/ecoticias.com\/hoyeco\/construccion-material-aislante\/1547\/\" target=\"_blank\" rel=\"noopener\">construcci\u00f3n<\/a> bioclim\u00e1tica no es algo nuevo. De hecho, nuestros antepasados ya la llevaban a cabo, pero no eran conscientes. Sin embargo, esta forma de construcci\u00f3n dej\u00f3 de frecuentarse en los a\u00f1os 50\/60.<\/p>\n<p>Era necesario construir r\u00e1pido y con un presupuesto limitado en tiempos en los que la ciudadan\u00eda no prestaba atenci\u00f3n al medio ambiente. A d\u00eda de hoy, sustancias como el petr\u00f3leo, la electricidad y el gas son m\u00e1s caros.<\/p>\n<p>Por otra parte, las m\u00e1quinas de construcci\u00f3n necesitan mucha energ\u00eda para funcionar, aunque los fabricantes se decanten cada vez m\u00e1s por desarrollar m\u00e1quinas m\u00e1s sostenibles como excavadores y retroexcavadoras, entre otros. En consecuencia, estamos volviendo al pasado, hacia un <strong>hogar bioclim\u00e1tico<\/strong>. Ante la necesidad de cuidar el espacio que nos rodea, las construcciones tienen muy en cuenta el sol, el viento, los relieves, la vegetaci\u00f3n&#8230;<\/p>\n<h2>\u00bfQu\u00e9 significa tener un hogar bioclim\u00e1tico?<\/h2>\n<p>El concepto \u2018<strong>bioclim\u00e1tico<\/strong>\u2019 es sencillo: est\u00e1 cimentado sobre el principio del <em>confort<\/em> t\u00e9rmico. Por ende, es necesario protegerse del viento, aprovechando el sol al m\u00e1ximo en invierno y protegerse de \u00e9l en verano. Hoy es posible dise\u00f1ar casas pasivas sin demasiadas complicaciones. Est\u00e1n pensadas para tomar la energ\u00eda solar, almacenarla y expandirla por su interior.<\/p>\n<p>Para lograr este prop\u00f3sito, es primordial la elecci\u00f3n de los materiales de construcci\u00f3n y una disposici\u00f3n \u00f3ptima de las habitaciones que permiten captar energ\u00eda. Gracias al sol es posible calentar una gran parte de la casa. El edificio tiene que aprovechar los aportes solares y almacenar calor en las masas, como muros y losas de piedra, hormig\u00f3n y tierra para ser eficiente.<\/p>\n<p>As\u00ed puede ahorrar calefacci\u00f3n y proporcionar un <em>confort<\/em> \u00f3ptimo todo el a\u00f1o. Con masas suficientes, la temperatura cambia a lo largo del a\u00f1o, instal\u00e1ndose entre los 18 y los 22 grados sin calefacci\u00f3n. En funci\u00f3n del aislamiento, este tipo de casa necesitar\u00e1 poco aporte de calefacci\u00f3n o climatizaci\u00f3n, y solo quedar\u00eda por contemplar otra posible calefacci\u00f3n.<\/p>\n<p>El <strong>hogar bioclim\u00e1tico<\/strong> es una concepci\u00f3n global inteligente a la que se le incorporan otras opciones. En este contexto y en todos los casos, la orientaci\u00f3n juega un papel fundamental en casas de este tipo. La fachada siempre tiene que orientarse hacia el sur brindando una exposici\u00f3n solar m\u00e1xima. Una casa bioclim\u00e1tica est\u00e1 cimentada para tomar la energ\u00eda del sol. Se alimenta de esta durante el d\u00eda, conserva su energ\u00eda, la restituye y difunde el calor dentro del hogar cuando la temperatura exterior disminuye.<\/p>\n<h2>\u00bfCu\u00e1nto vale un hogar bioclim\u00e1tico?<\/h2>\n<p>Los espacios m\u00e1s frecuentados, como la sala de estar, la cocina y el comedor, deben estar tambi\u00e9n orientadas al sur para aprovechar al m\u00e1ximo la luz. Las habitaciones deben ubicarse al este o al oeste y los cuartos de ba\u00f1o o cuartos t\u00e9cnicos al norte. Una casa de estas caracter\u00edsticas debe contar con una superficie de vidrio con una extensi\u00f3n muy importante para estar abierta el exterior y conectada con la naturaleza. Si se orientan las aperturas al sur, puede ahorrarse hasta un 30% de energ\u00eda.<\/p>\n<p>La construcci\u00f3n de un <strong>hogar bioclim\u00e1tico<\/strong> no cuesta m\u00e1s que una com\u00fan. No son la orientaci\u00f3n y las aperturas las que influyen en el precio sino la calidad de los materiales, la ejecuci\u00f3n de la misma y los resultados \u00f3ptimos lo que marca la diferencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hogar bioclim\u00e1tico es posible y no te costar\u00e1 m\u00e1s que una casa convencional. Siempre est\u00e1 orientada al sur en &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Estas son las claves para tener un hogar bioclim\u00e1tico perfecto, y no te costar\u00e1 m\u00e1s que una casa tradicional\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/hogar-bioclimatico-claves\/1952\/#more-1952\" aria-label=\"Leer m\u00e1s sobre Estas son las claves para tener un hogar bioclim\u00e1tico perfecto, y no te costar\u00e1 m\u00e1s que una casa tradicional\">Read more<\/a><\/p>\n","protected":false},"author":3,"featured_media":1955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/1955"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}