{"id":20291,"date":"2025-05-04T16:30:43","date_gmt":"2025-05-04T14:30:43","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=20291"},"modified":"2025-05-04T16:30:43","modified_gmt":"2025-05-04T14:30:43","slug":"multa-dgt-truco-matricula","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/multa-dgt-truco-matricula\/20291\/","title":{"rendered":"La picaresca espa\u00f1ola acaba en multa: La DGT, en vilo con el truco de la matr\u00edcula"},"content":{"rendered":"<p>La Direcci\u00f3n General de Tr\u00e1fico o DGT ha advertido sobre la severidad de la multa impuesta a quienes aplican una acci\u00f3n ilegal sobre la <strong>matr\u00edcula<\/strong> del veh\u00edculo, esto con el fin de evitar que la picaresca treta siga extendi\u00e9ndose como una moda. Aqu\u00ed te contamos en qu\u00e9 consiste el truco y el monto a pagar en caso de utilizarlo.<\/p>\n<h2><span data-sheets-root=\"1\">\u00bfYa conoces el truco de la matr\u00edcula? Estas son las sanciones que puede acarrear<\/span><\/h2>\n<p>Algunos conductores a sabiendas de que pueden verse tentados a infringir la ley en un determinado momento buscan <strong>aplicar acciones que les evite o reduzca la sanci\u00f3n<\/strong> a la que se hacen merecedores. Esta pr\u00e1ctica de evasi\u00f3n de responsabilidad forma parte de un comportamiento p\u00edcaro que generalmente deriva en trucos.<\/p>\n<p>El problema de estos trucos para evitar sanciones es que si bien evitan que el infractor sea castigado puede producir una suerte de comportamiento generalizado o cultura de la evasi\u00f3n que al final puede generar el caos y con ello la <a href=\"https:\/\/www.ecoticias.com\/movilidad-electrica\/reducir-accidentes-linea-onda\">ocurrencia de accidentes con lamentables consecuencias<\/a>.<\/p>\n<p>Uno de estos trucos que actualmente se est\u00e1 haciendo popular en Espa\u00f1a es el de <strong>utilizar pegatinas reflectantes u hojas magn\u00e9ticas que reducen la visibilidad<\/strong> de la matr\u00edcula para el esc\u00e1ner de los radares instalados en diversos puntos viales, lo que evita que sea impuesto de una multa el conductor al no poder identificar la unidad vehicular.<\/p>\n<h2>Este es el castigo para los conductores que tratan de disfrutar de la picaresca espa\u00f1ola<\/h2>\n<p>La ilegibilidad de las matr\u00edculas de los veh\u00edculos que circulan est\u00e1 siendo objeto de sanci\u00f3n administrativa en Espa\u00f1a, tal como lo establece la Ley sobre Tr\u00e1fico, Circulaci\u00f3n de Veh\u00edculos a Motor y Seguridad Vial, aunque puede haber consideraciones individuales en cada caso seg\u00fan las circunstancias espec\u00edficas.<\/p>\n<p>El uso de pegatinas reflectantes con el prop\u00f3sito de dificultar la <strong>lectura de las matr\u00edculas por parte de los radares provistos de flash<\/strong>, cuya funci\u00f3n de control y garant\u00eda de la seguridad vial se ve entorpecida por esta p\u00edcara maniobra, afectando con ello el cumplimiento de la ley en cuanto a los l\u00edmites de velocidad y evitar los accidentes, lo que acarrea:<\/p>\n<ul>\n<li>Multas de hasta 6000 euros<\/li>\n<li>Descuento de hasta 6 puntos en el carnet<\/li>\n<li>Penas privativas de libertad<\/li>\n<\/ul>\n<p>Afortunadamente, los modernos radares infrarrojos son capaces de mitigar la reflectancia de las pegatinas y hace ineficaces estos procedimientos evasivos de la ley, aunque han salido al mercado dispositivos con un cristal inteligente llamado PDLC que con pulsar un bot\u00f3n opacan la matr\u00edcula.<\/p>\n<h2>Estas son las nefastas consecuencias de unirse a una moda peligrosa<\/h2>\n<p>Si se asume que rebasar los l\u00edmites de velocidad es una acci\u00f3n que puede derivar en accidentes de tr\u00e1nsito con resultados lamentables como son las p\u00e9rdidas materiales y de vidas humanas, es l\u00f3gico pensar que el empleo de tales trucos para reducir la visibilidad de las matr\u00edculas y eludir responsabilidades es una pr\u00e1ctica nefasta.<\/p>\n<p>Es considerada una infracci\u00f3n grave por parte de la Polic\u00eda Nacional la acci\u00f3n de ocultamiento o alteraci\u00f3n de la legibilidad de la matr\u00edcula, porque contraviene el art\u00edculo 10 de la ley ya se\u00f1alada, ameritando <strong>para el infractor una sanci\u00f3n inicial de 200 euros<\/strong>, aumentando \u00e9sta en caso de reincidir o si se comprueba la plena intenci\u00f3n.<\/p>\n<p>La aplicaci\u00f3n de este tipo de trucos de por s\u00ed debe considerarse una actitud criminal puesto que no solo se trata de eludir la imposici\u00f3n de una sanci\u00f3n, sino que se est\u00e1 tratando de evitar que los dispositivos colocados cumplan con la funci\u00f3n de incentivar a los conductores a no exceder la velocidad en puntos cr\u00edticos como lo son v\u00edas cercanas a:<\/p>\n<ul>\n<li>Colegios<\/li>\n<li>Hospitales<\/li>\n<li>Mercados p\u00fablicos<\/li>\n<li>Zonas de alta concentraci\u00f3n vehicular o peatonal<\/li>\n<\/ul>\n<p>En conclusi\u00f3n, la DGT no perder\u00e1 ocasi\u00f3n en <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/multa-pagas-efectivo-hacienda\/18964\/\">colocar multa a todos<\/a> aquellos conductores que, con malas intenciones o no, empleen pegatinas reflectantes o cualquier otro truco que disminuya la legibilidad de la <strong>matr\u00edcula<\/strong> del veh\u00edculo, a sabiendas que puede tratarse de un comportamiento p\u00edcaro que llega a crear una moda perjudicial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Tr\u00e1fico o DGT ha advertido sobre la severidad de la multa impuesta a quienes aplican una &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La picaresca espa\u00f1ola acaba en multa: La DGT, en vilo con el truco de la matr\u00edcula\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/multa-dgt-truco-matricula\/20291\/#more-20291\" aria-label=\"Leer m\u00e1s sobre La picaresca espa\u00f1ola acaba en multa: La DGT, en vilo con el truco de la matr\u00edcula\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":20306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-20291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/20291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=20291"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/20291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/20306"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=20291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=20291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=20291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}