{"id":20418,"date":"2025-05-05T16:00:11","date_gmt":"2025-05-05T14:00:11","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=20418"},"modified":"2025-05-05T16:00:11","modified_gmt":"2025-05-05T14:00:11","slug":"china-coches-electricos-tesla","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/china-coches-electricos-tesla\/20418\/","title":{"rendered":"China toma el control sobre los coches el\u00e9ctricos a nivel global: Prohibe los veh\u00edculos Tesla"},"content":{"rendered":"<p>La seguridad en los coches el\u00e9ctricos ha sido una cuesti\u00f3n de prioridad entre los diferentes fabricantes de estos veh\u00edculos, sin embargo, ning\u00fan pa\u00eds ha dispuesto normas al respecto, limit\u00e1ndose a convalidar los est\u00e1ndares particulares de cada marca. Pero eso ha sido hasta ahora porque China ha decidido tomar control sobre esta tecnolog\u00eda, incluso <strong>ha adscripto a una normativa por la cual los veh\u00edculos de Tesla estar\u00edan prohibidos en su territorio.<\/strong><\/p>\n<h2>Tesla a punto de quedar sin mercado en China<\/h2>\n<p>Aunque no es muy com\u00fan que suceda, ocurren accidentes donde se incendian los coches el\u00e9ctricos a pesar de los diferentes sistemas de protecci\u00f3n de que disponen. M\u00e1s del 95 % de los mismos tiene como causa directa o indirecta las bater\u00edas internas. Cuando sufren fallas internas o da\u00f1os f\u00edsicos, pueden entrar en un proceso muy peligroso que se le conoce como fuga t\u00e9rmica.<\/p>\n<p>Puede ser la chispa que ocasione el incendio del coche y cree una gran cantidad de humo que es perjudicial para los pasajeros. Este proceso consiste en que una celda de ese componente <strong>sufre un sobrecalentamiento tal que afecta a otras celdas<\/strong>, provocando que sus reacciones qu\u00edmicas se descontrolen, ocasionando una explosi\u00f3n e incendio. Pero China ha decidido tomar cartas en el asunto para evitar estas situaciones.<\/p>\n<h2>C\u00f3mo China tomar\u00e1 el control de los coches el\u00e9ctricos para evitar accidentes<\/h2>\n<p>A partir de julio de 2026 entrar\u00e1 en vigencia la nueva normativa de seguridad que regular\u00e1 las bater\u00edas de los coches el\u00e9ctricos en su territorio. Aunque en realidad no prohibir\u00e1 los coches de Tesla en China, estos no podr\u00e1n ser comercializados hasta que sus <strong>bater\u00edas cumplan con estas normas<\/strong> que son las m\u00e1s estrictas del mundo y van en favor de evitar los incendios en los veh\u00edculos el\u00e9ctricos causados por estas.<\/p>\n<p>Esta nueva legislaci\u00f3n ser\u00e1 muy exigente, sobre todo en lo concerniente a que las mismas no deber\u00e1n explotar ni incendiarse bajo ning\u00fan concepto. Especialmente en el proceso de fuga t\u00e9rmica interna, que es la condici\u00f3n de mayor riesgo en esta tecnolog\u00eda de autom\u00f3viles. Es de hacer notar que la normativa anterior vigente desde el a\u00f1o 2020 era mucho m\u00e1s benevolente en este sentido.<\/p>\n<p>Ya que solo demandaba que el coche tuviera un sistema que alertara, con cinco minutos de anticipaci\u00f3n, sobre la posibilidad de ocurrencia de una explosi\u00f3n o incendio. Con esta nueva ley, los fabricantes de bater\u00edas deber\u00e1n contemplar sistemas para que ninguno de estos tipos de accidentes,<strong> explosi\u00f3n o incendio pueda ocurrir bajo ning\u00fan motivo,<\/strong> de igual manera, el humo que se genere no debe afectar a los pasajeros.<\/p>\n<p>Pero adem\u00e1s, la nueva normativa de China contempla pruebas y ensayos que son m\u00e1s exigentes, como el de que <strong>estos componentes deben resistir m\u00e1s de 300 ciclos de carga y descarga<\/strong> y que, en caso de cortocircuitos posteriores, no tengan riesgo de explosi\u00f3n o incendio. Asimismo, deben ser resistentes a impactos sufridos por la parte de abajo del coche. Por lo tanto, Tesla deber\u00e1 modificar sus dise\u00f1os de las bater\u00edas.<\/p>\n<h2>Lo que dicen los fabricantes de bater\u00edas del gigante asi\u00e1tico respecto a estas normas<\/h2>\n<p>A los fabricantes de bater\u00edas de China como CATL y Svolt Energy (los mismos de la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/bateria-de-sable-coches-1000-km\/5505\/\">misteriosa bater\u00eda de sable<\/a>) no los han pillado de sorpresa estas nuevas exigencias, ya que desde hace aproximadamente dos a\u00f1os hab\u00edan introducido estas mejoras en sus productos por lo que pueden decir que todos sus clientes cumplen con las mismas. <strong>Solo algunas marcas como Tesla<\/strong> deben introducir estas variantes en sus productos.<\/p>\n<p>En definitiva, China ha decidido tomar el control de la seguridad en los coches el\u00e9ctricos en lo concerniente a sus bater\u00edas (aunque ya hay un invento que puede ser el <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/bateria-agua-energia\/6521\/\">sustituto de la tecnolog\u00eda de litio<\/a>), estableciendo normas muy estrictas en sus pruebas. Ahora ser\u00e1 Tesla quien se adecue a estas normas si quiere continuar vendiendo coches en China.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La seguridad en los coches el\u00e9ctricos ha sido una cuesti\u00f3n de prioridad entre los diferentes fabricantes de estos veh\u00edculos, sin &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"China toma el control sobre los coches el\u00e9ctricos a nivel global: Prohibe los veh\u00edculos Tesla\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/china-coches-electricos-tesla\/20418\/#more-20418\" aria-label=\"Leer m\u00e1s sobre China toma el control sobre los coches el\u00e9ctricos a nivel global: Prohibe los veh\u00edculos Tesla\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":20420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-20418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/20418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=20418"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/20418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/20420"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=20418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=20418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=20418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}