{"id":2279,"date":"2024-02-01T15:00:29","date_gmt":"2024-02-01T14:00:29","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=2279"},"modified":"2024-02-01T15:00:29","modified_gmt":"2024-02-01T14:00:29","slug":"aplicacion-bono-bus","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/aplicacion-bono-bus\/2279\/","title":{"rendered":"La aplicaci\u00f3n que te salvar\u00e1 si eres de los que se dejan el bono bus en casa: olv\u00eddate de volver atr\u00e1s"},"content":{"rendered":"<p>Nuestro pa\u00eds ha encontrado una v\u00eda para la descarbonizaci\u00f3n en el transporte p\u00fablico, y ahora parece no querer soltarla. \u00bfSab\u00edas que hay una\u00a0<strong>aplicaci\u00f3n de bono bus<\/strong> que te evitar\u00e1 volver a casa si te lo dejas atr\u00e1s? Puedes descargarla desde este mismo momento para ahorrarte m\u00e1s de un disgusto. Es uno de nuestros trucos para moverte por la ciudad, como<a href=\"https:\/\/ecoticias.com\/hoyeco\/trasporte-publico-gratis\/1634\/\" target=\"_blank\" rel=\"noopener\"> este para subirte el autobus o al metro sin pagar<\/a>.<\/p>\n<h2>El transporte p\u00fablico urbano \u00abchoca\u00bb con las zonas de bajas emisiones<\/h2>\n<p>El transporte p\u00fablico est\u00e1 creciendo, tanto en n\u00famero de veh\u00edculos como de pasajeros, lo que dibuja un escenario optimista en nuestro pa\u00eds. Sin embargo, durante este a\u00f1o las ciudades deben tener listas sus zonas de bajas emisiones (ZBE) en los n\u00facleos urbanos, por normativa del Ministerio de Transportes.<\/p>\n<p>El problema es que la mayor\u00eda de los autobuses son veh\u00edculos de combusti\u00f3n, muy pocos son el\u00e9ctricos y, menos a\u00fan, de hidr\u00f3geno. La soluci\u00f3n que <strong>se lleva implementando desde el inicio de estas ZBE<\/strong> es permitir el paso del transporte p\u00fablico, con independencia del motor que utilice.<\/p>\n<p>No obstante, esto crea una especie de incoherencia, como han denunciado varias organizaciones ecologistas de toda la Uni\u00f3n Europea. La previsi\u00f3n, en cualquier caso, es que para 2035 empiecen a adoptarse las primeras flotas 100 % sostenibles en todo el pa\u00eds y tambi\u00e9n en los otros 26 comunitarios.<\/p>\n<h2>La aplicaci\u00f3n de bono bus que te ahorrar\u00e1 volver a casa: ya puedes despistarte sin problemas<\/h2>\n<p>\u00bfEres de los que tienen que volver atr\u00e1s porque se les olvida el bono bus? Desde ahora, no tendr\u00e1s que hacerlo m\u00e1s nunca, igual que sucede con <strong>el carn\u00e9 de conducir y la aplicaci\u00f3n oficial miDGT<\/strong>, que conocer\u00e1s desde hace tiempo (y que te permite llevarte el disgusto por saber si te han multado).<\/p>\n<p>La Comunidad de Madrid tiene una aplicaci\u00f3n oficial que, si bien cuenta con un n\u00famero de descargas superior a las 100 000, todav\u00eda no es conocida por todos los usuarios del transporte p\u00fablico. De hecho, lo m\u00e1s probable es que t\u00fa tampoco la tuvieras en el tel\u00e9fono&#8230; hasta ahora.<\/p>\n<p>La tarjeta f\u00edsica de transporte p\u00fablico en Madrid es cosa del pasado. Desde hace a\u00f1os, puedes recargarla con el m\u00f3vil, y desde el a\u00f1o pasado, <strong>puedes prescindir de ella completamente<\/strong>. La Comunidad de Madrid tiene una aplicaci\u00f3n oficial que permite tener la Tarjeta Transporte Virtual en tu m\u00f3vil.<\/p>\n<p>Incluso puedes tener acceso al bono metrobus de 10 viajes por 6,10 euros. Te da la posibilidad de cargar el bono bus directamente en tu smartphone ofrece comodidad y flexibilidad. De este modo, se elimina la necesidad de que cojas la tarjeta f\u00edsica antes de salir de casa (tampoco es que pese, pero siempre es m\u00e1s c\u00f3modo).<\/p>\n<h2>C\u00f3mo registrarte y utilizar la aplicaci\u00f3n de bono bus en esta ciudad<\/h2>\n<p>La aplicaci\u00f3n de bono bus en la Comunidad de Madrid es especialmente \u00fatil en dispositivos Android, ya que est\u00e1 integrada con Google Wallet. El objetivo es eliminar completamente la necesidad de la tarjeta f\u00edsica. Requiere un m\u00f3vil relativamente nuevo con <strong>Android 7.0 o superior y tecnolog\u00eda NFC<\/strong>.<\/p>\n<p>La aplicaci\u00f3n se integra con Google Wallet, la aplicaci\u00f3n de cartera oficial de Google, ofreciendo una experiencia simplificada y eficiente. La convergencia hacia la eliminaci\u00f3n de la tarjeta f\u00edsica refleja la adaptaci\u00f3n a un estilo de vida cada vez m\u00e1s digital, algo que ya te esperar\u00edas.<\/p>\n<p>Sin embargo, es esencial destacar los requisitos b\u00e1sicos para utilizar esta aplicaci\u00f3n: un m\u00f3vil relativamente nuevo con Android 7.0 o superior y tecnolog\u00eda NFC. Estos criterios, aunque comunes en la mayor\u00eda de los dispositivos modernos, son fundamentales para aprovechar al m\u00e1ximo la funcionalidad de la aplicaci\u00f3n.<\/p>\n<p>La\u00a0<strong>aplicaci\u00f3n de bono bus\u00a0<\/strong>viene a confirmar lo que venimos afirmando desde hace semanas: Espa\u00f1a ha pisado el acelerador para digitalizar el transporte p\u00fablico. Mientras tanto, hay otras alternativas de movilidad que est\u00e1n cayendo en picado por las trabas que se les est\u00e1 poniendo. La <a href=\"https:\/\/ecoticias.com\/hoyeco\/patinetes-electricos-homologados-dgt\/2105\/\" target=\"_blank\" rel=\"noopener\">\u00faltima decisi\u00f3n de la DGT con los patinetes el\u00e9ctricos<\/a> vuelve a dejarlos fuera de juego, pero ahora la cosa es m\u00e1s grave.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro pa\u00eds ha encontrado una v\u00eda para la descarbonizaci\u00f3n en el transporte p\u00fablico, y ahora parece no querer soltarla. \u00bfSab\u00edas &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La aplicaci\u00f3n que te salvar\u00e1 si eres de los que se dejan el bono bus en casa: olv\u00eddate de volver atr\u00e1s\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/aplicacion-bono-bus\/2279\/#more-2279\" aria-label=\"Leer m\u00e1s sobre La aplicaci\u00f3n que te salvar\u00e1 si eres de los que se dejan el bono bus en casa: olv\u00eddate de volver atr\u00e1s\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":2298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/2279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=2279"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/2279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/2298"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=2279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=2279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=2279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}