{"id":25188,"date":"2025-06-19T17:00:08","date_gmt":"2025-06-19T15:00:08","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=25188"},"modified":"2025-06-19T17:00:08","modified_gmt":"2025-06-19T15:00:08","slug":"pagos-tarjetas-hacienda-decreto","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/pagos-tarjetas-hacienda-decreto\/25188\/","title":{"rendered":"Debes llevar el registro de pagos con tarjetas: Hacienda vigila los que pasen de este monto"},"content":{"rendered":"<p>Una de las funciones fundamentales de Hacienda es vigilar que cada contribuyente realice la entrega justa de sus impuestos entre ellos los generados por pagos con<strong> tarjetas<\/strong>, de all\u00ed que se haya establecido un monto que funciona como l\u00edmite para la presentaci\u00f3n de un registro que involucren movimientos con estos medios.<\/p>\n<h2><span data-sheets-root=\"1\">Las entidades emisoras de tarjetas est\u00e1n sacando de la lista de clientes a estos usuarios<\/span><\/h2>\n<p>En la actualidad existen diversas entidades que emiten <strong>tarjetas que pueden utilizar los usuarios para realizar sus pagos<\/strong>, ya sea en forma presencial o en l\u00ednea, pudiendo ser estas de cr\u00e9dito o d\u00e9bito u otra forma de erogaci\u00f3n, siendo necesario llevar un control sobre este tipo de movimientos.<\/p>\n<p>La revisi\u00f3n de estos movimientos permitir\u00eda comprobar si el monto total anual de los pagos realizados por el usuario ameritan el pago del impuesto correspondiente, por lo tanto no a todos los tarjetahabientes la entidad emisora incluir\u00e1 en el informe que deben presentar ante la Agencia Estadal de Administraci\u00f3n Tributaria (AEAT).<\/p>\n<p>Y es que actualmente Hacienda planifica una novedosa medida con el fin de asumir el <strong>control de las operaciones que se realicen de tarjetas de cr\u00e9dito o d\u00e9bito<\/strong>, observ\u00e1ndose con ello el inter\u00e9s de la administraci\u00f3n tributaria de aumentar la vigilancia sobre los movimientos de dinero que se realizan en Espa\u00f1a.<\/p>\n<p>De all\u00ed que las autoridades legislativas est\u00e9n enfocadas en la elaboraci\u00f3n de un Real Decreto que posibilite a Hacienda obtener mayor control sobre los fraudes fiscales que se podr\u00edan cometer, especialmente aquellos vinculados con el pago con tarjeta a trav\u00e9s de intermediaci\u00f3n bancaria.<\/p>\n<h2>Est\u00e1 en camino un Real Decreto que te dir\u00e1 cu\u00e1nto te has sobrepasado en tus \u00f3rdenes de compra<\/h2>\n<p>La creaci\u00f3n del nuevo Real Decreto tendr\u00eda como objetivo asegurar el pago de los impuestos por cada contribuyente y con ello <strong>brindar garant\u00edas reales del complimiento de las obligaciones fiscales<\/strong> por parte de personas, naturales y jur\u00eddicas, as\u00ed como de diversas entidades.<\/p>\n<p>Cuando <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/dinero-familia-hacienda-multa\/24153\/\">Hacienda vigila todas estas transferencias<\/a> cumple con una de sus funciones m\u00e1s importantes como lo es el combate del fraude fiscal, pero con esto tambi\u00e9n estar\u00eda ayudando a que se obtengan m\u00e1s recursos para redistribuirlos en el financiamiento de servicios p\u00fablicos de primer orden como educaci\u00f3n, salud y defensa.<\/p>\n<p>En otras palabras, la medida apoyada en la creaci\u00f3n del Real Decreto a partir de este a\u00f1o conllevar\u00eda a una justa contribuci\u00f3n tributaria por parte de cada miembro de la sociedad, lo que permitir\u00eda el <strong>fortalecimiento de las arcas p\u00fablicas y el fomento de la confiabilidad del sistema<\/strong>.<\/p>\n<p class=\"article-body__text \">Uno de los objetivos finales de este accionar por parte de la administraci\u00f3n tributaria dirigido a la modernizaci\u00f3n y reforzamiento del control fiscal es que las empresas que emiten las tarjetas presenten informes detallados acerca de los movimientos efectuados por los usuarios.<\/p>\n<h2>Si te pasas de este monto tu nombre aparecer\u00e1 en un informe y lo pagar\u00e1s<\/h2>\n<p class=\"article-body__text \">En la pr\u00e1ctica estas entidades emisoras de tarjetas entre las que se cuentan redes de gasolineras, almacenes, bancos o cualquier otra entidad que las ofrezcan tendr\u00e1n la obligaci\u00f3n de exponer en forma desglosada la totalidad de movimientos que excedan los 25 mil euros al a\u00f1o por tarjeta de:<\/p>\n<ul>\n<li class=\"article-body__text \">Cr\u00e9dito<\/li>\n<li class=\"article-body__text \">D\u00e9bito<\/li>\n<li class=\"article-body__text \">Prepago<\/li>\n<li class=\"article-body__text \">Monedero<\/li>\n<li class=\"article-body__text \">Pagos virtuales<\/li>\n<li class=\"article-body__text \">Compras en l\u00ednea<\/li>\n<li class=\"article-body__text \">Otras<\/li>\n<\/ul>\n<p>Independientemente si se trata de una persona o entidad el informe presentado por estas compa\u00f1\u00edas emisoras deber\u00e1 tener un <strong>conjunto de datos que permitan identificar al titular de dicho medio de pago<\/strong>, adem\u00e1s de la cantidad de cargos realizados anualmente y el importe total de tales movimientos, sean compras o retiros de efectivo.<\/p>\n<p>En el proyecto del Real Decreto que ser\u00e1 remitido al Consejo de Estado se establece que las entidades brindar\u00e1n un informe anual a la AEAT de los movimientos de sus clientes cuando observen que estos han realizado operaciones de compra por una cantidad de 25 000 euros o m\u00e1s durante el a\u00f1o en curso<\/p>\n<p>En conclusi\u00f3n, en realidad ser\u00e1n las entidades que llevar\u00e1n un registro estricto de los movimientos que realices con la <a href=\"https:\/\/www.ecoticias.com\/tecnologia-verde\/166226_Correos-lanza-una-nueva-tarjeta-para-facilitar-pagos-seguros-sus-cliente\">tarjeta para facilitar los pagos<\/a> y si estos en total durante el a\u00f1o han sido de 25 mil euros o m\u00e1s lo informar\u00e1n a Hacienda el \u00f3rgano encargado de evitar el blanqueo de capitales y el fraude fiscal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las funciones fundamentales de Hacienda es vigilar que cada contribuyente realice la entrega justa de sus impuestos entre &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Debes llevar el registro de pagos con tarjetas: Hacienda vigila los que pasen de este monto\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/pagos-tarjetas-hacienda-decreto\/25188\/#more-25188\" aria-label=\"Leer m\u00e1s sobre Debes llevar el registro de pagos con tarjetas: Hacienda vigila los que pasen de este monto\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":25232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-25188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/25188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=25188"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/25188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/25232"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=25188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=25188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=25188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}