{"id":26113,"date":"2025-07-14T16:00:02","date_gmt":"2025-07-14T14:00:02","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=26113"},"modified":"2025-07-14T16:00:02","modified_gmt":"2025-07-14T14:00:02","slug":"europa-reactores-nucleares-espacio","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/europa-reactores-nucleares-espacio\/26113\/","title":{"rendered":"Europa tiene un plan descabellado: Lanzar\u00e1 reactores nucleares encendidos al espacio"},"content":{"rendered":"<p>Motivados por los grandes problemas que enfrenta nuestro planeta, los pa\u00edses est\u00e1n en busca de nuevos hogares en los cuerpos celestes cercanos como la Luna o Marte lo cual hace que esta sea una verdadera competencia. En este respecto, en la carrera espacial nada est\u00e1 dicho, pues continuamente surgen nuevas ideas. Como este plan de Europa que consiste en lanzar hacia el firmamento reactores at\u00f3micos.<\/p>\n<h2>El sistema id\u00f3neo de propulsi\u00f3n espacial<\/h2>\n<p>El sistema m\u00e1s viable para la propulsi\u00f3n de naves espaciales tripuladas para viajes de larga duraci\u00f3n, como el que nos conducir\u00eda a Marte, es el de impulso t\u00e9rmico nuclear (NTP por sus siglas en ingl\u00e9s). <strong>Consiste en usar la fisi\u00f3n nuclear<\/strong>, por medio de un reactor de reducido tama\u00f1o, con el fin de calentar un elemento como el hidr\u00f3geno, el cual, una vez caliente es expulsado por una tobera a una velocidad muy alta.<\/p>\n<p>Por lo que produce un gran empuje en la direcci\u00f3n opuesta.\u00a0 El mecanismo de NTP m\u00e1s eficiente es el que utiliza un reactor tradicional con combustible fisible en forma de barras s\u00f3lidas, que es el que los expertos de Europa prefieren, sobre todo cuando se requieren maniobras de inyecci\u00f3n en direcci\u00f3n a la Tierra o de inserci\u00f3n en la \u00f3rbita de un cuerpo donde es necesario tener un empuje muy alto y sostenido.<\/p>\n<h2>El plan de Europa respecto a la propulsi\u00f3n espacial<\/h2>\n<p>Aunque los \u00fanicos pa\u00edses que poseen motores con tecnolog\u00eda NTP son Estados Unidos y Rusia, otras\u00a0potencias como Europa est\u00e1n estudiando este <strong>mecanismo para sus propulsores espaciales<\/strong>. En este sentido, la Agencia Espacial Europea propone un plan que a muchos les resulta descabellado: \u00a0el uso de reactores at\u00f3micos. Ha encargado un estudio a la Agencia Francesa de Energ\u00eda At\u00f3mica y Energ\u00edas Alternativas o CEA.<\/p>\n<p>Junto con Framatome Space y Ariane Group, con el que se pretende establecer la factibilidad de usar tecnolog\u00eda NTP en los propulsores de sus propias naves espaciales (aunque debes saber que otras potencias asi\u00e1ticas <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/amenaza-spacex-cohete-honda\/25400\/\">tambi\u00e9n est\u00e1n investigando<\/a>), es de destacar que todos estos entes son franceses debido a que la industria at\u00f3mica est\u00e1 muy desarrollada en esta naci\u00f3n. El estudio compar\u00f3 dos dise\u00f1os.<\/p>\n<p>Uno con la propulsi\u00f3n NTP y la cl\u00e1sica qu\u00edmica en un hipot\u00e9tico viaje a la Luna en una nave Delta \u2013 V que desarrolla una velocidad de 12 kil\u00f3metros por segundo, la misma tiene la propiedad de que se desacopla uno de los dos tanques de hidr\u00f3geno. En este contexto se concluy\u00f3 que, tanto para su empleo en una \u00f3rbita el\u00edptica como para trasladarse en la superficie lunar, claramente tiene la ventaja la propulsi\u00f3n at\u00f3mica.<\/p>\n<p>Luego se estudiaron los dos principales sistemas de impulso nuclear, como son el CERMAT y el NERVA hechos en Europa, a pesar de sus diferencias en cuanto al empuje, potencia generada, que la matriz del primero es met\u00e1lica y la del segundo es de grafito, esta comparaci\u00f3n te\u00f3rica se hace con un viaje hasta Marte y dio como resultado que <strong>ambos sistemas son igualmente viables y eficientes<\/strong>.<\/p>\n<h2>Otra opci\u00f3n diferente, pero que tambi\u00e9n usa la propulsi\u00f3n nuclear<\/h2>\n<p>Esta opci\u00f3n para Europa consiste en emplear un reactor de fisi\u00f3n para producir <strong>electricidad en lugar de calentar un elemento propelente<\/strong>. Con esta energ\u00eda se podr\u00edan alimentar motores de tecnolog\u00eda de plasma o i\u00f3nicos, esta forma de propulsi\u00f3n es la Nuclear Electric Propulsion o NEP, la cual produce menos empuje que la NTP pero lo compensa siendo mucho m\u00e1s eficiente que esta \u00faltima.<\/p>\n<p>En definitiva, el plan de Europa para lanzar propulsores espaciales basados en reactores nucleares de \u00faltima tecnolog\u00eda no es precisamente descabellado, puesto que se sustenta en una serie de estudios previos (incluso podr\u00eda aplicarse en la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/central-energetica-espacial\/5276\/\">primera central energ\u00e9tica espacial<\/a> del futuro). Aunque tiene tres opciones, las mismas tienen algo en com\u00fan y es la aplicaci\u00f3n de la energ\u00eda at\u00f3mica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motivados por los grandes problemas que enfrenta nuestro planeta, los pa\u00edses est\u00e1n en busca de nuevos hogares en los cuerpos &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Europa tiene un plan descabellado: Lanzar\u00e1 reactores nucleares encendidos al espacio\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/europa-reactores-nucleares-espacio\/26113\/#more-26113\" aria-label=\"Leer m\u00e1s sobre Europa tiene un plan descabellado: Lanzar\u00e1 reactores nucleares encendidos al espacio\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":26115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/26113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=26113"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/26113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/26115"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=26113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=26113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=26113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}