{"id":26377,"date":"2025-07-26T16:30:58","date_gmt":"2025-07-26T14:30:58","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=26377"},"modified":"2025-07-26T16:30:58","modified_gmt":"2025-07-26T14:30:58","slug":"agua-coches-electricos-neumaticos","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/agua-coches-electricos-neumaticos\/26377\/","title":{"rendered":"Es grave, cada vez que conducimos envenenamos el agua y el aire: Incluso los coches el\u00e9ctricos"},"content":{"rendered":"<p>Resulta sorprendente que hasta los <strong>coches<\/strong> el\u00e9ctricos pueden ser altamente contaminantes del ambiente porque todos los veh\u00edculos son capaces de verter poderosas sustancias t\u00f3xicas a las aguas y al aire. Veamos c\u00f3mo se producen estos compuestos y la forma en que llegan al entorno circundante afectando tu salud y la existencia de otras especies.<\/p>\n<h2><span data-sheets-root=\"1\">Hasta los coches el\u00e9ctricos pueden envenenar con algo m\u00e1s que micropl\u00e1sticos el aire respirado\u00a0<\/span><\/h2>\n<p>Son bien conocidas las causas de la <strong>contaminaci\u00f3n ambiental producida por la emisi\u00f3n de gases de efecto invernadero<\/strong>, atribuy\u00e9ndose principalmente a la combusti\u00f3n de f\u00f3siles que se produce a diario por el funcionamiento de millones de coches en todo el mundo.<\/p>\n<p>De all\u00ed que se promueva la sustituci\u00f3n de los coches contaminantes por aquellos con reducida huella de carbono, sin embargo, un reciente informe cient\u00edfico alerta sobre la posibilidad de que igualmente se produzca contaminaci\u00f3n ambiental debido a otras causas e independientemente del tipo de veh\u00edculo.<\/p>\n<p>De hecho, \u00bfSab\u00edas que cada vez que frenas tu coche <strong>se produce la liberaci\u00f3n de part\u00edculas t\u00f3xicas que generan contaminaci\u00f3n ambiental<\/strong> y nefastas consecuencias para tu salud y las dem\u00e1s especies que se encuentran en el entorno? No se trata de los micropl\u00e1sticos desprendidos sino de algo mucho m\u00e1s grave.<\/p>\n<p><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">El desgaste de un neum\u00e1tico produce la expulsi\u00f3n de metales pesados y aditivos que representan m\u00e1s de 2400 compuestos t\u00f3xicos para muchas especies acu\u00e1ticas, as\u00ed como las pastillas de freno emiten miles de toneladas de part\u00edculas finas que pueden ingresar al sistema respiratorio.<\/span><\/p>\n<h2>Un poderoso veneno que llega lejos llevado por el viento y la lluvia en la carretera<\/h2>\n<p>Los micropl\u00e1sticos que son arrastrados por la lluvia hasta los cursos de agua <strong>proceden en un 45% de los neum\u00e1ticos de los coches<\/strong> y contienen entre 50-90% de componentes t\u00f3xicos, planteando un grave riesgo de contaminaci\u00f3n de las aguas, el suelo y la atm\u00f3sfera del entorno circundante.<\/p>\n<p>Estas part\u00edculas de desgaste de los neum\u00e1ticos se producen durante la conducci\u00f3n mediante la abrasi\u00f3n mec\u00e1nica ocasionada generalmente al frenar y estas van acompa\u00f1adas de muchos <a href=\"https:\/\/www.ecoticias.com\/eco-america\/detectando-metales-pesados-en-los-rios\">componentes qu\u00edmicos y metales pesados en los r\u00edos<\/a>, llegando a representar concentraciones de 0.00001 hasta 10 000 miligramos por litro.<\/p>\n<p>Los efectos sobre los organismos acu\u00e1ticos de estos <strong>compuestos t\u00f3xicos provenientes del desgaste de los neum\u00e1ticos<\/strong> han sido examinados por el Instituto Leibniz de Ecolog\u00eda de Agua Dulce y Pesca Continental (IGB), entre otros, y los resultados han sido publicados en el Journal of Environmental Management.<\/p>\n<h2>Incre\u00edble: Cada vez que pisas el freno hasta los peces sienten el impacto<\/h2>\n<p>Anualmente las frenadas de coches terminan enviando millones de part\u00edculas con miles de componentes al ambiente, sobre todo a los ecosistemas acu\u00e1ticos movilizados por la lluvia y el viento, y de los que llegan a desprenderse sustancias de alta toxicidad, tales como:<\/p>\n<ul>\n<li><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Metales pesados (cadmio, plomo y zinc) <\/span><\/li>\n<li><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Aditivos (ftalato de dibutilo y 6\u2011PPD) <\/span><\/li>\n<\/ul>\n<p><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Es de resaltar que un compuesto como el 6-PPD cuando reacciona con ozono se transforma en 6\u2011PPD\u2011quinona, increment\u00e1ndose de manera alarmante su toxicidad, al punto de ser<strong> la principal causa de muerte de miles de ejemplares de salm\u00f3n<\/strong> en algunas regiones estadounidenses.\u00a0<\/span><\/p>\n<p>Por consiguiente, no son los micropl\u00e1sticos los que representan el principal factor a atender cuando se trata de evaluar la contaminaci\u00f3n generada por los neum\u00e1ticos cuando se desgastan sino los componentes t\u00f3xicos que normalmente acompa\u00f1an a los micropl\u00e1sticos desprendidos.<\/p>\n<p>En conclusi\u00f3n, <span data-sheets-root=\"1\">cada vez que conducimos envenenamos el agua y el aire, Incluso si se trata de <strong>coches<\/strong> el\u00e9ctricos, porque aunque se trate del <a href=\"https:\/\/www.ecoticias.com\/residuos-reciclaje\/neumatico-futurista-historia\">neum\u00e1tico m\u00e1s futurista de la historia<\/a>, el rodamiento y el frenado produce un desgaste estructural del mismo y de las pastillas de freno, liberando poderosas toxinas que luego son arrastradas por el viento y la lluvia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resulta sorprendente que hasta los coches el\u00e9ctricos pueden ser altamente contaminantes del ambiente porque todos los veh\u00edculos son capaces de &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Es grave, cada vez que conducimos envenenamos el agua y el aire: Incluso los coches el\u00e9ctricos\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/agua-coches-electricos-neumaticos\/26377\/#more-26377\" aria-label=\"Leer m\u00e1s sobre Es grave, cada vez que conducimos envenenamos el agua y el aire: Incluso los coches el\u00e9ctricos\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":26419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/26377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=26377"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/26377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/26419"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=26377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=26377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=26377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}