{"id":27545,"date":"2025-08-23T15:00:22","date_gmt":"2025-08-23T13:00:22","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=27545"},"modified":"2025-08-23T15:00:22","modified_gmt":"2025-08-23T13:00:22","slug":"aeropuerto-se-hunde-kansai","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/aeropuerto-se-hunde-kansai\/27545\/","title":{"rendered":"El aeropuerto que deb\u00eda flotar, pero se hunde a\u00f1o tras a\u00f1o: Cu\u00e1nto tiempo de vida le queda"},"content":{"rendered":"<p>En la actualidad, el hombre ha emprendido obras que son retadoras ya que no terminan al culminarse, sino que requieren adicionales que pueden tardar a\u00f1os o toda la vida, como ejemplo tenemos las infraestructuras que requieren un mantenimiento constante. En esta l\u00ednea te presentamos un aeropuerto que deb\u00eda mantenerse en flotaci\u00f3n, pero se est\u00e1 hundiendo a medida que pasa el tiempo.<\/p>\n<h2>Las islas artificiales de Jap\u00f3n: extendiendo el territorio<\/h2>\n<p>El pa\u00eds del sol naciente enfrenta grandes limitaciones de espacio por su tama\u00f1o y geograf\u00eda monta\u00f1osa, lo cual aunado a una creciente poblaci\u00f3n, ha obligado a los gobernantes a buscar soluciones creativas para ampliar su territorio. La que m\u00e1s les ha dado resultado es la <strong>construcci\u00f3n de islas artificiales en sus bah\u00edas y \u00e1reas costeras<\/strong> donde funcionan con gran efectividad como centros urbanos que prestan todos los servicios.<\/p>\n<p>Estas moles se ubican, como m\u00ednimo, a tres kil\u00f3metros de la costa y comienzan con colosales excavaciones en las monta\u00f1as de la zona a fin de obtener el material para el relleno. Diariamente se vierten miles de metros c\u00fabicos de roca y tierra en el fondo marino a la vez que se va compactando hasta conseguir una base s\u00f3lida donde se apoyar\u00e1n los pilotes que sostendr\u00e1n las estructuras de la isla, como ser\u00eda un aeropuerto o edificios residenciales.<\/p>\n<h2>El aeropuerto que se est\u00e1 hundiendo<\/h2>\n<p>A finales de la d\u00e9cada de los a\u00f1os 70, Jap\u00f3n comenz\u00f3 con un megaproyecto que era la construcci\u00f3n del Aeropuerto Internacional de Kansai el cual fue proyectado para descongestionar al de Osaka de su creciente tr\u00e1fico. Esta decisi\u00f3n fue tomada porque no era posible ampliar esta terminal. Sin embargo, como fue construido sobre una isla artificial, <strong>se est\u00e1 hundiendo con el paso de los a\u00f1os<\/strong>.<\/p>\n<p>De acuerdo al proyecto, esta infraestructura estar\u00eda apoyada sobre una isla artificial con una superficie de 15 hect\u00e1reas (los japoneses tuvieron cuidado de que los paneles solares colocados en el sitio <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/paneles-solares-aeropuerto-amsterdam\/18563\/\">no ocasionaran estos problemas<\/a>). La isla en cuesti\u00f3n se construy\u00f3 a cinco kil\u00f3metros de la bah\u00eda de Osaka, mar adentro, esto con el fin de evitar las consecuencias de la contaminaci\u00f3n ac\u00fastica ocasionada por el paso de los aviones.<\/p>\n<p>Las obras iniciaron a finales del a\u00f1o 1987. Es de hacer notar que la topograf\u00eda del \u00e1rea donde se asentar\u00eda la isla, su capa m\u00e1s superficial tiene un espesor de 20 metros, debajo de ella se encuentra otra compuesta por grava y arcilla dura que tiene un grosor de cientos de metros. Este terreno submarino cuando es sometido a presi\u00f3n,\u00a0 cede, situaci\u00f3n de la que los japoneses estaban enterados. Los constructores instalaron unas columnas a fin de que la infraestructura no se hundiera.<\/p>\n<p>Se trataba de unas piezas especiales especialmente dise\u00f1adas que utilizaban placas en su base que estaban hechas de metal para sostener la enorme mole del aeropuerto. Finalmente, en 1994 recibi\u00f3 su primer vuelo en su \u00fanica pista y en 1996 se aprob\u00f3 la construcci\u00f3n de una segunda pista, la que fue inaugurada en 2007. Durante todos estos a\u00f1os se han llevado a cabo <strong>trabajos de mejora y mantenimiento referidos a su flotabilidad<\/strong>.<\/p>\n<h2>\u00bfC\u00f3mo est\u00e1 la megaconstrucci\u00f3n hoy en d\u00eda?<\/h2>\n<p>Actualmente, el aeropuerto se hunde menos de 10 cm por a\u00f1o debido al nuevo sistema implementado que consiste en un mecanismo de drenaje donde se colocan columnas de arena en la capa de arcilla para que as\u00ed el agua salga, permitiendo que ese material se endurezca. Se han colocado m\u00e1s de 900 000 de estos pilotes y, como est\u00e1n dando resultado, se seguir\u00e1n instalando hasta que se detenga el hundimiento, <strong>as\u00ed que le quedan muchos a\u00f1os de vida<\/strong>.<\/p>\n<p>En conclusi\u00f3n, si bien el Aeropuerto Internacional de Kansai deb\u00eda mantenerse a flote sobre la isla artificial en que fue construido, se est\u00e1 hundiendo con el paso de los a\u00f1os (pudiera ser m\u00e1s liviano como esta estructura que usa hidr\u00f3geno y que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/aeropuerto-hub-hidrogeno-espana\/8698\/\">Espa\u00f1a propone al mundo<\/a>). Sin embargo, una nueva estrategia parece estar dando resultado, la misma consiste en colocar pilotes de arena que dejan que el agua drene.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la actualidad, el hombre ha emprendido obras que son retadoras ya que no terminan al culminarse, sino que requieren &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El aeropuerto que deb\u00eda flotar, pero se hunde a\u00f1o tras a\u00f1o: Cu\u00e1nto tiempo de vida le queda\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/aeropuerto-se-hunde-kansai\/27545\/#more-27545\" aria-label=\"Leer m\u00e1s sobre El aeropuerto que deb\u00eda flotar, pero se hunde a\u00f1o tras a\u00f1o: Cu\u00e1nto tiempo de vida le queda\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":27549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-27545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/27545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=27545"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/27545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/27549"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=27545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=27545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=27545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}