{"id":28300,"date":"2025-09-05T17:00:25","date_gmt":"2025-09-05T15:00:25","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=28300"},"modified":"2025-09-05T17:00:25","modified_gmt":"2025-09-05T15:00:25","slug":"windows-95-aeropuertos-seguridad","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/windows-95-aeropuertos-seguridad\/28300\/","title":{"rendered":"\u00bfQu\u00e9 relaci\u00f3n tienen Windows 95 y los aeropuertos?: La seguridad de millones de pasajeros en este pa\u00eds"},"content":{"rendered":"<p>La seguridad de millones de pasajeros en modernos y aparentemente sofisticados aeropuertos todav\u00eda depende de un software tan antiguo como <strong>Windows<\/strong> 95. Los motivos por los que el viejo sistema operativo de Microsoft a\u00fan est\u00e9 vigente en algunos sistemas de control de tr\u00e1fico obedece a m\u00faltiples y complicados argumentos. Aunque hay razones de peso econ\u00f3mico no todo es dinero cuando se trata de actualizar y hay una justificaci\u00f3n autoimpuesta para no producir cambios, obligando a que todo siga igual a\u00fan a riesgo de nuestras propias vidas.<\/p>\n<h2>Pese a sus fallas de seguridad Windows 95 sigue estando presente en todo lo alto<\/h2>\n<p>El sistema operativo Windows 95 fue lanzado por Microsoft el 24 de agosto de 1995, de all\u00ed su nombre. Una interfaz gr\u00e1fica h\u00edbrida de 16 y 32 bits que sustituir\u00eda a MS-DOS y a Windows 3.x y para ese entonces marc\u00f3 un hito por su funcionalidad avanzada. Evidencia de la relevancia del SO es que <strong>varias de sus innovaciones se mantienen en versiones modernas de Windows<\/strong>.<\/p>\n<p>Pese a estas innovaciones este sistema operativo de hace 30 a\u00f1os al d\u00eda de hoy presenta varias vulnerabilidades significativas a nivel de seguridad. Prueba de esta debilidad es la facilidad que tienen los atacantes para hacerse pasar por usuarios leg\u00edtimos y as\u00ed acceder a archivos y sistemas.<\/p>\n<p>Aunque las fallas en su seguridad de red y recursos compartidos todav\u00eda hay computadoras operativas en el entorno Windows 95 en torres de control en aeropuertos con las cuales monitorean y gu\u00edan modernas aeronaves. Asombroso tambi\u00e9n es que <strong>en las cabinas de estos aviones se encuentran ordenadores con el antiguo sistema operativo<\/strong> de Microsoft.<\/p>\n<h2>Aunque sea necesario cuesta mucho cambiar es lo que han dicho las autoridades en las alturas<\/h2>\n<p>Para sustentar operaciones diarias esta tecnolog\u00eda casi fosilizada todav\u00eda es utilizada el algunos terminales a\u00e9reos, incluso <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/aeropuerto-se-hunde-kansai\/27545\/\">en un aeropuerto que deb\u00eda flotar.<\/a> Una muestra de ello son los disquetes. Al igual que las viejas tiras de papel, las antiguas unidades de almacenamiento de baja capacidad sirven para la carga de datos en dispositivos inform\u00e1ticos que cumplen funciones esenciales como parte de los sistemas de control.<\/p>\n<p>La raz\u00f3n de la permanencia de un sistema operativo Windows tan antiguo es econ\u00f3mica, porque llevar a cabo una <strong>actualizaci\u00f3n del software del equipo inform\u00e1tico de los terminales aeroportuarios costar\u00eda miles de millones<\/strong> de d\u00f3lares. De all\u00ed que la Administraci\u00f3n Federal de Aviaci\u00f3n o FAA, seg\u00fan siglas en ingl\u00e9s, siga desactualizada en materia de software.<\/p>\n<p>Informaci\u00f3n sobre esta desactualizaci\u00f3n del software fue proporcionada por el administrador interino de la FAA, Chris Rocheleau, durante el reporte de una audiencia presupuestaria dado en d\u00edas recientes ante el Congreso de Estados Unidos. En un informe de car\u00e1cter interno de la Administraci\u00f3n de 2023 ya se hab\u00eda advertido de la insostenibilidad de los sistemas.<\/p>\n<h2>No todo es dinero: Muchos quieren hacerlo pero no hay tiempo para cambiar y aprender<\/h2>\n<p>El obsoleto sistema ha sido responsable de fallos como la paralizaci\u00f3n del sistema de Avisos a los Aviadores de la FAA que se produjo en enero de 2023. La interrupci\u00f3n provoc\u00f3 la <strong>suspensi\u00f3n de los vuelos en todo el pa\u00eds por unas 2 horas<\/strong>. Igualmente, fallos de cableado han producido:<\/p>\n<ul>\n<li>Interrupciones en los radares<\/li>\n<li>Fallos en sistemas de comunicaci\u00f3n<\/li>\n<li>Cientos de retrasos y cancelaciones<\/li>\n<\/ul>\n<p>La actualizaci\u00f3n de esta tecnolog\u00eda aeroportuaria no solo es frenada por un presupuesto limitado, sino que adem\u00e1s est\u00e1 la <strong>necesidad de mantener operativos los sistemas de control de tr\u00e1fico a\u00e9reo las 24\/7<\/strong>. Por otro lado, los sistemas de reemplazo deben superar previamente las evaluaciones de seguridad, comprob\u00e1ndose su resistencia ante ciberataques.<\/p>\n<p>Por los momentos el Departamento de Transporte o DOT, seg\u00fan siglas en ingl\u00e9s, ha fijado cuatro a\u00f1os como meta para la finalizaci\u00f3n del proyecto de modernizaci\u00f3n. Sin embargo, expertos consideran que el plazo es poco realista. De hecho, en un informe se advierte sobre el hecho de que todav\u00eda no se haya fijado un presupuesto para esta actualizaci\u00f3n.<\/p>\n<p>En conclusi\u00f3n, pese a las fallas en su seguridad de red y recursos compartidos no evitan que <strong>Windows<\/strong> 95 siga siendo utilizado en <a href=\"https:\/\/www.ecoticias.com\/co2\/aeropuertos-crisis-climatica\">entornos modernos como algunos aeropuertos de Europa<\/a>. En la pr\u00e1ctica, no es recomendado usar este sistema operativo en entornos modernos como aeropuertos, especialmente en una \u00e9poca en la que la seguridad inform\u00e1tica es prioritaria y los ciberataques son muy sofisticados. Pero ya hemos visto que cambiar este viejo programa inform\u00e1tico no solo involucra mucho dinero sino adem\u00e1s la vida de muchos pasajeros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La seguridad de millones de pasajeros en modernos y aparentemente sofisticados aeropuertos todav\u00eda depende de un software tan antiguo como &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u00bfQu\u00e9 relaci\u00f3n tienen Windows 95 y los aeropuertos?: La seguridad de millones de pasajeros en este pa\u00eds\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/windows-95-aeropuertos-seguridad\/28300\/#more-28300\" aria-label=\"Leer m\u00e1s sobre \u00bfQu\u00e9 relaci\u00f3n tienen Windows 95 y los aeropuertos?: La seguridad de millones de pasajeros en este pa\u00eds\">Read more<\/a><\/p>\n","protected":false},"author":9,"featured_media":28345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/28300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=28300"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/28300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/28345"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=28300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=28300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=28300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}