{"id":29840,"date":"2025-10-18T15:30:14","date_gmt":"2025-10-18T13:30:14","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=29840"},"modified":"2025-10-18T15:30:14","modified_gmt":"2025-10-18T13:30:14","slug":"bacterias-oro-planta-finlandia","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/bacterias-oro-planta-finlandia\/29840\/","title":{"rendered":"Juntas bacterias y oro, no pasa nada: Agrega esta planta y podr\u00eda ocurrir la mayor revoluci\u00f3n de la historia"},"content":{"rendered":"<p>Sabemos que la naturaleza est\u00e1 llena de maravillas, pero ahora un descubrimiento est\u00e1 obligando a los cient\u00edficos a poner todo en duda. Se ha descubierto que si combinamos una planta, bacterias y oro, podr\u00eda ocurrir una revoluci\u00f3n en la econom\u00eda y en la naturaleza, pero \u00bfC\u00f3mo es posible esto? Qu\u00e9date para descubrirlo.<\/p>\n<h2>Un descubrimiento en Finlandia<\/h2>\n<p>Un estudio reciente en los fr\u00edos bosques boreales de Finlandia ha puesto patas arriba todo lo que sab\u00edamos sobre la geolog\u00eda y la bot\u00e1nica. Los cient\u00edficos est\u00e1n asombrados por un fen\u00f3meno que parece desafiar las leyes de la naturaleza y cambiar la econom\u00eda.<\/p>\n<p>Investigadores han descubierto un \u00e1rbol que es capaz de absorber, manipular y concentrar ciertos materiales que tienen un alto valor comercial y cient\u00edfico, pero detr\u00e1s de este fen\u00f3meno que parece magia est\u00e1n unos diminutos aliados.<\/p>\n<p><strong>Esos aliados son bacterias especiales que viven dentro de la planta<\/strong> y que tienen el poder de tomar un elemento que sube disuelto en el agua del suelo y lo transforman en una sustancia s\u00f3lida y de gran valor, como si fuera una peque\u00f1a f\u00e1brica.<\/p>\n<p>Los cient\u00edficos han descifrado el misterio. Resulta que <strong>el \u00e1rbol que est\u00e1 haciendo esto es el abeto rojo, un pino de Finlandia <\/strong>y el material que el \u00e1rbol fabrica dentro en forma de peque\u00f1as bolitas, es nada m\u00e1s y nada menos que el codiciado <strong>oro<\/strong>.<\/p>\n<h2>La miner\u00eda necesita bacterias<\/h2>\n<p><a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/china-tierras-raras\">Si te sorprendiste con lo que usa China para encontrar tierras raras<\/a>, qu\u00e9date, porque este hallazgo nos da una herramienta muy potente para buscar metales. Antes, ya us\u00e1bamos plantas para ver si hab\u00eda algo de valor abajo, pero este m\u00e9todo se vuelve mucho m\u00e1s exacto al incluir a las bacterias.<\/p>\n<p>Si encontramos a las bacterias correctas pegadas a las bolitas de oro, los ge\u00f3logos tienen una pista s\u00faper precisa de d\u00f3nde excavar. Esto tiene un gran beneficio: <strong>se reduce la necesidad de hacer muchos agujeros innecesarios y costosos, lo que disminuye el da\u00f1o a los bosques.<\/strong><\/p>\n<p>Esto es fundamental en lugares como Finlandia, donde se exige que la miner\u00eda sea muy limpia. Al usar esta mezcla de bot\u00e1nica (plantas), microbiolog\u00eda (bacterias) y tecnolog\u00eda, la industria puede buscar recursos con mucho menos impacto en la naturaleza.<\/p>\n<h2>Un filtro natural para limpiar el agua<\/h2>\n<p>Pero la magia de este proceso biol\u00f3gico va mucho m\u00e1s all\u00e1 de la b\u00fasqueda de riquezas. Los cient\u00edficos ven una gran oportunidad en el uso de la naturaleza para limpiar la contaminaci\u00f3n por metales pesados, pero \u00bfC\u00f3mo lo har\u00e1n?<\/p>\n<p>B\u00e1sicamente el mismo proceso de \u00abbiomineralizaci\u00f3n\u00bb (la formaci\u00f3n de minerales por un ser vivo) que ocurre en el abeto podr\u00eda ser copiado para tratar aguas residuales. Las plantas y sus microbios actuar\u00edan como un filtro natural y masivo, capaz metales t\u00f3xicos.<\/p>\n<p>Pero \u00bfRealmente esto funciona? La respuesta es un rotundo <strong>s\u00ed<\/strong>, de hecho, <strong>ya existen proyectos en Escandinavia que est\u00e1n probando el uso de musgos y bacterias end\u00e9micas para realizar esta descontaminaci\u00f3n.<\/strong><\/p>\n<p>Pero aunque tenemos pruebas s\u00f3lidas de que el abeto produce oro, los cient\u00edficos no han resuelto el misterio por completo, pues han notado que el proceso no funciona igual en todos los \u00e1rboles, ni siquiera si est\u00e1n en el mismo lugar.<\/p>\n<p>Factores como la cantidad de agua que llega a las ra\u00edces, el clima y los diferentes tipos de bacterias que habitan cada planta podr\u00edan cambiar el resultado, as\u00ed que, el siguiente paso es realizar experimentos muy controlados para seguir el oro desde que sube por la ra\u00edz hasta que se vuelve una nanopart\u00edcula.<\/p>\n<p>Sin duda, esta investigaci\u00f3n, que une biolog\u00eda, nanotecnolog\u00eda y ciencias de la tierra, promete revolucionar la comprensi\u00f3n de los ciclos naturales de los metales. La lecci\u00f3n es que podemos buscar recursos trabajando de la mano con la inteligencia de la naturaleza, sin destruirla, <a href=\"https:\/\/www.ecoticias.com\/sostenibilidad\/reutilizacion-aguas-grises\">tal como lo hace este sistema que cambiar\u00e1 al mundo.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos que la naturaleza est\u00e1 llena de maravillas, pero ahora un descubrimiento est\u00e1 obligando a los cient\u00edficos a poner todo &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Juntas bacterias y oro, no pasa nada: Agrega esta planta y podr\u00eda ocurrir la mayor revoluci\u00f3n de la historia\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/bacterias-oro-planta-finlandia\/29840\/#more-29840\" aria-label=\"Leer m\u00e1s sobre Juntas bacterias y oro, no pasa nada: Agrega esta planta y podr\u00eda ocurrir la mayor revoluci\u00f3n de la historia\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":29841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-29840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/29840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=29840"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/29840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/29841"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=29840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=29840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=29840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}