{"id":300,"date":"2023-12-25T15:00:18","date_gmt":"2023-12-25T14:00:18","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=300"},"modified":"2023-12-25T15:00:18","modified_gmt":"2023-12-25T14:00:18","slug":"hidrogeno-natural-energia","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-natural-energia\/300\/","title":{"rendered":"Hidr\u00f3geno natural: la energ\u00eda que podr\u00eda cambiar al mundo"},"content":{"rendered":"<p>\u00bfRecuerdas cuando se hablaba de que pronto obtendr\u00edamos energ\u00eda a trav\u00e9s del agua? Pues eso es lo que la industria de las renovables est\u00e1 tratando de hacer (bueno, con ligeros matices). El uso de<strong> hidr\u00f3geno natural<\/strong> es prometedor de cara al futuro pr\u00f3ximo, pero lo que han descubierto durante las investigaciones ha dejado al mundo con la boca abierta. \u00bfPuede ser el paso que necesit\u00e1bamos frente al cambio clim\u00e1tico?<\/p>\n<h2>La electrificaci\u00f3n echa el freno: un nuevo combustible entra en escena<\/h2>\n<p>La electrificaci\u00f3n, considerada durante mucho tiempo la soluci\u00f3n al calentamiento global, muestra signos de debilitamiento, y es en este contexto que<strong> el hidr\u00f3geno natural es un valor determinante<\/strong> en el panorama energ\u00e9tico. \u00bfCu\u00e1ntas veces no lo has o\u00eddo en noticias sobre coches del futuro?<\/p>\n<p>La transici\u00f3n hacia fuentes m\u00e1s sostenibles se vuelve fundamental para lograr la descarbonizaci\u00f3n definitiva. El Oxford Institute for Energy Studies ha examinado a fondo las l\u00edneas de transmisi\u00f3n de corriente continua de alto voltaje y las ha comparado con las tuber\u00edas de hidr\u00f3geno, generando un debate enorme.<\/p>\n<p>La transmisi\u00f3n de electrones verdes a largas distancias mediante l\u00edneas de transmisi\u00f3n de corriente continua y el transporte de mol\u00e9culas verdes a trav\u00e9s de regiones mediante tuber\u00edas de hidr\u00f3geno se han presentado a menudo como competidores por la financiaci\u00f3n destinada a la descarbonizaci\u00f3n.<\/p>\n<p>Sin embargo, ambos sistemas presentan ventajas y desaf\u00edos \u00fanicos, lo que plantea interrogantes a los expertos y planificadores energ\u00e9ticos que buscan la mejor soluci\u00f3n. De todos modos, est\u00e1 claro que <strong>el\u00a0hidr\u00f3geno natural va a ser la energ\u00eda que cambie el mundo<\/strong>, como dec\u00edamos al principio, \u00bfno est\u00e1s de acuerdo?<\/p>\n<h2>El hidr\u00f3geno natural va a cambiar el mundo: descubre los motivos<\/h2>\n<p>El descubrimiento realizado por Jacques Pironon y Philippe De Donato, investigadores del Centro Nacional de Investigaciones Cient\u00edficas de Francia (CNRS), podr\u00eda transformar radicalmente nuestra perspectiva sobre el futuro energ\u00e9tico.<\/p>\n<p>Mientras buscaban combustibles f\u00f3siles en la regi\u00f3n de Lorena, utilizaron una sonda especializada para analizar los gases disueltos en el agua subterr\u00e1nea, revelando un dep\u00f3sito de hidr\u00f3geno natural con una capacidad extraordinaria de hasta 46 millones de toneladas.<\/p>\n<p>Este hallazgo, que equivale a m\u00e1s de la mitad de la producci\u00f3n anual de hidr\u00f3geno gris, <strong>posiciona al hidr\u00f3geno natural como una alternativa significativa<\/strong> y colosal. La accesibilidad y la abundancia de este recurso podr\u00edan cambiar el paradigma energ\u00e9tico global y ofrecer una soluci\u00f3n crucial en la lucha contra el cambio clim\u00e1tico.<\/p>\n<p>En una expedici\u00f3n en la regi\u00f3n de Lorena, los cient\u00edficos descubrieron un dep\u00f3sito de hidr\u00f3geno blanco de proporciones colosales. Las estimaciones indican que este dep\u00f3sito podr\u00eda contener entre 6 y 250 millones de toneladas m\u00e9tricas de hidr\u00f3geno.<\/p>\n<p>La concentraci\u00f3n aumenta con la profundidad, alcanzando el 20 % a 1250 metros, lo que subraya el potencial de este hallazgo y su potencial para transformar la matriz energ\u00e9tica. De hecho, se hab\u00eda especulado con que las excavaciones a esta magnitud iban a ser prometedoras&#8230; y as\u00ed fue.<\/p>\n<h2>\u00bfQu\u00e9 aplicaciones tiene el hidr\u00f3geno natural en la sociedad?<\/h2>\n<p>El <strong>hidr\u00f3geno natural<\/strong> no solo se presenta como una fuente de energ\u00eda prometedora sino que tambi\u00e9n desempe\u00f1a un papel crucial en diversas industrias. En el sector de refinado de petr\u00f3leo, se utiliza para convertir el petr\u00f3leo en productos como gasolina, di\u00e9sel, queroseno y asfalto.<\/p>\n<p>En la industria metal\u00fargica, se emplea junto con el nitr\u00f3geno para crear una atm\u00f3sfera protectora en los hornos de recocido de metales. Asimismo, en la industria alimentaria, el hidr\u00f3geno se utiliza para hidrogenar aceites y producir grasas hidrogenadas.<\/p>\n<p>La Comisi\u00f3n Europea, <strong>consciente del potencial del hidr\u00f3geno natural<\/strong>, ha incluido esta fuente en planes ambiciosos de financiaci\u00f3n como REPowerEU y Objetivo 55, donde el hidr\u00f3geno juega un papel clave como alternativa energ\u00e9tica.<\/p>\n<p>\u00bfNo crees que es un motivo para ser optimistas de cara a los pr\u00f3ximos a\u00f1os? Como te imaginar\u00e1s, el potencial que extriagamos del\u00a0<strong>hidr\u00f3geno natural<\/strong> depender\u00e1 de lo que investiguen las empresas. Obviamente, ser\u00e1 importante la intervenci\u00f3n y financiaci\u00f3n de los gobiernos, para lo que conviene no perder de vista las subvenciones de la Uni\u00f3n Europea para la innovaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfRecuerdas cuando se hablaba de que pronto obtendr\u00edamos energ\u00eda a trav\u00e9s del agua? Pues eso es lo que la industria &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Hidr\u00f3geno natural: la energ\u00eda que podr\u00eda cambiar al mundo\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-natural-energia\/300\/#more-300\" aria-label=\"Leer m\u00e1s sobre Hidr\u00f3geno natural: la energ\u00eda que podr\u00eda cambiar al mundo\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":302,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/302"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}