{"id":30805,"date":"2025-11-16T14:30:09","date_gmt":"2025-11-16T13:30:09","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=30805"},"modified":"2025-11-16T14:30:09","modified_gmt":"2025-11-16T13:30:09","slug":"espana-hombre-poderoso","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/espana-hombre-poderoso\/30805\/","title":{"rendered":"Cuando un solo hombre casi quiebra a toda Espa\u00f1a: Ni siquiera el rey ten\u00eda tanto poder"},"content":{"rendered":"<p>A trav\u00e9s de la historia de Espa\u00f1a, casi todo el poder total siempre lo tuvieron los Reyes y las Reinas. Ellos mov\u00edan a los ej\u00e9rcitos, creaban las leyes y decid\u00edan c\u00f3mo se gastaba el dinero del pa\u00eds. Pero existe una historia muy conocida, que se cuenta mucho en Navidad, que habla de un solo hombre que, aunque no era militar ni de la realeza, lleg\u00f3 a tener tanta riqueza y poder que puso a todo el pa\u00eds al borde de la ruina. Se dice que sus ganancias fueron tan escandalosas que la <strong>Tesorer\u00eda Real<\/strong>, que en esa \u00e9poca ya luchaba con grandes deudas, no tuvo c\u00f3mo pagarle, abriendo una crisis econ\u00f3mica nacional. Ac\u00e1 te contamos los detalles.<\/p>\n<h2>Un hombre muy poderoso en Espa\u00f1a<\/h2>\n<p>Un j\u00f3ven de origen humilde y conocido por su ascenso mete\u00f3rico, protagoniz\u00f3 una de las historias de suerte m\u00e1s incre\u00edbles del siglo XIX. Se dice que gan\u00f3 tanto dinero que la Tesorer\u00eda Real, que en ese momento ya ten\u00eda muchas deudas, no ten\u00eda c\u00f3mo pagarle, y esto provoc\u00f3 una crisis econ\u00f3mica en todo el pa\u00eds, pero \u00bfQui\u00e9n era este se\u00f1or?<\/p>\n<p>El personaje principal de esta historia es <strong>Santiago Alonso Cordero<\/strong>, un se\u00f1or que antes trabajaba como arriero en Le\u00f3n, pero que logr\u00f3 hacerse un empresario importante y hasta lleg\u00f3 a ser pol\u00edtico. El rumor dice que acert\u00f3 tantos n\u00fameros de la <strong>Loter\u00eda Primitiva<\/strong> (el juego que exist\u00eda en ese tiempo) que el gobierno no pudo cubrir el premio.<\/p>\n<h2>El premio gordo de la loter\u00eda<\/h2>\n<p>La leyenda cuenta que el Estado lleg\u00f3 a un acuerdo con \u00e9l, donde en lugar de darle el dinero, le entregaron un terreno en la Puerta del Sol. Justo all\u00ed se construyeron los edificios que hoy se conocen como las famosas Casas del Cordero, pero, en realidad, la verdad hist\u00f3rica detr\u00e1s de esto mucho m\u00e1s complicada y <a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/seres-vivos-cemento\">tan extra\u00f1a como la creaci\u00f3n de cemento con bacterias<\/a>.<\/p>\n<p>Los documentos oficiales confirman que Cordero s\u00ed se hizo con ese important\u00edsimo solar en el centro de Madrid en el a\u00f1o 1841, sin embargo, esos mismos papeles indican que \u00e9l lo compr\u00f3 a trav\u00e9s de una subasta p\u00fablica que se realiz\u00f3 despu\u00e9s de que el gobierno quit\u00f3 propiedades a la Iglesia (un proceso llamado desamortizaci\u00f3n).<\/p>\n<p>A pesar de esto, la leyenda que cuenta la gente sugiere que esa subasta pudo haber sido arreglada. La sospecha m\u00e1s fuerte es que el acuerdo para cambiar el premio de la loter\u00eda por los terrenos se hizo en secreto, funcionando como una estrategia para blanquear dinero o como un plan para salvar las cuentas del Estado de una quiebra segura.<\/p>\n<h2>El hombre detr\u00e1s del poder<\/h2>\n<p>Santiago Alonso Cordero era un hombre \u00fanico y especial, pues aunque ven\u00eda de un origen muy pobre, comenz\u00f3 trabajando como arriero y poco a poco se hizo un lugar en el mundo de los negocios. Su ascenso en la sociedad se hizo oficial cuando fue nombrado diputado en el Congreso. Se dice que, a pesar de toda su riqueza y su nuevo puesto pol\u00edtico, \u00e9l segu\u00eda yendo a las reuniones del Congreso usando la ropa tradicional de la zona donde naci\u00f3.<\/p>\n<p>La leyenda de Santiago Alonso Cordero nos ense\u00f1a que, en algunos momentos de la historia, la influencia de una sola persona y su dinero pueden ser m\u00e1s grandes que el poder de los reyes y aunque su historia est\u00e1 mezclada con mitos y verdades, lo seguro es que este empresario junt\u00f3 una fortuna tan grande que el gobierno de Espa\u00f1a tuvo que tomar decisiones muy arriesgadas. El futuro de las cuentas del Estado se tuvo que arreglar d\u00e1ndole unos terrenos, y aunque su historia no es tan misteriosa como <a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/china-laboratorio-secreto\">el laboratorio ultrasecreto de China<\/a>, termin\u00f3 escrita en piedra justo en el centro de Madrid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la historia de Espa\u00f1a, casi todo el poder total siempre lo tuvieron los Reyes y las Reinas. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Cuando un solo hombre casi quiebra a toda Espa\u00f1a: Ni siquiera el rey ten\u00eda tanto poder\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-hombre-poderoso\/30805\/#more-30805\" aria-label=\"Leer m\u00e1s sobre Cuando un solo hombre casi quiebra a toda Espa\u00f1a: Ni siquiera el rey ten\u00eda tanto poder\">Read more<\/a><\/p>\n","protected":false},"author":11,"featured_media":30806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-30805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/30805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=30805"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/30805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/30806"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=30805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=30805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=30805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}