{"id":31352,"date":"2025-11-26T14:30:52","date_gmt":"2025-11-26T13:30:52","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=31352"},"modified":"2025-11-26T14:30:52","modified_gmt":"2025-11-26T13:30:52","slug":"avance-mineria-chile","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/avance-mineria-chile\/31352\/","title":{"rendered":"El mayor avance en miner\u00eda de la historia: Logran ponerlos a trabajar y producen un recurso clave"},"content":{"rendered":"<p>La miner\u00eda, tal como la conocemos, ha sido siempre un proceso costoso, complejo y, a menudo, muy contaminante. Para obtener los metales que mueven el mundo, hemos tenido que excavar profundo y usar mucha energ\u00eda y qu\u00edmicos. Sin embargo, el mundo moderno necesita desesperadamente nuevos recursos, como los que se usan para las bater\u00edas de autos el\u00e9ctricos, obligando a los cient\u00edficos a buscar m\u00e9todos m\u00e1s inteligentes y limpios, as\u00ed que ahora ha llegado el mejor avance de la historia, pero \u00bfDe qu\u00e9 se trata?<\/p>\n<h2>Un nuevo logro en la miner\u00eda<\/h2>\n<p>Un equipo de ingenieros y biotecn\u00f3logos chilenos ha logrado un avance que muchos consideran el salto m\u00e1s grande en la historia de la miner\u00eda. Han encontrado una forma de extraer un metal crucial para la electromovilidad, no de la roca virgen, sino de los relaves mineros, transformando un problema ambiental en una fuente de riqueza.<\/p>\n<p>El m\u00e9todo es realmente revolucionario, pues en lugar de usar maquinaria o qu\u00edmicos agresivos, han encontrado una forma de \u00abcontratar\u00bb a un ej\u00e9rcito invisible de peque\u00f1os trabajadores. El misterio se centra en qui\u00e9nes son estos nuevos \u00abmineros\u00bb y c\u00f3mo logran sacar metales valiosos que la maquinaria tradicional dej\u00f3 atr\u00e1s.<\/p>\n<p>La respuesta es que han logrado poner a trabajar a microorganismos que ya viven de forma natural en los relaves del <strong>desierto de Atacama<\/strong>, en Chile. Estos diminutos seres vivos, que se alimentan de hierro y azufre, fueron aislados y \u00abdomesticados\u00bb en el laboratorio por su gran capacidad para recuperar metales valiosos de los desechos, como el cobalto, un recurso clave.<\/p>\n<h2>Un equipo de microorganismos mineros<\/h2>\n<p><a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/seres-vivos-cemento\">Si te sorprendiste con el cemento hecho con bacteria<\/a>, debes quedarte a ver el proyecto <strong>Cobalto Verde<\/strong>, se enfoca en usar la biolixiviaci\u00f3n, una tecnolog\u00eda limpia que ya existe en la naturaleza, pero que ahora es acelerada por la ciencia. La doctora <strong>Pilar Parada<\/strong> explica que se trata de un consorcio de tres tipos de microorganismos que ya estaban adaptados a las duras condiciones de los relaves mineros.<\/p>\n<p>Estos microorganismos que encontraron son como peque\u00f1os ayudantes naturales. En lugar de tener que calentar la roca o usar \u00e1cidos peligrosos, ellos se comen el azufre y el hierro que est\u00e1n en los desechos. Al hacer esto, liberan los metales valiosos que estaban escondidos. Este proceso permite sacar metales como el cobalto de forma mucho m\u00e1s r\u00e1pida y limpia que antes.<\/p>\n<p>El metal que estos diminutos trabajadores est\u00e1n ayudando a recuperar es el cobalto. Este es un elemento esencial para las bater\u00edas de litio que se usan en los autos el\u00e9ctricos y en casi toda la tecnolog\u00eda moderna. Como es tan solicitado en el mundo, al cobalto se le llama el &#8216;oro azul&#8217; y el impacto de este invento para Chile es enorme.<\/p>\n<p><strong>Los expertos creen que el pa\u00eds puede obtener entre 10 000 y 15 000 toneladas de cobalto cada a\u00f1o \u00a1solamente de sus desechos!<\/strong> El director del proyecto, <strong>Patricio Mart\u00ednez<\/strong>, incluso cree que <strong>podr\u00edan llegar a 25 000 toneladas,<\/strong> lo que pondr\u00eda a Chile como el segundo pa\u00eds que m\u00e1s cobalto produce en el mundo, lo que sin duda ser\u00eda realmente impresionante y un gran aporte a la econom\u00eda.<\/p>\n<h2>Una soluci\u00f3n amigable con nuestro planeta<\/h2>\n<p>Sabemos que la ganancia econ\u00f3mica es bastante, pero el proyecto ofrece grandes beneficios ambientales, ya que, Chile tiene cerca de 800 dep\u00f3sitos de relaves en todo el pa\u00eds, que son una fuente constante de problemas ambientales y sociales. La t\u00e9cnica de la biolixiviaci\u00f3n ayuda a terminar con este problema. El cobalto en esos desechos est\u00e1 junto a un mineral llamado pirita, que es el culpable de generar los peligrosos drenajes \u00e1cidos (un l\u00edquido muy contaminante).<\/p>\n<p>Sin duda, el proyecto Cobalto Verde representa un avance hist\u00f3rico en la miner\u00eda. Al poner a trabajar a microorganismos que ya estaban en el pa\u00eds, Chile est\u00e1 pasando de tener un problema ambiental enorme a ser un l\u00edder mundial en la producci\u00f3n sostenible de un metal clave para el futuro verde. Este m\u00e9todo no solo aumenta la riqueza del pa\u00eds, sino que tambi\u00e9n lo pone en un lugar de privilegio como un proveedor \u00e9tico y avanzado en el mercado global, que cada vez exige m\u00e1s cuidado ambiental. Y si quieres conocer m\u00e1s avances como este, <a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/material-energia-solar-2\">ac\u00e1 te contamos sobre el material que llevar\u00e1 la producci\u00f3n de energ\u00eda al siguiente nivel<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La miner\u00eda, tal como la conocemos, ha sido siempre un proceso costoso, complejo y, a menudo, muy contaminante. Para obtener &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El mayor avance en miner\u00eda de la historia: Logran ponerlos a trabajar y producen un recurso clave\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/avance-mineria-chile\/31352\/#more-31352\" aria-label=\"Leer m\u00e1s sobre El mayor avance en miner\u00eda de la historia: Logran ponerlos a trabajar y producen un recurso clave\">Read more<\/a><\/p>\n","protected":false},"author":11,"featured_media":31353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-31352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/31352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=31352"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/31352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/31353"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=31352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=31352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=31352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}