{"id":33005,"date":"2026-01-30T20:33:00","date_gmt":"2026-01-30T19:33:00","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=33005"},"modified":"2026-01-26T17:08:43","modified_gmt":"2026-01-26T16:08:43","slug":"rusia-vuelve-a-mirar-a-argentina-10-anos-despues-para-construir-una-planta-nuclear-de-alta-tecnologia-que-reduciria-los-cortes-de-luz","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/rusia-vuelve-a-mirar-a-argentina-10-anos-despues-para-construir-una-planta-nuclear-de-alta-tecnologia-que-reduciria-los-cortes-de-luz\/33005\/","title":{"rendered":"Rusia vuelve a mirar a Argentina 10 a\u00f1os despu\u00e9s para construir una planta nuclear de alta tecnolog\u00eda que reducir\u00eda los cortes de luz"},"content":{"rendered":"\n<p>Argentina es el pa\u00eds sudamericano que aparece en la mira de <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/europa-rusia-energia-nuclear-uranio\/20515\/\">Rusia<\/a> para un proyecto de central nuclear de alta tecnolog\u00eda, seg\u00fan el informe \u00ab<a href=\"https:\/\/csd.eu\/fileadmin\/user_upload\/publications_library\/files\/2024_9\/Kremlin_Playbook_in_Latin_America.pdf\" target=\"_blank\" rel=\"noopener\">Global Reach<\/a> (The Kremlin Playbook in Latin America)\u00bb del Center for the Study of Democracy (CSD).<\/p>\n\n\n\n<p>El antecedente clave se remonta a abril de 2015, cuando durante la visita de Cristina Fern\u00e1ndez de Kirchner a Mosc\u00fa se abri\u00f3 la puerta a trabajar con <a href=\"https:\/\/www.world-nuclear-news.org\/Articles\/Russia-s-Rosatom-outlines-plans-for-Argentina\" target=\"_blank\" rel=\"noopener\">Rosatom<\/a> en un reactor de alrededor de 1.200 megavatios, asociado a la familia VVER (habitualmente referida como VVER 1200 en las coberturas del acuerdo).<\/p>\n\n\n\n<p>La promesa p\u00fablica es f\u00e1cil de vender (m\u00e1s generaci\u00f3n firme para apuntalar una red el\u00e9ctrica exigida y reducir cortes). El detalle que suele quedar fuera del titular es el verdadero producto que exporta una potencia nuclear (un v\u00ednculo de d\u00e9cadas). Un reactor no llega solo, llega con ingenier\u00eda, combustible, repuestos, capacitaci\u00f3n, financiamiento y una cadena de servicios que ata decisiones t\u00e9cnicas y pol\u00edticas durante buena parte de la vida \u00fatil de la planta. Esa es justamente la l\u00f3gica que el CSD describe como palanca de influencia en infraestructura cr\u00edtica.<\/p>\n\n\n\n<p>Por eso, incluso cuando un proyecto no se concreta en el corto plazo, la conversaci\u00f3n ya cumple una funci\u00f3n estrat\u00e9gica (abrir canales, instalar opciones, condicionar futuras licitaciones y crear dependencia tecnol\u00f3gica). En ese marco, el mismo informe ubica el inter\u00e9s ruso en Argentina dentro de una agenda regional m\u00e1s amplia, donde Mosc\u00fa busca sostener presencia econ\u00f3mica y diplom\u00e1tica en <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-nuclear-argentina-atucha\/16472\/\">Am\u00e9rica Latina<\/a> en un contexto de presi\u00f3n internacional por la guerra en Ucrania.&nbsp;<\/p>\n\n\n\n<p>Foto: Planta Nuclear de Atucha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Argentina es el pa\u00eds sudamericano que aparece en la mira de Rusia para un proyecto de central nuclear de alta &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Rusia vuelve a mirar a Argentina 10 a\u00f1os despu\u00e9s para construir una planta nuclear de alta tecnolog\u00eda que reducir\u00eda los cortes de luz\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/rusia-vuelve-a-mirar-a-argentina-10-anos-despues-para-construir-una-planta-nuclear-de-alta-tecnologia-que-reduciria-los-cortes-de-luz\/33005\/#more-33005\" aria-label=\"Leer m\u00e1s sobre Rusia vuelve a mirar a Argentina 10 a\u00f1os despu\u00e9s para construir una planta nuclear de alta tecnolog\u00eda que reducir\u00eda los cortes de luz\">Read more<\/a><\/p>\n","protected":false},"author":17,"featured_media":33006,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-33005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/33005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=33005"}],"version-history":[{"count":1,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/33005\/revisions"}],"predecessor-version":[{"id":33007,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/33005\/revisions\/33007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/33006"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=33005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=33005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=33005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}