{"id":334,"date":"2023-12-28T09:45:28","date_gmt":"2023-12-28T08:45:28","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=334"},"modified":"2023-12-28T09:45:28","modified_gmt":"2023-12-28T08:45:28","slug":"objetivo-55-coches","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/objetivo-55-coches\/334\/","title":{"rendered":"Estas son las medidas m\u00e1s destacables del paquete &#8216;Objetivo 55&#8217;: as\u00ed va a cambiar la automoci\u00f3n hasta 2030"},"content":{"rendered":"<p>La Uni\u00f3n Europea ha dado un paso de gigante que ha asombrado al resto del mundo. Hace varios a\u00f1os que lo hab\u00edan deslizado, pero ahora acaban de anunciar\u00a0<strong>Objetivo 55<\/strong>, una propuesta que va a cambiar los <strong>coches en 2030<\/strong>. Pero no es el \u00fanico sector que est\u00e1 afectado, hay otros tantos que quiz\u00e1 te afecten, y te los vamos a mostrar todos en este art\u00edculo.<\/p>\n<h2>El paquete Objetivo 55 llevar\u00e1 la automoci\u00f3n al futuro<\/h2>\n<p>Desde el Consejo Europeo de 2014 hasta el Pacto Verde para el Clima en 2019, la Uni\u00f3n Europea ha intensificado sus compromisos clim\u00e1ticos. <strong>La iniciativa Objetivo 55 es la respuesta<\/strong>, con el objetivo de reducir las emisiones en al menos un 55 % para 2030.<\/p>\n<p>Este ambicioso plan se extiende al transporte, donde se exige una transformaci\u00f3n que permita una reducci\u00f3n del 90 % de las emisiones de gases de efecto invernadero para 2050. Este cambio de paradigma no solo se trata de cumplir con los compromisos clim\u00e1ticos, sino de forjar un nuevo camino para la movilidad.<\/p>\n<p>La Uni\u00f3n Europea reconoce la urgencia de abordar la crisis clim\u00e1tica y, mediante el paquete que hoy te presentamos busca liderar la transici\u00f3n hacia una automoci\u00f3n m\u00e1s sostenible y respetuosa con el medioambiente. Justo lo que necesit\u00e1bamos, \u00bfverdad?<\/p>\n<h2>\u00bfQu\u00e9 objetivos se ha marcado la Uni\u00f3n Europea para 2030?<\/h2>\n<p><strong>El paquete Objetivo 55 establece metas claras<\/strong> para abordar las emisiones en diversos sectores, con la iniciativa FuelEU Maritime liderando el camino en la reducci\u00f3n de emisiones en el transporte mar\u00edtimo. Este conjunto de medidas busca descarbonizar el transporte por carretera, a\u00e9reo y mar\u00edtimo.<\/p>\n<p>Lo han conseguido ahora con la revisi\u00f3n de la Directiva sobre Fuentes de Energ\u00eda Renovables apuntando a un aumento significativo en el uso de fuentes renovables para 2030. \u00bfQu\u00e9 te parece la apuesta por reducir la intensidad de las emisiones de gases de efecto invernadero en el transporte mar\u00edtimo hasta un 80 % para 2050?<\/p>\n<p>Como te imaginar\u00e1s, demuestra lo ambiciosos que se han puesto las autoridades comunitarias. El compromiso no solo se limita a la reducci\u00f3n de emisiones, sino que tambi\u00e9n impulsa la adopci\u00f3n de combustibles renovables en el sector mar\u00edtimo, marcando as\u00ed <strong>una nueva era para los coches en 2030<\/strong>.<\/p>\n<h2>Cuatro medidas estrella para renovar la automoci\u00f3n<\/h2>\n<p>Hemos visto los objetivos de Objetivo 55 y, como ves, es toda una redundancia, pero es que la Uni\u00f3n Europea ha querido ponerle un nombre en el que quede muy claro lo que se pretende conseguir. De todos modos, lo que m\u00e1s nos impresionan con las medidas con las que demuestran que, de una vez por todas, van muy en serio.<\/p>\n<h3>L\u00edmites en las emisiones de CO2 para veh\u00edculos<\/h3>\n<p>El transporte por carretera, responsable del 12 % de las emisiones de CO2 en la UE, se enfrenta a normas revisadas para reducir progresivamente las emisiones de turismos y furgonetas nuevas en un 55 % y 50 %, respectivamente, para 2030. Estas medidas son cruciales para <strong>lograr los planes de Objetivo 55<\/strong>.<\/p>\n<p>La clave est\u00e1 en cambiar la trayectoria actual del impacto medioambiental del transporte. La revisi\u00f3n de los l\u00edmites de emisiones de CO2 para veh\u00edculos es un paso fundamental hacia la descarbonizaci\u00f3n del transporte por carretera, con el compromiso de reducir las emisiones de los turismos nuevos en un 55 %.<\/p>\n<h3>Los peajes se ampl\u00edan como nunca antes<\/h3>\n<p>La revisi\u00f3n de la Directiva del Eurodistintivo y el impulso hacia un transporte m\u00e1s ecol\u00f3gico y eficiente <strong>son aspectos clave del paquete Objetivo 55<\/strong>. La inclusi\u00f3n de un r\u00e9gimen que aborda las emisiones de CO2 refleja la ambici\u00f3n de reducir la huella de carbono del sector.<\/p>\n<p>Esta propuesta se alinea con los objetivos del Pacto Verde Europeo y el Acuerdo de Par\u00eds. La expansi\u00f3n de los peajes marca un cambio paradigm\u00e1tico en la fiscalidad del transporte. Este enfoque no solo busca financiar infraestructuras m\u00e1s sostenibles, sino que tambi\u00e9n act\u00faa como un incentivo para que las empresas.<\/p>\n<h3>Impulso al transporte por ferrocarril<\/h3>\n<p>El transporte ferroviario, considerado el medio m\u00e1s sostenible, recibe un respaldo significativo con medidas para mejorar la gesti\u00f3n y coordinaci\u00f3n de la infraestructura ferroviaria. Esta iniciativa busca aumentar la capacidad de los ferrocarriles y fomentar un medio de transporte m\u00e1s respetuoso con el medioambiente.<\/p>\n<p>El fomento del transporte por ferrocarril es <strong>un pilar fundamental del paquete Objetivo 55<\/strong>. Con el ferrocarril representando solo el 0,4 % de las emisiones totales de gases de efecto invernadero de la UE, su potencial para contribuir a la descarbonizaci\u00f3n es evidente.<\/p>\n<p>La mejora en la gesti\u00f3n y coordinaci\u00f3n de la infraestructura ferroviaria no solo optimiza la eficiencia, sino que tambi\u00e9n facilita la transici\u00f3n hacia un modo de transporte m\u00e1s sostenible. De hecho, es una iniciativa que consideramos de las m\u00e1s relevantes.<\/p>\n<h3>Combustible sostenibles para los aviones<\/h3>\n<p>La propuesta ReFuelEU Aviation es un paso significativo para reducir la huella medioambiental de la aviaci\u00f3n. Estableciendo un objetivo del 70 % de combustibles sostenibles para 2050, la Uni\u00f3n Europea pretende <strong>impulsar el cambio hacia opciones m\u00e1s ecol\u00f3gicas<\/strong> en el transporte a\u00e9reo.<\/p>\n<p>El sector de la aviaci\u00f3n, a menudo desafiante en t\u00e9rminos de descarbonizaci\u00f3n, recibe una atenci\u00f3n especial con la propuesta ReFuelEU Aviation. La meta de combustibles sostenibles para 2050 es ambiciosa y establece un est\u00e1ndar elevado para la industria.<\/p>\n<p>\u00bfQu\u00e9 te han parecido estas cuatro metas? Lo cierto es que\u00a0<strong>Objetivo 55<\/strong> se ha consolidado como una de las propuestas que m\u00e1s van a definir los\u00a0<strong>coches en 2030<\/strong>. Est\u00e1 planteada para cumplir el Pacto Verde Europeo, que ganar\u00e1 bastante protagonismo durante 2024. \u00bfEl motivo? Las normas fiscales se han impuesto de nuevo, lo que se traducir\u00e1 en m\u00e1s financiaci\u00f3n para implementar medidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Europea ha dado un paso de gigante que ha asombrado al resto del mundo. Hace varios a\u00f1os que &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Estas son las medidas m\u00e1s destacables del paquete &#8216;Objetivo 55&#8217;: as\u00ed va a cambiar la automoci\u00f3n hasta 2030\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/objetivo-55-coches\/334\/#more-334\" aria-label=\"Leer m\u00e1s sobre Estas son las medidas m\u00e1s destacables del paquete &#8216;Objetivo 55&#8217;: as\u00ed va a cambiar la automoci\u00f3n hasta 2030\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/339"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}