{"id":34199,"date":"2026-03-12T23:26:00","date_gmt":"2026-03-12T22:26:00","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=34199"},"modified":"2026-03-11T21:03:18","modified_gmt":"2026-03-11T20:03:18","slug":"llevaban-anos-pensando-que-era-una-montana-pero-la-nasa-ha-encontrado-un-crater-gigante-que-se-ve-desde-el-espacio-y-ya-saben-lo-que-hay-dentro","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/llevaban-anos-pensando-que-era-una-montana-pero-la-nasa-ha-encontrado-un-crater-gigante-que-se-ve-desde-el-espacio-y-ya-saben-lo-que-hay-dentro\/34199\/","title":{"rendered":"Llevaban a\u00f1os pensando que era una monta\u00f1a pero la NASA ha encontrado un cr\u00e1ter gigante que se ve desde el espacio y ya saben lo que hay dentro"},"content":{"rendered":"\n<p>La NASA ha puesto el foco en el noreste de China y, desde cientos de kil\u00f3metros de altura, ha confirmado algo que un bosque denso llevaba miles de a\u00f1os ocultando. Bajo las copas de los \u00e1rboles se esconde el cr\u00e1ter de Yilan, una huella de impacto de unos 50 000 a\u00f1os que podr\u00eda ser uno de los cr\u00e1teres m\u00e1s j\u00f3venes de este tama\u00f1o identificados en la Tierra y el mayor con menos de 100 000 a\u00f1os de antig\u00fcedad, abierto por un meteorito similar a otros objetos que la ciencia sigue de cerca, como el <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/origen-vida-bennu-asteroide\/17080\/\">asteroide Bennu<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un anillo casi perfecto camuflado entre \u00e1rboles<\/h2>\n\n\n\n<p>El cr\u00e1ter se encuentra a unos 20 kil\u00f3metros de la ciudad de Yilan, en la cordillera de Lesser Xing\u2019an, en la provincia de Heilongjiang. Desde el suelo, quienes viven all\u00ed lo conoc\u00edan simplemente como \u201cQuanshan\u201d, algo as\u00ed como \u201ccresta monta\u00f1osa circular\u201d. A pie parece una especie de anfiteatro natural cubierto de vegetaci\u00f3n. Desde el espacio, las im\u00e1genes del sat\u00e9lite <a href=\"https:\/\/science.nasa.gov\/mission\/landsat-8\/\" target=\"_blank\" rel=\"noopener\">Landsat 8<\/a> revelan una depresi\u00f3n casi circular, con un anillo norte bien marcado y un tercio sur desaparecido. Ese borde preservado se eleva unos 150 metros sobre el fondo del cr\u00e1ter y la cavidad alcanza un m\u00e1ximo de unos 1,85 kil\u00f3metros de di\u00e1metro.<\/p>\n\n\n\n<p>La clave de que se les escapase tanto tiempo a los ge\u00f3logos est\u00e1 en esa cubierta forestal. A simple vista se confunde con una colina m\u00e1s. Solo al combinar datos de sat\u00e9lite y trabajo de campo se ha podido reconstruir su verdadera forma, una tarea que encaja con el esfuerzo global por vigilar mejor el <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/impacto-paises-asteroide-2024-yr4\/17246\/\">impacto<\/a> de los objetos que llegan del espacio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lo que esconden 438 metros bajo el suelo<\/h2>\n\n\n\n<p>Para confirmar que no era solo una curiosidad geol\u00f3gica, un equipo chino perfor\u00f3 el centro de la estructura hasta unos 438 metros de profundidad. Bajo m\u00e1s de 100 metros de sedimentos de antiguo lago y pantano aparecieron centenares de metros de granito fracturado. En esas rocas encontraron cuarzo \u201cchocado\u201d, granito fundido y fragmentos v\u00edtreos con burbujas de gas, se\u00f1ales t\u00edpicas de presiones y temperaturas extremas asociadas a un impacto de meteorito contra la superficie terrestre, el mismo tipo de proceso que deja fragmentos vagando en \u00f3rbita como el <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/trozo-luna-orbita-terrestre\/17208\/\">trozo de Luna descubierto recientemente<\/a>.<\/p>\n\n\n\n<p>La edad se ha estimado mediante carbono 14 en restos de carb\u00f3n y sedimentos org\u00e1nicos del antiguo lago que ocup\u00f3 la depresi\u00f3n. Los resultados sit\u00faan la formaci\u00f3n del cr\u00e1ter entre hace 46 000 y 53 000 a\u00f1os, una cifra muy parecida a la del cr\u00e1ter Barringer, en Arizona, pero con un tama\u00f1o mayor, ya que ese cr\u00e1ter estadounidense mide unos 1,2 kil\u00f3metros de ancho. Hoy, parte del interior de Yilan est\u00e1 ocupada por campos de cultivo y zonas h\u00famedas. Los sedimentos del antiguo lago guardan un archivo natural del clima y de los ecosistemas del final de la \u00faltima glaciaci\u00f3n, un periodo en el que ya hab\u00eda humanos en la regi\u00f3n y en el que el <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/nasa-sistema-solar-exoplaneta\/17260\/\">Sistema Solar<\/a> se parec\u00eda mucho al que conocemos hoy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>China suma cr\u00e1teres a su mapa de impactos<\/strong><\/h2>\n\n\n\n<p>Hasta hace pocos a\u00f1os, el \u00fanico cr\u00e1ter de impacto confirmado en el pa\u00eds era el <a href=\"https:\/\/link.springer.com\/article\/10.1007\/s11434-010-3010-1\" target=\"_blank\" rel=\"noopener\">cr\u00e1ter de Xiuyan<\/a>, de 1,8 kil\u00f3metros, reconocido en 2009. La identificaci\u00f3n de Yilan como estructura de impacto abri\u00f3 la puerta a revisar otras formas \u201csospechosas\u201d y, desde entonces, se han descrito dos cr\u00e1teres adicionales en el noreste chino, Baijifeng y Hailin, que elevan a cuatro el n\u00famero de impactos confirmados en la regi\u00f3n y se suman a otros escenarios extremos que marcan la geolog\u00eda del planeta, como los supervolcanes o los grandes cr\u00e1teres lunares que ayudan a explicar misterios sobre nuestro sat\u00e9lite y su historia de colisiones.<\/p>\n\n\n\n<p>Para la ciencia del clima y del medio ambiente, estos hallazgos no son una simple curiosidad astron\u00f3mica. Ayudan a calcular mejor cada cu\u00e1nto se producen impactos capaces de alterar ecosistemas enteros y a entender c\u00f3mo se recuperan los paisajes despu\u00e9s de una perturbaci\u00f3n extrema, algo clave cuando se analizan desde otros puntos del <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/origen-vida-bennu-asteroide\/17080\/\">vecindario c\u00f3smico<\/a> los riesgos que afronta la Tierra. En el caso de Yilan, el cr\u00e1ter alberga hoy suelos f\u00e9rtiles, bosques y humedales, un ejemplo de c\u00f3mo la Tierra recicla incluso sus cicatrices m\u00e1s violentas.<\/p>\n\n\n\n<p>Adem\u00e1s, el caso ilustra el papel de los sat\u00e9lites de observaci\u00f3n terrestre. Las mismas im\u00e1genes que usamos para seguir incendios, p\u00e9rdida de bosques o sequ\u00edas permiten tambi\u00e9n localizar estructuras enterradas y mejorar los mapas geol\u00f3gicos, algo clave cuando se planifican infraestructuras o se eval\u00faan riesgos naturales, del mismo modo que otras misiones ayudan a localizar cuasilunas y objetos que pasan silenciosamente cerca de nuestro planeta, como el descrito en la historia de la cuasi-luna 2025 PN7.<\/p>\n\n\n\n<p>La nota oficial de la agencia espacial puede consultarse en la p\u00e1gina del <a href=\"https:\/\/science.nasa.gov\/earth\/earth-observatory\/blast-from-the-past-young-impact-crater-uncovered-in-yilan-154506\/\" target=\"_blank\" rel=\"noopener\"><em>Earth Observatory de la NASA<\/em><\/a>,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NASA ha puesto el foco en el noreste de China y, desde cientos de kil\u00f3metros de altura, ha confirmado &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Llevaban a\u00f1os pensando que era una monta\u00f1a pero la NASA ha encontrado un cr\u00e1ter gigante que se ve desde el espacio y ya saben lo que hay dentro\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/llevaban-anos-pensando-que-era-una-montana-pero-la-nasa-ha-encontrado-un-crater-gigante-que-se-ve-desde-el-espacio-y-ya-saben-lo-que-hay-dentro\/34199\/#more-34199\" aria-label=\"Leer m\u00e1s sobre Llevaban a\u00f1os pensando que era una monta\u00f1a pero la NASA ha encontrado un cr\u00e1ter gigante que se ve desde el espacio y ya saben lo que hay dentro\">Read more<\/a><\/p>\n","protected":false},"author":17,"featured_media":34200,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-34199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/34199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=34199"}],"version-history":[{"count":2,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/34199\/revisions"}],"predecessor-version":[{"id":34272,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/34199\/revisions\/34272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/34200"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=34199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=34199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=34199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}