{"id":394,"date":"2023-12-29T14:00:09","date_gmt":"2023-12-29T13:00:09","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=394"},"modified":"2023-12-29T14:00:09","modified_gmt":"2023-12-29T13:00:09","slug":"energia-solar-carriles-bicicletas","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/energia-solar-carriles-bicicletas\/394\/","title":{"rendered":"Este es el incre\u00edble invento que genera energ\u00eda solar en los carriles de bicicletas"},"content":{"rendered":"<p>\u00bfQu\u00e9 te parecer\u00eda si el ciclismo no solo evitara emisiones contaminantes, sino que aportara electricidad limpia? Es justo lo que venimos a contarte hoy y que demuestra c\u00f3mo estamos apostando por el medioambiente. Descubre c\u00f3mo est\u00e1n generando\u00a0<strong>energ\u00eda solar<\/strong> en los\u00a0<strong>carriles de bicicletas<\/strong>, un m\u00e9todo innovador y que, hasta hace algunos meses, parec\u00eda de ciencia ficci\u00f3n.<\/p>\n<h2>La energ\u00eda solar llega a las bicicletas: nunca hab\u00edamos generado tanto<\/h2>\n<p><strong>Las energ\u00eda solar y la fotovoltaica<\/strong> son vistas desde hace a\u00f1os como la soluci\u00f3n para acabar con la dependencia que tenemos frente a los combustibles f\u00f3siles. La clave est\u00e1 en su potencial para generar electricidad sin tener que emitir gases contaminantes.<\/p>\n<p>Otra de las propuestas con las que vamos a combatir el cambio clim\u00e1tico son las bicicletas, que en naciones como los Pa\u00edses Bajos son cada vez m\u00e1s comunes y forman parte de la vida diaria. Pero \u00bfy si te dij\u00e9ramos que van a combinar ambos para crear un ecosistema ecol\u00f3gico y sostenible como nunca antes?<\/p>\n<p>Han propuesto desarrollar los <strong>carriles de bicicletas con paneles solares<\/strong>, de manera que el propio desplazamiento de los usuarios produzca energ\u00eda para utilizar en el sector residencial o en el alumbrado p\u00fablico. \u00bfNo te parece un invento del futuro?<\/p>\n<p>Quiz\u00e1 pienses que el invento del que te vamos a hablar llega desde China o desde Corea del Sur, pa\u00edses punteros en tecnolog\u00eda. Pues nada m\u00e1s lejos de la realidad, dado que viene desde Pa\u00edses Bajos, que ya innovaron haciendo carreteras con pl\u00e1stico obtenido de fuentes recicladas.<\/p>\n<h2>In\u00e9dito: un invento genera energ\u00eda solar en los carriles de bicicletas<\/h2>\n<p>Aunque pueda sonar futurista, el primer tramo de <strong>carriles de bicicletas con paneles solares<\/strong> se instal\u00f3 en Pa\u00edses Bajos en 2014. Este proyecto pionero ha evolucionado, y recientemente se han inaugurado dos nuevos tramos, sumando 2,000 metros cuadrados de tecnolog\u00eda solar.<\/p>\n<p>Wattway, especializada en pavimentaci\u00f3n de carreteras con paneles solares, se asoci\u00f3 con la constructora BAM Royal Group para hacer posible este avance. El proyecto no solo es una proeza tecnol\u00f3gica, sino tambi\u00e9n una muestra de eficiencia.<\/p>\n<p>Estos nuevos tramos, instalados en Brabante Septentrional y Holanda Septentrional, presentan una tecnolog\u00eda m\u00e1s avanzada y eficiente que la primera v\u00eda ciclista en Krommenie. Los <strong>paneles para producir energ\u00eda solar<\/strong> utilizados son s\u00f3lidos, con apenas unos mil\u00edmetros de espesor, capaces de soportar el tr\u00e1fico diario.<\/p>\n<h2>\u00bfCu\u00e1ndo y c\u00f3mo se podr\u00eda empezar a aplicar este invento?<\/h2>\n<p>\u00bfTe imaginas tener <strong>carriles de bicicletas que generan energ\u00eda solar<\/strong> que se pueda suministrar electricidad a miles de viviendas al mismo tiempo? Estamos hablando de traer a nuestro pa\u00eds el invento que en Pa\u00edses Bajos ya est\u00e1n poniendo en marcha, lo que ser\u00eda incre\u00edble.<\/p>\n<p>La clave est\u00e1 en el potencial que tienen regiones como el interior o el Levante peninsulares, con m\u00e1s de 3000 horas de sol al a\u00f1o. La media en toda Espa\u00f1a es de 2500, con la que podr\u00edamos ser punteros en la generaci\u00f3n de energ\u00eda solar en este tipo de v\u00edas para ciclistas.<\/p>\n<p>El \u00fanico problema es que la tradici\u00f3n de ir en bicicleta <strong>no est\u00e1 tan arraigada en nuestro pa\u00eds<\/strong>, lo que supone una cierta desventaja. De todos modos, cada vez se ven m\u00e1s personas pedaleando en las calles, as\u00ed que podr\u00edamos hablar de un proyecto que a corto-medio plazo funcionar\u00eda.<\/p>\n<p>Como ves, la integraci\u00f3n de la <strong>energ\u00eda solar <\/strong>en <strong>carriles de bicicletas<\/strong> es un ejemplo fascinante de c\u00f3mo la innovaci\u00f3n puede transformar nuestra forma de movernos y generar energ\u00eda. Pa\u00edses Bajos nos se\u00f1ala el camino hacia un futuro m\u00e1s sostenible, donde incluso nuestras rutas diarias pueden contribuir a un cambio positivo en el medioambiente. \u00bfNo crees que es un invento que ilusiona? Nosotros, desde luego, lo estamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 te parecer\u00eda si el ciclismo no solo evitara emisiones contaminantes, sino que aportara electricidad limpia? Es justo lo que &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este es el incre\u00edble invento que genera energ\u00eda solar en los carriles de bicicletas\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-solar-carriles-bicicletas\/394\/#more-394\" aria-label=\"Leer m\u00e1s sobre Este es el incre\u00edble invento que genera energ\u00eda solar en los carriles de bicicletas\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":511,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/511"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}