{"id":4023,"date":"2024-03-13T16:30:04","date_gmt":"2024-03-13T15:30:04","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=4023"},"modified":"2024-03-13T16:30:04","modified_gmt":"2024-03-13T15:30:04","slug":"reciclar-mayor-decepcion-historia","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/reciclar-mayor-decepcion-historia\/4023\/","title":{"rendered":"La mayor decepci\u00f3n en la historia de la humanidad: llevamos d\u00e9cadas haciendo esto al reciclar, pero no sirvi\u00f3 de nada"},"content":{"rendered":"<p>La sociedad est\u00e1 haciendo grandes esfuerzos para cuidar del planeta \u2014unos m\u00e1s que otros, todo sea dicho\u2014. Una cuesti\u00f3n tan sencilla como\u00a0<strong>reciclar<\/strong> se ha convertido en un h\u00e1bito, pero \u00bfy si te decimos que hemos hecho algo que no ha servido de nada? Descubre c\u00f3mo la humanidad se ha llevado la mayor decepci\u00f3n de su historia y tampoco te pierdas <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/ue-carnes-dieta-eliminar\/3867\/\">el alimento que la Uni\u00f3n Europea quiere quitar de tu dieta<\/a>.<\/p>\n<h2>Un acto tan sencillo como reciclar, en nuestras vidas desde hace d\u00e9cadas<\/h2>\n<p class=\"mb-3\">El reciclaje como concepto <strong>empez\u00f3 a ganar importancia en la d\u00e9cada de los 70<\/strong>, cuando la crisis del petr\u00f3leo hizo que muchos pa\u00edses se dieran cuenta de la necesidad de depender menos de los recursos finitos y empezar a reutilizar los materiales que ya se hab\u00edan extra\u00eddo.<\/p>\n<p class=\"mb-3\">En esos a\u00f1os surgieron las primeras campa\u00f1as masivas para fomentar el reciclaje entre la poblaci\u00f3n general. Los gobiernos y las empresas invirtieron en infraestructura para facilitar la recolecci\u00f3n y el procesamiento de materiales reciclables, como el vidrio.<\/p>\n<p class=\"mb-3\">Se cre\u00f3 una imagen muy positiva en torno al reciclaje, present\u00e1ndolo como una soluci\u00f3n viable y efectiva para reducir la contaminaci\u00f3n ambiental. \u00bfNunca has escuchado la t\u00edpica afirmaci\u00f3n de \u00abeso se lo llevan luego todo junto\u00bb? <strong>Mitos como este se llevan desmontando desde hace a\u00f1os<\/strong>.<\/p>\n<h2>Una larga lista de promesas y expectativas: el recorrido que ha tenido reciclar<\/h2>\n<p class=\"mb-3\">Desde la d\u00e9cada de los 80, cuando el reciclaje se populariz\u00f3 en varios pa\u00edses, se nos vendi\u00f3 la idea de que separar nuestros residuos en diferentes contenedores era la soluci\u00f3n para acabar con los problemas de contaminaci\u00f3n y el da\u00f1o al medio ambiente.<\/p>\n<p class=\"mb-3\">Las campa\u00f1as de concienciaci\u00f3n nos convencieron de que si recicl\u00e1bamos todo lo que estaba a nuestro alcance, podr\u00edamos salvar el planeta. Nos llenaron de optimismo al decirnos que nuestros envases de pl\u00e1stico, latas, botellas, peri\u00f3dicos y dem\u00e1s desechos tendr\u00edan <strong>una segunda vida si pasaban por el proceso de reciclaje<\/strong>.<\/p>\n<p class=\"mb-3\">Parec\u00eda algo tan sencillo e impactante al mismo tiempo. Bastaba con poner cada cosa en su lugar, y como por arte de magia, nuestros residuos se convertir\u00edan en nuevos productos, evitando as\u00ed la contaminaci\u00f3n. Esta idea de que el reciclaje iba a cambiar el mundo se expandi\u00f3 r\u00e1pidamente.<\/p>\n<h2>La realidad de reciclar hoy en d\u00eda: por qu\u00e9 no est\u00e1 funcionando<\/h2>\n<p class=\"mb-3\">A pesar de <strong>d\u00e9cadas de esfuerzos por fomentar el reciclaje<\/strong>, las cifras muestran una realidad decepcionante. Seg\u00fan un informe de la Universidad de Virginia, la tasa de reciclaje en Occidente es de apenas 32 %. La gran mayor\u00eda de los materiales al reciclar acaban en vertederos, siendo incinerados o exportados.<\/p>\n<p class=\"mb-3\">Solo se recicla el 30 % del pl\u00e1stico, con cifras a\u00fan menores para ciertos tipos como los pl\u00e1sticos del n\u00ba. 3 al n\u00ba. 7. Incluso materiales como papel y cart\u00f3n, con tasas de reciclaje de 60 %, a\u00fan est\u00e1n lejos de alcanzar su potencial. Vidrio y metales tienen algo m\u00e1s \u00e9xito, con porcentajes de reciclar de 34 % y 55 % respectivamente.<\/p>\n<p class=\"mb-3\">Pero en general, <strong>la brecha entre lo que podr\u00edamos y deber\u00edamos reciclar<\/strong> sigue siendo enorme. La verdad es que el reciclaje ha resultado ser mucho m\u00e1s complicado de lo que se pensaba originalmente. Existen varios desaf\u00edos y problemas sist\u00e9micos que han impedido que el reciclaje tenga el impacto positivo que se esperaba.<\/p>\n<p class=\"mb-3\">Uno de los principales problemas es que muchos materiales simplemente no son reciclables de una manera econ\u00f3micamente viable. Pl\u00e1sticos como bolsas, envoltorios y contenedores de alimentos son muy dif\u00edciles y costosos de reciclar (por no hablar de la ropa del contenedor azul que acaba en \u00c1frica).<\/p>\n<p>Como puedes ver,\u00a0<strong>reciclar<\/strong> ha vuelto a convertirse en una cuesti\u00f3n pol\u00e9mica, ahora por una noticia bien diferente. De cualquier modo, queremos aclarar algo, y es que jam\u00e1s desaconsejaremos hacerlo; todo lo contrario: es indispensable para mejorar la gesti\u00f3n de residuos y darles una segunda vida a los recursos de la Tierra (todo sea por que no suceda <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/agua-tecnologia-electricidad\/3880\/\">este caos del que ya advierten los expertos<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sociedad est\u00e1 haciendo grandes esfuerzos para cuidar del planeta \u2014unos m\u00e1s que otros, todo sea dicho\u2014. Una cuesti\u00f3n tan &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La mayor decepci\u00f3n en la historia de la humanidad: llevamos d\u00e9cadas haciendo esto al reciclar, pero no sirvi\u00f3 de nada\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/reciclar-mayor-decepcion-historia\/4023\/#more-4023\" aria-label=\"Leer m\u00e1s sobre La mayor decepci\u00f3n en la historia de la humanidad: llevamos d\u00e9cadas haciendo esto al reciclar, pero no sirvi\u00f3 de nada\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":4025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=4023"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/4025"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=4023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=4023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=4023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}