{"id":4281,"date":"2024-03-21T12:30:11","date_gmt":"2024-03-21T11:30:11","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=4281"},"modified":"2024-03-21T12:30:11","modified_gmt":"2024-03-21T11:30:11","slug":"inteligencia-artificial-ser-humano","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/inteligencia-artificial-ser-humano\/4281\/","title":{"rendered":"La primera inteligencia artificial hecha de luz: acaba de superar al ser humano, y no es una buena noticia"},"content":{"rendered":"<p>Aparece la primera <strong>inteligencia artificial<\/strong> hecha de luz. Est\u00e1 superando al <strong>ser humano<\/strong> y no son buenas noticias. Con la cantidad de noticias que est\u00e1n llegando sobre esta disciplina, podr\u00edamos decir que estamos en la era de la IA. De hecho, ya hemos sido testigos de varios de sus alcances, como el <a href=\"https:\/\/www.ecoticias.com\/energias-renovables\/aerogeneradores-software\">software basado en IA para diagnosticar fallos y aver\u00edas en aerogeneradores<\/a>.<\/p>\n<p>No se debe confundir el t\u00e9rmino<strong> inteligencia artificial<\/strong> con realidad aumentada. Son dos disciplinas que est\u00e1n creciendo casi a la par, pero tienen una clara diferencia. La IA permite que los ordenadores imiten la inteligencia humana, mientras que la RA mejora la percepci\u00f3n que tenemos de la realidad.<\/p>\n<p>O sea, la IA muestra un entorno artificial al 100% mientras que la RA superpone contenidos digitales en un entorno que s\u00ed es real.<\/p>\n<h2>Aterriza la primera inteligencia artificial hecha de luz: supera al ser humano<\/h2>\n<p>Esta disciplina hecha de luz cuenta con una elevada eficiencia energ\u00e9tica y viene de la mano de una nueva arquitectura inform\u00e1tica. Usa ondas de luz para procesar de manera ultrarr\u00e1pida y energ\u00e9ticamente eficiente redes neuronales artificiales. Este concepto enciende una IA hecha de luz que tiene una creciente eficiencia energ\u00e9tica.<\/p>\n<p>Est\u00e1 cimentada en redes digitales de m\u00faltiples capas de nodos y caminos de conexi\u00f3n que demandan una considerable cantidad de energ\u00eda. As\u00ed los sistemas fot\u00f3nicos se colocan como una posible soluci\u00f3n a este problema de eficiencia. Estos m\u00e9todos no trabajan con ceros y unos, sino con las caracter\u00edsticas de una onda de luz.<\/p>\n<p>Es decir, par\u00e1metros que pueden cambiar de manera continua y obtener diferentes formas, haciendo posible el proceso paralelo en diferentes grados de libertad \u00f3ptica. No obstante, hasta ahora no se ten\u00eda conocimiento de si la computaci\u00f3n fot\u00f3nica anal\u00f3gica es lo suficientemente potente para soportar el procesamiento de informaci\u00f3n desarrollado por esta tecnolog\u00eda. Ni tampoco c\u00f3mo ser\u00eda una basada en luz.<\/p>\n<p>Esta inc\u00f3gnita ha llegado a su fin de la mano de unos investigadores del <strong>Instituto Leibniz de Tecnolog\u00eda Fot\u00f3nica<\/strong> (Leibniz IPHT) en Jena (<strong>Alemania<\/strong>) y su equipo internacional. Juntos han creado una nueva tecnolog\u00eda que emplea la luz para la computaci\u00f3n neuronal, inspirada en las redes neuronales del ser humano.<\/p>\n<h2>Una sola fibra \u00f3ptica es clave en este proyecto<\/h2>\n<p>No depende de miles de elementos electr\u00f3nicos. M\u00e1s bien, usa una sola fibra \u00f3ptima, capaz de ejecutar las tareas de varias redes neuronales a la velocidad de la luz. Usa las propiedades f\u00edsicas de las ondas de luz dentro de la fibra \u00f3ptica para establecer un avanzado sistema de aprendizaje artificial.<\/p>\n<p>Es decir, pese a estar compuesto por una sola fibra \u00f3ptica, tiene la capacidad de procesar la informaci\u00f3n introducida y aprender a partir de ella.<\/p>\n<h2>Los resultados de la inteligencia artificial hecha con luz son alentadores<\/h2>\n<p>Los resultados obtenidos hasta ahora son alentadores. El sistema fot\u00f3nico consigui\u00f3 una tasa de acierto del 100% en unas tareas de clasificaci\u00f3n de orqu\u00eddeas y variedades de vino. Sin embargo, en otras pruebas ha obtenido puntajes m\u00e1s modestos. Ejemplo de ello han sido la identificaci\u00f3n de n\u00fameros escritos a mano. En este caso, la tasa de acierto fue del 86,7%.<\/p>\n<p>Otra prueba para diagnosticar infecciones por COVID-19 a trav\u00e9s de muestra de voz super\u00f3 los mejores sistemas digitales actuales. Este proyecto acarrear incertidumbre debido al avance tecnol\u00f3gico que supone. Ya hay un importante grupo preocupado ante la posibilidad de que el<strong> ser humano<\/strong> pueda ser sustituido en varios trabajos ante la llegada de nuevos dispositivos capaces de replicar sus acciones.<\/p>\n<p>El trabajo de estos investigadores fue publicado en la revista cient\u00edfica <em>Advanced Science<\/em> y supone un importante avance en el campo de la <strong>inteligencia artificial<\/strong>. Asimismo, promete dejar una huella significativa. Con este proyecto, y otros como el del <a href=\"https:\/\/www.ecoticias.com\/movilidad-electrica\/coche-inteligencia-artificial\">primer coche con IA y RA<\/a>, el mundo est\u00e1 en <em>shock<\/em>. As\u00ed se demuestra que la <strong>inteligencia artificial<\/strong> est\u00e1 cada vez m\u00e1s presente en la vida del <strong>ser humano<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aparece la primera inteligencia artificial hecha de luz. Est\u00e1 superando al ser humano y no son buenas noticias. Con la &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La primera inteligencia artificial hecha de luz: acaba de superar al ser humano, y no es una buena noticia\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/inteligencia-artificial-ser-humano\/4281\/#more-4281\" aria-label=\"Leer m\u00e1s sobre La primera inteligencia artificial hecha de luz: acaba de superar al ser humano, y no es una buena noticia\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":4379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=4281"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/4379"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=4281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=4281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=4281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}