{"id":4399,"date":"2024-03-25T16:00:28","date_gmt":"2024-03-25T15:00:28","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=4399"},"modified":"2024-03-25T16:00:28","modified_gmt":"2024-03-25T15:00:28","slug":"peninsula-iberica-pais-independiente","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/peninsula-iberica-pais-independiente\/4399\/","title":{"rendered":"El desconocido pa\u00eds independiente de la pen\u00ednsula Ib\u00e9rica: est\u00e1 dentro de esta comunidad aut\u00f3noma, pero no lo puedes visitar"},"content":{"rendered":"<p>Esta semana conocimos <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/pais-digital-cambio-climatico\/4274\/\">el primer pa\u00eds digital de la historia<\/a>, producto del cambio clim\u00e1tico. Pero \u00bfy si te decimos que tambi\u00e9n hemos descubierto un pa\u00eds independiente en plena <strong>pen\u00ednsula Ib\u00e9rica<\/strong>? No te preocupes, no ha pasado nada sin que te hayas enterado, y tampoco es Andorra. No te creer\u00e1s cu\u00e1l es, pero por un motivo muy peculiar tampoco lo vas a poder visitar en tu vida.<\/p>\n<h2>Un pa\u00eds entre Espa\u00f1a y Portugal: la rep\u00fablica independiente que no conoces<\/h2>\n<p class=\"mb-3\">Ubicado entre Espa\u00f1a y Portugal, Coto Mixto fue un peculiar y desconocido pa\u00eds independiente que existi\u00f3 durante varios siglos en la pen\u00ednsula ib\u00e9rica. Durante su breve historia, <strong>Coto Mixto desarroll\u00f3 una identidad \u00fanica<\/strong> con elementos tomados de las culturas espa\u00f1ola y portuguesa.<\/p>\n<p class=\"mb-3\">Geogr\u00e1ficamente, Coto Mixto ocupaba una peque\u00f1a regi\u00f3n monta\u00f1osa situada al norte de la actual Ourense, Galicia. Su territorio era accidentado y contaba incluso con una peque\u00f1a localidad deshabitada situada donde hoy en d\u00eda est\u00e1 el municipio de Montalegre, que forma parte de Portugal.<\/p>\n<p class=\"mb-3\">La capital era la villa de Santiago de Rubi\u00e1s, situada estrat\u00e9gicamente en una colina, mientras que las principales ciudades eran Rubi\u00e1s y Meaus. De acuerdo con sus or\u00edgenes, <strong>fue una rep\u00fablica independiente<\/strong>, algo poco com\u00fan en una \u00e9poca dominada por el auge de las monarqu\u00edas.<\/p>\n<h2>La pen\u00ednsula Ib\u00e9rica tuvo un desconocido pa\u00eds: as\u00ed fue el Coto Mixto<\/h2>\n<p class=\"mb-3\">Coto Mixto fue fundado en el contexto de la tensi\u00f3n fronteriza <strong>entre los reinos de Portugal y Castilla<\/strong> en la Pen\u00ednsula Ib\u00e9rica durante la Edad Media. Despu\u00e9s, en 1864, la reina Isabel II de Espa\u00f1a se empe\u00f1\u00f3 en que fuera un territorio de nuestro pa\u00eds mediante el Tratado de Lisboa.<\/p>\n<p class=\"mb-3\">Lo hicieron para evitar la guerra y fijando los l\u00edmites de sus respectivos reinos y acordando la creaci\u00f3n de una franja neutral entre ambos, que ser\u00eda gobernada conjuntamente. Esta zona, conocida como Coto Mixto, abarcaba numerosos pueblos, algunos de ellos deshabitados (como el que te avanz\u00e1bamos antes).<\/p>\n<p class=\"mb-3\">Su prop\u00f3sito era <strong>evitar disputas por un territorio<\/strong> que hist\u00f3ricamente hab\u00eda estado en constante conflicto. Coto Mixto naci\u00f3 as\u00ed como un pa\u00eds independiente gobernado de forma compartida, con estatus diferente a sus vecinos Portugal y Castilla. \u00bfQu\u00e9 te parece esta curiosidad geogr\u00e1fica?<\/p>\n<p class=\"mb-3\">Lo cierto es que uno de los temas que m\u00e1s pol\u00e9mica levant\u00f3 en su momento fue la tributaci\u00f3n. En el siglo XIX, el pago de impuestos se efectuaba ante las autoridades espa\u00f1oles, un hecho del que las portuguesas se quejaron. En este sentido, entraban en juego los arcaicos y abolidos derechos feudales.<\/p>\n<h2>Un lugar peque\u00f1o, pero con una estructura pol\u00edtica muy clara<\/h2>\n<p class=\"mb-3\">Coto Mixto contaba con una organizaci\u00f3n pol\u00edtica y social \u00fanica para la \u00e9poca. Producto de esa singularidad, nadie pod\u00eda ser detenido por fuerzas extranjeras dentro de esas fronteras. Como resultado, numerosas personas se escondieron como refugiados, lo que acrecentaba todav\u00eda m\u00e1s el conflicto.<\/p>\n<p class=\"mb-3\">La poblaci\u00f3n de Coto Mixto gozaba de amplias libertades desconocidas en otros lugares. Los habitantes pod\u00edan elegir a sus gobernantes, dispon\u00edan de garant\u00edas procesales frente al poder y no exist\u00eda una nobleza privilegiada como en el resto de Europa.<\/p>\n<p class=\"mb-3\">El sistema republicano <strong>permit\u00eda una gran autonom\u00eda local<\/strong>. Las aldeas y villas eleg\u00edan a sus propias autoridades y gestionaban sus asuntos internos con independencia. Solo los asuntos de inter\u00e9s general eran coordinados por el Consejo central.<\/p>\n<p>Como ves, la geograf\u00eda de nuestro pa\u00eds est\u00e1 llena de misterios, y este pa\u00eds de la\u00a0<strong>pen\u00ednsula Ib\u00e9rica<\/strong> lo pone de relieve. Es el perfecto ejemplo de c\u00f3mo vivimos en un lugar m\u00e1s diverso del que cabr\u00eda imaginar, pero no solo en tierra, tambi\u00e9n en mar. \u00bfA qu\u00e9 nos referimos con esto? <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-nueva-isla-san-borondon\/4236\/\">Esta es la novena isla de Canarias<\/a>, rodeada de misterios y que lleva en los mapas desde hace m\u00e1s de 400 a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana conocimos el primer pa\u00eds digital de la historia, producto del cambio clim\u00e1tico. Pero \u00bfy si te decimos que &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El desconocido pa\u00eds independiente de la pen\u00ednsula Ib\u00e9rica: est\u00e1 dentro de esta comunidad aut\u00f3noma, pero no lo puedes visitar\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/peninsula-iberica-pais-independiente\/4399\/#more-4399\" aria-label=\"Leer m\u00e1s sobre El desconocido pa\u00eds independiente de la pen\u00ednsula Ib\u00e9rica: est\u00e1 dentro de esta comunidad aut\u00f3noma, pero no lo puedes visitar\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":4403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=4399"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/4403"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=4399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=4399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=4399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}