{"id":4497,"date":"2024-03-30T16:30:14","date_gmt":"2024-03-30T15:30:14","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=4497"},"modified":"2024-03-30T16:30:14","modified_gmt":"2024-03-30T15:30:14","slug":"huracanes-hipercan-cambio-climatico","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/huracanes-hipercan-cambio-climatico\/4497\/","title":{"rendered":"El \u00abpadre de todos los huracanes\u00bb: as\u00ed es el hiperc\u00e1n: el tama\u00f1o de Estados Unidos y por el cambio clim\u00e1tico"},"content":{"rendered":"<p>Los <strong>huracanes<\/strong> generan desastre \u00faltimamente Caribe y a Estados Unidos surgen en Cabo Verde, frente a las costas de \u00c1frica. Este comienza desde un ligero aire que sale por el continente africano, llegan al oc\u00e9ano por los vientos alisios que yacen desde el este y se dirige al oeste. En este caso, la perturbaci\u00f3n se convierte en tormenta desde que se alimenta del agua caliente de la regi\u00f3n Atl\u00e1ntica.<\/p>\n<h2>Una amenaza extrema que desaf\u00eda las escalas de desastres naturales<\/h2>\n<p>El hiperc\u00e1n, que tambi\u00e9n se le puede llamar \u201cmegacicl\u00f3n\u201d es una clase de huracanes que se forman dependiendo la temperatura del agua del mar (50\u00b0, 15\u00b0 m\u00e1s que la temperatura marina) Este megacicl\u00f3n si llegara a hacer efecto provocar\u00eda da\u00f1os muchos m\u00e1s graves que un hurac\u00e1n categorizado. Puede ser causado por asteroides, volcanes, cometas o por el mismo calentamiento global.<\/p>\n<p>Este se forma por el agua caliente y por los vientos alisios que nacen, con solo la erupci\u00f3n de un volc\u00e1n puede crearse un hurac\u00e1n dependiendo su categor\u00eda. Los huracanes tienen la escala de categor\u00eda para definir qu\u00e9 tipo de desastre natural es y su gravedad.<\/p>\n<p>Para poder identificar cada tipo de hurac\u00e1n, tenemos la ayuda de una escala de cifras de Saffir Simpson, y en esta se encuentra:<\/p>\n<ul>\n<li>Categor\u00eda 1: aporta vientos entre 119 y 153 km\/h.;<\/li>\n<li>Categor\u00eda 2: aporta vientos entre 154 y 177 km\/h.<\/li>\n<li>Categor\u00eda 3: aporta vientos entre 178 y 208 km\/h.;<\/li>\n<li>Categor\u00eda 4: aporta vientos entre 209 y 251 km\/h.<\/li>\n<li>Categor\u00eda 5: aporta vientos de 252 km\/h o superiores.<\/li>\n<\/ul>\n<p>Hubo un caso de 2015 que abri\u00f3 un debate para que se agregara una cifra m\u00e1s en la escala (6). Pero ser\u00eda curioso, porque un hiperc\u00e1n a\u00fan no ha llegado al planeta Tierra, es decir, est\u00e1 teorizado como lo es un hurac\u00e1n de la categor\u00eda 1 a 5. Ya que este desastre se provoca si la temperatura del mar llegar\u00e1 a los 50\u00b0 que ser\u00eda muy lejano.<\/p>\n<h2>Paralizante advertencia sobre la amenaza de estas cat\u00e1strofes<\/h2>\n<p>Kerry Emanuel es un climat\u00f3logo reconocido al cumplimiento de sus predicciones sobre al calentamiento global, el admite lo dif\u00edcil que es poder reconocer si el efecto que da\u00f1a la atm\u00f3sfera ser\u00eda un calentamiento o enfriamiento.<\/p>\n<p>Las radiaciones ultravioletas del Sol se convertir\u00edan en f\u00f3rmulas de hidroxilo en el agua, para que act\u00fae junto al cloro del agua salada y sea introducido en el hiperc\u00e1n; <strong>esto podr\u00eda llevar a la destrucci\u00f3n de una gran parte de la capa de ozono<\/strong> estratosf\u00e9rico y algo letal para los habitantes del planeta Tierra.<\/p>\n<p>El climat\u00f3logo sostiene la teor\u00eda de que un hiperc\u00e1n <strong>alterar\u00eda de m\u00e1s el clima y destruir\u00eda la capa de ozono<\/strong>, ya que estos introducir\u00e1n enormes cantidades de vapor de agua y polvo dentro de la estrat\u00f3sfera. Kerry, piensa que estos tipos de huracanes llevaron a la desaparici\u00f3n de los dinosaurios.<\/p>\n<p>Este no solo se basa en la hip\u00f3tesis de la extinci\u00f3n de los dinosaurios, sino que tambi\u00e9n sostiene que, a pesar de los desastres naturales que cada d\u00eda aumentan a\u00fan m\u00e1s podr\u00edan desatar hasta la misma tercera guerra mundial. As\u00ed como tambi\u00e9n predijo que los huracanes ser\u00edan m\u00e1s destructivos con el tiempo dejando as\u00ed a ciertos lugares con, escasez de agua, hambre y guerras.<\/p>\n<h2>Cuidados para tener en cuenta en caso de hipercanes<\/h2>\n<p>\u00bfAlguna vez has escuchado sobre los efectos que dejar\u00eda este desastre natural? Si un hurac\u00e1n deja lluvias fuertes que van a m\u00e1s de 160km\/h, casa totalmente derribadas, gente herida y fallecida, solo queda imaginarnos el triple de las consecuencias que pasar\u00eda con un hiperc\u00e1n, adem\u00e1s de inundaciones severas.<\/p>\n<p>Es de suma importancia que tengamos los recursos necesarios en nuestros hogares todo el tiempo, pero en fechas donde pueda frecuentar m\u00e1s <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-atmosfera-aire\/4358\/\">un desastre como huracanes<\/a> y, en el peor de los casos, se podr\u00eda presenciar por primera vez un hiperc\u00e1n, a partir de 15 de mayo (Norte Pac\u00edfico), 1 de junio (Atl\u00e1ntico y Caribe), y finaliza el 30 de noviembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los huracanes generan desastre \u00faltimamente Caribe y a Estados Unidos surgen en Cabo Verde, frente a las costas de \u00c1frica. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El \u00abpadre de todos los huracanes\u00bb: as\u00ed es el hiperc\u00e1n: el tama\u00f1o de Estados Unidos y por el cambio clim\u00e1tico\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/huracanes-hipercan-cambio-climatico\/4497\/#more-4497\" aria-label=\"Leer m\u00e1s sobre El \u00abpadre de todos los huracanes\u00bb: as\u00ed es el hiperc\u00e1n: el tama\u00f1o de Estados Unidos y por el cambio clim\u00e1tico\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":4501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=4497"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/4497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/4501"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=4497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=4497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=4497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}