{"id":5182,"date":"2024-04-16T15:00:14","date_gmt":"2024-04-16T13:00:14","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5182"},"modified":"2024-04-16T15:00:14","modified_gmt":"2024-04-16T13:00:14","slug":"espana-fabrica-celulosa","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/espana-fabrica-celulosa\/5182\/","title":{"rendered":"El coloso de azufre que quieren construir en Espa\u00f1a: tan grande como Santiago de Compostela"},"content":{"rendered":"<p>La transici\u00f3n ecol\u00f3gica avanza en todos los pa\u00edses \u2014aunque de un modo diferente\u2014. Si hace poco vimos <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/coches-paneles-solares-alemania\/5108\/\">el pa\u00eds en el que los coches el\u00e9ctricos circulan con paneles solares<\/a>, ahora te sorprender\u00e1 ver lo que se est\u00e1 haciendo viral. Este es el coloso de azufre que quieren levantar en\u00a0<strong>Espa\u00f1a<\/strong>, del tama\u00f1o de Santiago de Compostela y para un fin relacionado con la construcci\u00f3n del futuro (o no tanto).<\/p>\n<h2>Un coloso de azufre en Espa\u00f1a: atenci\u00f3n al proyecto que pretenden levantar<\/h2>\n<p class=\"mb-3 last:mb-0\">La industria papelera en Espa\u00f1a lleva d\u00e9cadas en declive, con muchas f\u00e1bricas cerrando o reduciendo su producci\u00f3n debido a la competencia global y otros factores. Sin embargo, recientemente se ha propuesto un controvertido proyecto para construir una gigantesca planta de celulosa en Galicia.<\/p>\n<p class=\"mb-3 last:mb-0\">Estar\u00e1 levantada, espec\u00edficamente, en una de las zonas encuadradas dentro de la Red Natura. Se trata de un complejo industrial, promovido por la empresa portuguesa Altri, que <strong>producir\u00eda 500 000 toneladas de celulosa al a\u00f1o<\/strong>, \u2014casi nada en comparaci\u00f3n con las dem\u00e1s del pa\u00eds\u2014.<\/p>\n<p class=\"mb-3 last:mb-0\">Esta ser\u00eda la planta de celulosa m\u00e1s grande de Espa\u00f1a, con dimensiones comparables al tama\u00f1o de la ciudad de Santiago de Compostela. La propuesta ha generado reacciones encontradas entre los residentes locales, grupos ambientalistas y las autoridades, de las que nos vamos a hacer eco.<\/p>\n<h2>La ubicaci\u00f3n de la f\u00e1brica de celulosa, un motivo de preocupaci\u00f3n<\/h2>\n<p class=\"mb-3 last:mb-0\">La megacelulosa se ubicar\u00eda en el concello de Palas de Rei, en la provincia de Lugo. Lo cierto es que ocupar\u00eda <strong>una superficie de 800 parcelas agr\u00edcolas<\/strong>. Se trata de una zona rural, de gran valor paisaj\u00edstico y ambiental, ubicada cerca del r\u00edo Ulla, a donde llegar\u00edan 30 millones de litros de vertidos.<\/p>\n<p class=\"mb-3 last:mb-0\">Este entorno se encuentra a tan solo 15 km de la ciudad de Lugo. La elecci\u00f3n de esta ubicaci\u00f3n se debe a la disponibilidad de terrenos y tambi\u00e9n a la cercan\u00eda a las plantaciones de eucalipto que abastecer\u00edan la f\u00e1brica. Sin embargo, la construcci\u00f3n en esta zona natural protegida ha despertado una fuerte oposici\u00f3n.<\/p>\n<p class=\"mb-3 last:mb-0\">La empresa promotora detr\u00e1s del pol\u00e9mico proyecto es Altri, un grupo industrial portugu\u00e9s especializado en la producci\u00f3n de pasta y papel. Se trata de <strong>uno de los mayores productores de celulosa<\/strong> de eucalipto del mundo, con plantas industriales en Portugal y Espa\u00f1a.<\/p>\n<h2>La indignaci\u00f3n no se ha hecho esperar: un proyecto rechazado y pol\u00e9mico<\/h2>\n<p class=\"mb-3 last:mb-0\">La construcci\u00f3n de una f\u00e1brica de este tama\u00f1o tendr\u00eda efectos muy graves sobre el medioambiente de la zona. Se teme que genere grandes cantidades de contaminaci\u00f3n del aire y del agua, adem\u00e1s de un aumento significativo del tr\u00e1fico de camiones y barcos.<\/p>\n<p class=\"mb-3 last:mb-0\">Los grupos ecologistas advierten que la megacelulosa consumir\u00eda enormes cantidades de agua y energ\u00eda. Tambi\u00e9n producir\u00eda residuos t\u00f3xicos y emisiones de di\u00f3xido de carbono. Su <strong>impacto sobre los ecosistemas cercanos como el r\u00edo Ulla <\/strong>podr\u00eda ser desastroso.<\/p>\n<p class=\"mb-3 last:mb-0\">Muchos expertos creen que una f\u00e1brica de este tama\u00f1o es incompatible con el desarrollo sostenible. Amenazar\u00eda la riqueza natural de Galicia y sus recursos escasos como el agua. La construcci\u00f3n destruir\u00eda parte del bosque atl\u00e1ntico, un ecosistema \u00fanico y fr\u00e1gil.<\/p>\n<p class=\"mb-3 last:mb-0\">La construcci\u00f3n de una megacelulosa del tama\u00f1o de Santiago de Compostela plantea grandes preocupaciones sociales para los habitantes de la zona. Igualmente, afirman que un complejo industrial de semejante envergadura alterar\u00eda por completo el car\u00e1cter rural y la forma de vida de la poblaci\u00f3n local.<\/p>\n<p>Llegados a este punto, no nos queda m\u00e1s que sorprendernos por la dimensi\u00f3n que tendr\u00e1 esta\u00a0<strong>f\u00e1brica de celulosa en Ulloa<\/strong>. \u00bfEntiendes la pol\u00e9mica que se est\u00e1 levantando? Nosotros permanecemos neutrales e informativos, pero no podemos evitar extra\u00f1arnos por esta propuesta. De hecho, es casi tan impactante como la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/zona-de-espana-subida-de-mar\/4722\/\">primera ciudad de\u00a0<strong>Espa\u00f1a<\/strong> afectada por la subida en el nivel del mar<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La transici\u00f3n ecol\u00f3gica avanza en todos los pa\u00edses \u2014aunque de un modo diferente\u2014. Si hace poco vimos el pa\u00eds en &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El coloso de azufre que quieren construir en Espa\u00f1a: tan grande como Santiago de Compostela\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-fabrica-celulosa\/5182\/#more-5182\" aria-label=\"Leer m\u00e1s sobre El coloso de azufre que quieren construir en Espa\u00f1a: tan grande como Santiago de Compostela\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":5222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5182"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5222"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}