{"id":5402,"date":"2024-04-22T17:00:11","date_gmt":"2024-04-22T15:00:11","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5402"},"modified":"2024-04-22T17:00:11","modified_gmt":"2024-04-22T15:00:11","slug":"espana-energia-marruecos-hidrogeno","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/espana-energia-marruecos-hidrogeno\/5402\/","title":{"rendered":"Espa\u00f1a, traicionada por este pa\u00eds aliado con la energ\u00eda: as\u00ed nos han robado 300 000 hect\u00e1reas"},"content":{"rendered":"<p>La <strong>energ\u00eda<\/strong> renovable es vital para la transici\u00f3n ecol\u00f3gica, pero no todos los pa\u00edses han sabido explorarla de manera adecuada \u2014recuerda <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-nuclear-natrium\/5243\/\">este de Estados Unidos que en nuestro pa\u00eds ser\u00e1 ilegal<\/a>\u2014. No obstante, ahora que hab\u00edamos encontrado en\u00a0<strong>Espa\u00f1a<\/strong> una fuente aut\u00e9nticamente futurista y sostenible, nuestro aliado nos ha traicionado. \u00bfC\u00f3mo lo ha hecho? Destinando 300 000 hect\u00e1reas para dejarnos sin ella.<\/p>\n<h2>Un pa\u00eds aliado que va a ser rival energ\u00e9tico: atenci\u00f3n al inesperado movimiento<\/h2>\n<p class=\"mb-3 last:mb-0\">Recientemente, Marruecos anunci\u00f3 planes para <strong>destinar 300 000 hect\u00e1reas de tierra<\/strong> para proyectos de hidr\u00f3geno verde. Este movimiento estrat\u00e9gico por parte de Marruecos tiene implicaciones geopol\u00edticas y econ\u00f3micas significativas, especialmente para su vecino Espa\u00f1a.<\/p>\n<p class=\"mb-3 last:mb-0\">Marruecos y Espa\u00f1a tienen una relaci\u00f3n compleja, con cooperaci\u00f3n en algunas \u00e1reas pero tambi\u00e9n rivalidad en otras. En el contexto energ\u00e9tico, Marruecos ahora emerge como un competidor para Espa\u00f1a. El anuncio marroqu\u00ed sobre el hidr\u00f3geno verde es una se\u00f1al de sus ambiciones para convertirse en un exportador clave.<\/p>\n<p class=\"mb-3 last:mb-0\">Solo para que lo recuerdes, el hidr\u00f3geno verde es <strong>un combustible producido a partir de energ\u00edas renovables<\/strong> como la e\u00f3lica o la solar, mediante un proceso llamado electr\u00f3lisis que separa el hidr\u00f3geno del ox\u00edgeno en el agua. Este hidr\u00f3geno se considera verde y libre de emisiones contaminantes.<\/p>\n<h2>Un objetivo muy marcado: 5 GW para 2040 de hidr\u00f3geno, y no en Espa\u00f1a<\/h2>\n<p class=\"mb-3 last:mb-0\">Marruecos ha anunciado planes para destinar 300 000 hect\u00e1reas de tierra para proyectos de producci\u00f3n de hidr\u00f3geno verde en las regiones de Guelmim Oued Noun, La\u00e2youne-Sakia El Hamra y Dakhla-Oued Ed Dahab. La inversi\u00f3n total necesaria <strong>se estima en unos 9000 millones de euros<\/strong>.<\/p>\n<p class=\"mb-3 last:mb-0\">El objetivo es aprovechar el gran potencial renovable del pa\u00eds, especialmente la energ\u00eda e\u00f3lica y solar, para producir hidr\u00f3geno verde a gran escala y convertirse en un exportador clave de este combustible limpio. El pa\u00eds cuenta con importantes ventajas competitivas, como mayor n\u00famero de horas de sol al a\u00f1o.<\/p>\n<p class=\"mb-3 last:mb-0\">Marruecos planea tener una capacidad de producci\u00f3n de hidr\u00f3geno verde de <strong>3 GW para 2030 y de 5 GW para 2040<\/strong>. Como ves, se est\u00e1 posicionando como un nuevo competidor energ\u00e9tico para Espa\u00f1a en el \u00e1rea del hidr\u00f3geno verde, a pesar de tener proyectos conjuntos por delante como el Mundial de F\u00fatbol de 2030.<\/p>\n<h2>El impacto para Espa\u00f1a, mayor del que puedas imaginar: nos quedamos sin hidr\u00f3geno<\/h2>\n<p class=\"mb-3 last:mb-0\">La apuesta de Marruecos por el hidr\u00f3geno verde perjudica los intereses energ\u00e9ticos de Espa\u00f1a de varias maneras. En primer lugar, puede reducir las exportaciones energ\u00e9ticas espa\u00f1olas a Europa, ya que Marruecos podr\u00eda convertirse en un nuevo proveedor importante de hidr\u00f3geno verde.<\/p>\n<p class=\"mb-3 last:mb-0\">Adem\u00e1s, <strong>amenaza el liderazgo que Espa\u00f1a ha conseguido<\/strong> hasta ahora en el desarrollo de proyectos de hidr\u00f3geno verde, sobre todo en Andaluc\u00eda y otras regiones del sur. Si Marruecos consigue atraer grandes inversiones extranjeras y desarrollar una industria a gran escala, podr\u00eda superar r\u00e1pidamente a Espa\u00f1a.<\/p>\n<p class=\"mb-3 last:mb-0\">Por \u00faltimo, la cercan\u00eda geogr\u00e1fica de Marruecos con Europa le da una ventaja log\u00edstica importante respecto a Espa\u00f1a para exportar hidr\u00f3geno verde por barco o a trav\u00e9s de futuros gasoductos. La apuesta marroqu\u00ed complica el objetivo espa\u00f1ol de convertirse en l\u00edder de hidr\u00f3geno verde en Europa.<\/p>\n<p class=\"mb-3 last:mb-0\">Entre los inversores interesados destacan grandes empresas energ\u00e9ticas europeas como la alemana Siemens Energy, la italiana Enel o la francesa Engie, que ven en Marruecos una oportunidad para producir hidr\u00f3geno verde a gran escala y a bajo coste. Tambi\u00e9n petroleras como TotalEnergies est\u00e1n evaluando proyectos.<\/p>\n<p>\u00bfQu\u00e9 nos queda por ver despu\u00e9s de conocer la traici\u00f3n con el\u00a0<strong>hidr\u00f3geno en Espa\u00f1a<\/strong>? Cuando perdamos esta oportunidad \u2014si es que finalmente acaba siendo as\u00ed\u2014, podremos demostrar nuestra resiliencia. \u00bfDe qu\u00e9 modo? Estamos preparando un plan para quintuplicar nuestra capacidad energ\u00e9tica y <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-invernaderos-centrales\/5241\/\">convertir los invernaderos en centrales el\u00e9ctricas renovables<\/a>, con una nueva fuente que es 100 % limpia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La energ\u00eda renovable es vital para la transici\u00f3n ecol\u00f3gica, pero no todos los pa\u00edses han sabido explorarla de manera adecuada &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a, traicionada por este pa\u00eds aliado con la energ\u00eda: as\u00ed nos han robado 300 000 hect\u00e1reas\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-energia-marruecos-hidrogeno\/5402\/#more-5402\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a, traicionada por este pa\u00eds aliado con la energ\u00eda: as\u00ed nos han robado 300 000 hect\u00e1reas\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":5429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5402"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5429"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}