{"id":5446,"date":"2024-04-23T16:30:09","date_gmt":"2024-04-23T14:30:09","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5446"},"modified":"2024-04-23T16:30:09","modified_gmt":"2024-04-23T14:30:09","slug":"vapor-de-agua-motor","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/vapor-de-agua-motor\/5446\/","title":{"rendered":"Este motor funciona con vapor de agua: lo predijo Einstein hace un siglo y esconde un misterio"},"content":{"rendered":"<p>En plena transici\u00f3n energ\u00e9tica, aparece un <strong>motor<\/strong> que funciona con<strong> vapor de agua<\/strong>. Hace un siglo que<strong> Einstein<\/strong> lo predijo y encierra un poderoso misterio. La importancia de la descarbonizaci\u00f3n es cada vez m\u00e1s latente, raz\u00f3n por la que ya se han presentado <a href=\"https:\/\/www.ecoticias.com\/co2\/industria-cero-emisiones-netas-perte\">m\u00e1s de 100 solicitudes a la convocatoria de PERTE de descarbonizaci\u00f3n<\/a>. En los \u00faltimos a\u00f1os, varias compa\u00f1\u00edas y naciones han definido objetivos sostenibles para mejorar el estado del medio ambiente.<\/p>\n<p>Varios lugares del mundo, entre ellos <strong>Europa<\/strong>, ya se han fijado como objetivo el conseguir una econom\u00eda neutra en carbono a largo plazo. Sin embargo, para alcanzar ese ansiado objetivo, es necesario pasar por un proceso de descarbonizaci\u00f3n. Esta palabra tiene que ver con el proceso que se lleva a cabo para reducir las emisiones de carbono.<\/p>\n<p>Dichas emisiones est\u00e1n afectando negativamente al medio ambiente. Bajo estas circunstancias, se torna cada vez m\u00e1s importante la llegada de motores m\u00e1s compasivos con el entorno, como es el caso del <strong>motor<\/strong> con <strong>vapor de agua<\/strong> que nos concierne.<\/p>\n<h2>FireStar Drive, el motor con vapor de agua que Einstein profetiz\u00f3<\/h2>\n<p><strong>Einstein<\/strong> habl\u00f3 en 1929 sobre la posibilidad de crear un motor de protones basado en fusi\u00f3n nuclear. Sin embargo, esta es la primera vez que logra materializarse desafiando las leyes de la f\u00edsica y el universo. La fantas\u00eda de anta\u00f1o era que fuera capaz de propulsar naves espaciales a velocidades cercanas a la luz.<\/p>\n<p>En cuanto al uso, se estimaba que utilizara las altas temperaturas de la fusi\u00f3n para expulsar un chorro de protones y generar empuje. Los intentos previos de desarrollar un motor de fusi\u00f3n nuclear fracasaron ante una tecnolog\u00eda obsoleta que hoy se ha modernizado.<\/p>\n<p>Con el avance de las \u00faltimas d\u00e9cadas por fin somos testigos de la idea en la que confiaba<strong> Einstein<\/strong>. <strong>FireStar Drive<\/strong> es el primer modelo\u00a0de fusi\u00f3n nuclear espacial. Acaba de superar sus primeras pruebas tras un desarrollo r\u00e9cord, seg\u00fan ha informado la <em>startup<\/em> detr\u00e1s del invento, <strong>RocketStar<\/strong>. Su fuente de combustible es agua y, si funciona como advierte la compa\u00f1\u00eda, se viene una aut\u00e9ntica revoluci\u00f3n.<\/p>\n<h2>Hace un siglo que se habla de este motor, pero solo ahora podemos disfrutarlo<\/h2>\n<p>El modelo<strong> FireStar Drive<\/strong> funciona ionizando el <strong>vapor de agua<\/strong> para generar protones de alta velocidad. Seg\u00fan ha manifestado<strong> RocketStar<\/strong>, los protones chocan con \u00e1tomos de boro iniciando una reacci\u00f3n de fusi\u00f3n nuclear. El resultado es un propulsor de plasma por pulsos que se alimenta de agua. Brinda un aumento notable en el empuje compar\u00e1ndolo con otros motores como los de iones.<\/p>\n<p>Esta afirmaci\u00f3n se fundamenta en las part\u00edculas de alta energ\u00eda ocasionada en la reacci\u00f3n. <strong>RocketStar<\/strong> tiene confianza en que la demanda de propulsores de fusi\u00f3n nuclear de exploraci\u00f3n espacial y el despliegue de sat\u00e9lites aumentar\u00e1 dr\u00e1sticamente en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>La empresa advierte que la eficiencia y la mejora del empuje demostrado por esta pieza demuestra su potencial para mejorar las capacidades de esta tecnolog\u00eda para la culminaci\u00f3n de viajes interplanetarios extendidos y el posicionamiento y despliegue m\u00e1s flexible de sat\u00e9lites.<\/p>\n<p>El siguiente paso de la insignia es lanzar el<strong> FireStar Drive<\/strong> al espacio.<strong> RocketStar <\/strong>ya ha programado varias demostraciones tecnol\u00f3gicas en \u00f3rbita a bordo de la plataforma <strong>D-Orbit<\/strong> que se ejecutar\u00e1 en los pr\u00f3ximos meses. En los planes de la firma tambi\u00e9n se encuentra la realizaci\u00f3n de pruebas en tierra y el lanzamiento de una nueva m\u00e1quina en febrero de 2023 a bordo de la nave espacial <strong>Barry-2<\/strong> de <strong>Rogue Space System<\/strong>.<\/p>\n<p>As\u00ed, el <strong>motor<\/strong> que funciona con <strong>vapor de agua<\/strong> se postula como una gran soluci\u00f3n para la descarbonizaci\u00f3n (al igual que el <a href=\"https:\/\/www.ecoticias.com\/movilidad-electrica\/motor-combustion-cero-emisiones\">nuevo motor cero emisiones<\/a>) y cumple uno de los sue\u00f1os de <strong>Einstein<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En plena transici\u00f3n energ\u00e9tica, aparece un motor que funciona con vapor de agua. Hace un siglo que Einstein lo predijo &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este motor funciona con vapor de agua: lo predijo Einstein hace un siglo y esconde un misterio\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/vapor-de-agua-motor\/5446\/#more-5446\" aria-label=\"Leer m\u00e1s sobre Este motor funciona con vapor de agua: lo predijo Einstein hace un siglo y esconde un misterio\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":5497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-5446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5446"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5497"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}