{"id":5521,"date":"2024-04-25T16:30:40","date_gmt":"2024-04-25T14:30:40","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5521"},"modified":"2024-04-25T16:30:40","modified_gmt":"2024-04-25T14:30:40","slug":"mar-energia-undimotriz","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/mar-energia-undimotriz\/5521\/","title":{"rendered":"Espa\u00f1a tiene bajo el mar 30 000 TWh de energ\u00eda: el problema es que no podemos llegar hasta ah\u00ed"},"content":{"rendered":"<p>\u00bfSab\u00edas que se puede generar energ\u00eda a partir del oleaje? Entonces, \u00bfpor qu\u00e9 en los 8000 kil\u00f3metros que abarca la costa espa\u00f1ola solamente existe una planta de energ\u00eda undimotriz? En este art\u00edculo te contamos todo sobre la energ\u00eda limpia, renovable y segura que promete electrificar decenas de miles de hogares y <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/gas-natural-europa\/5109\/\">reemplazar a los combustibles f\u00f3siles como energ\u00eda de reserva<\/a>.<\/p>\n<h2>Qu\u00e9 es la energ\u00eda undimotriz<\/h2>\n<p>Las olas del mar tienen un ofrecen un gran potencial para la generaci\u00f3n de energ\u00eda el\u00e9ctrica. A este tipo de energ\u00eda se la llama\u00a0<strong>energ\u00eda undimotriz\u00a0<\/strong>y se obtiene aprovechando los movimientos de la marea para mover turbinas hidr\u00e1ulicas que convierten la energ\u00eda cin\u00e9tica en electricidad.<\/p>\n<p>Hay diferentes maneras de aprovechar la energ\u00eda del oleaje, aunque la m\u00e1s popular es el sistema de boyas que empujan el aire hacia una c\u00e1mara de compresi\u00f3n que desemboca en una turbina. La turbina, similar al sistema de una represa hidroel\u00e9ctrica, gira a gran velocidad generando electricidad gracias a un d\u00ednamo.\u00a0 Sin embargo, a diferencia de una represa, cuando el oleaje se retrae, las boyas succionan el aire, aprovechando tambi\u00e9n este movimiento para producir electricidad.<\/p>\n<p>Aunque es una gran promesa para la electrificaci\u00f3n de la Uni\u00f3n Europea, esta energ\u00eda alternativa conlleva una serie de dificultades que es necesario resolver antes de implementar su uso masivo:<\/p>\n<ul>\n<li><strong>La profundidad:<\/strong> el verdadero potencial energ\u00e9tico de la marea est\u00e1 mar adentro, donde el oleaje es m\u00e1s alto.<\/li>\n<li><strong>El mantenimiento:<\/strong> a mayor profundidad, m\u00e1s dif\u00edcil es mantener la integridad de las piezas de maquinaria de los generadores y m\u00e1s dif\u00edcil y costoso es llevar los recursos humanos y equipos de mantenimiento necesarios.<\/li>\n<li><strong>El impacto ambiental:<\/strong> las estructuras de los generadores y el cableado necesario para transportar la energ\u00eda producida, inevitablemente modifican los delicados ecosistemas marinos, lo que obliga a sopesar si los costos compensan los beneficios de la energ\u00eda undimotriz.<\/li>\n<li><strong>Presupuesto e investigaci\u00f3n:\u00a0<\/strong>la primera central de energ\u00eda undimotriz del mundo se instal\u00f3 en Australia, en 2014, por lo que es todav\u00eda una energ\u00eda mu joven y en pleno desarrollo.<\/li>\n<\/ul>\n<h2>\u00bfExiste una soluci\u00f3n?<\/h2>\n<p>Si bien podr\u00eda pensarse que la Pen\u00ednsula Ib\u00e9rica, con todos sus kil\u00f3metros de costa, deber\u00eda ser el primero lugar donde aprovechar el potencial de las mareas para producir electricidad, el mar Mediterr\u00e1neo es tan tranquilo que se requiere ir a gran profundidad. No obstante, la empresa Eco Wave Power ha anunciado sus planes para instalar una planta de energ\u00eda undimotriz en Port Adriano, en Mallorca.<\/p>\n<p>Hasta ahora, <strong>la \u00fanica planta de este tipo en Espa\u00f1a era\u00a0Mutriuki, en Guip\u00fazcoa, Pa\u00edz Vazco<\/strong>. La innovadora planta que se instalar\u00eda en Mallorca podr\u00eda generar energ\u00eda a partir de olas de apenas medio metro, lo que representar\u00eda una gran eficiencia energ\u00e9tica y podr\u00eda ser el comienzo de un gran avance para el aprovechamiento de las mareas.<\/p>\n<p>Eco Wave Power planea establecer una serie de botes en lugares clave donde el oleaje sea m\u00e1s alto. Estos son los elementos que mover\u00edan los pistones hidr\u00e1ulicos que, a su vez, llevar\u00edan energ\u00eda potencial a la turbina de la central el\u00e9ctrica.<\/p>\n<p>Aunque la capacidad de la planta alcanzar\u00eda para unos modestos 400 hogares, ser\u00eda un gran paso para desarrollar nuevos materiales y m\u00e9todos que permitan producir energ\u00eda a partir de un recurso tan abundante como son los mares y oc\u00e9anos.<\/p>\n<h2>Las ventajas de la energ\u00eda undimotriz<\/h2>\n<p>Aunque queda mucho por hacer para que esta energ\u00eda sea accesible y pueda implementarse masivamente, los beneficios que podr\u00eda aportar son muchos, por lo que vale la pena invertir en investigaci\u00f3n y desarrollo enfocado a la energ\u00eda producida por las olas.<\/p>\n<p>Las ventajas de obtener electricidad de las olas incluyen:<\/p>\n<ul>\n<li><strong>Superficie abundante:<\/strong> nuestro planeta esta cubierto en un 70% de su superficie por mares y oc\u00e9anos, por lo que supondr\u00eda una fuente de energ\u00eda inagotable.<\/li>\n<li><strong>Sin contaminaci\u00f3n sonora:<\/strong> La contaminaci\u00f3n sonora de la maquinaria es un gran problema, tanto para las personas como para otras especies que pueden ser mucho m\u00e1s sensibles a ruido que nosotros.<\/li>\n<li><strong>Sin emisiones de CO2:<\/strong> ninguna de las partes del proceso emite gases de efecto invernadero.<\/li>\n<li><strong>Energ\u00eda segura;<\/strong> no existe ning\u00fan tipo de riesgo en las plantas de energ\u00eda undimotriz.<\/li>\n<\/ul>\n<h2>Conclusi\u00f3n<\/h2>\n<p>La energ\u00eda undimotriz est\u00e1 todav\u00eda en una etapa de desarrollo. Quedan todav\u00eda muchos obst\u00e1culos por superar. No obstante, el inter\u00e9s de empresas que est\u00e1n invirtiendo capital en nuevas plantas es la clave para que, en un futuro cercano, podamos obtener energ\u00eda limpia y renovable a partir de los mares que ba\u00f1an nuestras costas, <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-nuclear-natrium\/5243\/\">evitando los riesgos de otras formas de obtener energ\u00eda en la actualidad<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00edas que se puede generar energ\u00eda a partir del oleaje? Entonces, \u00bfpor qu\u00e9 en los 8000 kil\u00f3metros que abarca la &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a tiene bajo el mar 30 000 TWh de energ\u00eda: el problema es que no podemos llegar hasta ah\u00ed\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/mar-energia-undimotriz\/5521\/#more-5521\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a tiene bajo el mar 30 000 TWh de energ\u00eda: el problema es que no podemos llegar hasta ah\u00ed\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":5522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5521"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5522"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}