{"id":5738,"date":"2024-04-30T14:30:38","date_gmt":"2024-04-30T12:30:38","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5738"},"modified":"2024-04-30T14:30:38","modified_gmt":"2024-04-30T12:30:38","slug":"la-capa-de-ozono","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/la-capa-de-ozono\/5738\/","title":{"rendered":"La capa de ozono empieza a comportarse de manera extra\u00f1a: los cient\u00edficos, en vilo y mirando al cielo"},"content":{"rendered":"<p>Las metas iniciales propuestas por la comunidad cient\u00edfica en 1987 parecen estar muy bien encaminadas para lograr el resultado planeado. Y es que el \u00faltimo informe publicado por la ONU confirma que todos los esfuerzos destinados a detener el perjuicio a<strong> la capa de ozono<\/strong> han resultado exitosos y se espera una recuperaci\u00f3n total para el a\u00f1o 2066.<\/p>\n<h2>Nuevas actualizaciones sobre el estado de la capa de ozono<\/h2>\n<p>El informe dado a conocer por el Programa de Naciones Unidas para el Medio Ambiente (UNEP), confirman que, de continuar con la aplicaci\u00f3n de las medidas adoptadas en el protocolo internacional de Montreal de 1987, se reestablecer\u00eda la salud de la atm\u00f3sfera.<\/p>\n<p>Seg\u00fan el informe presentado por la autoridad m\u00e1xima internacional en materia ambiental se revelaron los datos del estado actual y dieron fechas a la noticia m\u00e1s esperada por todos: ratificaron<strong> la recuperaci\u00f3n total de la capa de ozono entre los a\u00f1os 2040 y 2066.<\/strong><\/p>\n<p>Las evaluaciones confirman una restauraci\u00f3n global de la capa de ozono a comienzos del a\u00f1o 2040. Sin embargo, el tiempo de esta recuperaci\u00f3n podr\u00eda oscilar en diferentes latitudes, siendo las zonas polares las m\u00e1s conflictivas. <a href=\"https:\/\/www.ecoticias.com\/co2\/el-yodo-es-letal-para-la-capa-de-ozono-en-el-artico\">En este art\u00edculo conocer\u00e1s m\u00e1s elementos nocivos para el \u00c1rtico.<\/a><\/p>\n<p>En este sentido, el da\u00f1o en<strong> el polo \u00c1rtico descubierto hace menos a\u00f1os, espera su reestructuraci\u00f3n para 2045<\/strong>. En tanto que, para la zona Ant\u00e1rtica, que lleva la mayor longitud del agujero de la capa de ozono recuperar\u00eda los niveles alcanzados en 1980 para el a\u00f1o 2066.<\/p>\n<h2>El agujero de la capa de ozono<\/h2>\n<p>No parece que haya pasado tanto, pero hace unos 40 a\u00f1os nos sorprend\u00eda la noticia de un art\u00edculo en la revista cient\u00edfica Nature, que informaba sobre la existencia de un agujero en la capa de ozono, producido por el da\u00f1o que la mano del hombre ven\u00eda ejerciendo a la ecolog\u00eda.<\/p>\n<p>As\u00ed conocimos su composici\u00f3n y su funcionalidad dentro de la atm\u00f3sfera, actuando como<strong> l\u00e1mina protectora de la radiaci\u00f3n solar<\/strong>. Adem\u00e1s, se investigaron las causas que pod\u00edan estar afectando su estructura y las peligrosas consecuencias para las personas y para el medio ambiente.<\/p>\n<p>Los an\u00e1lisis cient\u00edficos hab\u00edan constatado que el origen del agujero de la capa de ozono surg\u00eda a consecuencia del uso de gases llamados clorofluorocarburos (CFCs) utilizados por la industria cosm\u00e9tica, los aerosoles e insecticidas.<\/p>\n<p>Este <strong>gas nocivo emitido en la atm\u00f3sfera se descompon\u00eda al llegar a la estrat\u00f3sfera<\/strong> liberando \u00e1tomos de cloro que perjudicaban la capa protectora solar de la Tierra. El problema real era la formaci\u00f3n de grandes huecos que nos dejaba directamente expuestos a la radiaci\u00f3n.<\/p>\n<h2>El \u00e9xito hist\u00f3rico que signific\u00f3 la regulaci\u00f3n del tratado de Montreal.<\/h2>\n<p>Hacia 1987 se firma el tratado en Montreal entre las naciones comprometidas con el cambio clim\u00e1tico y se <strong>proh\u00edbe la utilizaci\u00f3n y circulaci\u00f3n del CFCs en las industrias<\/strong> para frenar el aumento del agujero de la capa de ozono ya ocasionado, y otras soluciones que revirtieran este peligro.<\/p>\n<p>De esta manera, comenzaron a aumentar las medidas de precauci\u00f3n relacionadas con las horas de exposici\u00f3n al sol, y se elev\u00f3 el consumo de protectores solares para prevenir y contrarrestar las altas tasas de enfermedades en la piel presentadas hasta el momento.<\/p>\n<p>El protocolo que anunciaba la sustituci\u00f3n de productos que emitieran gases contaminantes a la atm\u00f3sfera permiti\u00f3 tambi\u00e9n que<strong> disminuyera 0,5\u00b0 la temperatura de la tierra<\/strong>, y se espera que descienda otro valor igual para 2100.<\/p>\n<p>Ante un panorama desolador como el actual, en el que asistimos al gran deterioro del planeta por el calentamiento clim\u00e1tico, los altos valores de contaminaci\u00f3n, la reducci\u00f3n de los bosques y la p\u00e9rdida de la diversidad, este informe es por lo menos esperanzador. No obstante, aun necesitamos m\u00e1s medidas para frenar el cambio clim\u00e1tico. <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/coger-bus-en-barcelona-precio-reducido\/2110\/\">Aqu\u00ed hay otras sugerencias sostenibles para comenzar a aplicar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las metas iniciales propuestas por la comunidad cient\u00edfica en 1987 parecen estar muy bien encaminadas para lograr el resultado planeado. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La capa de ozono empieza a comportarse de manera extra\u00f1a: los cient\u00edficos, en vilo y mirando al cielo\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/la-capa-de-ozono\/5738\/#more-5738\" aria-label=\"Leer m\u00e1s sobre La capa de ozono empieza a comportarse de manera extra\u00f1a: los cient\u00edficos, en vilo y mirando al cielo\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":5739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5738"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5739"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}