{"id":5802,"date":"2024-05-02T14:30:37","date_gmt":"2024-05-02T12:30:37","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5802"},"modified":"2024-05-02T14:30:37","modified_gmt":"2024-05-02T12:30:37","slug":"plastico-primer-pais-prohibir","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/plastico-primer-pais-prohibir\/5802\/","title":{"rendered":"Este es el primer pa\u00eds que ha prohibido el pl\u00e1stico: la medida radical que Espa\u00f1a podr\u00eda seguir pronto"},"content":{"rendered":"<p>Ya se conoce cu\u00e1l es <strong>el primer pa\u00eds que ha prohibido el pl\u00e1stico<\/strong>, coloc\u00e1ndose a la vanguardia en materia de reglamentaci\u00f3n y aplicaci\u00f3n de normas para contrarrestar el calentamiento global y ejercer pol\u00edticas p\u00fablicas en contra de la contaminaci\u00f3n ambiental. Con una nueva ley proh\u00edbe el uso de las pajillas, bolsas y botellas con el objeto de reducir el da\u00f1o que producen al planeta.<\/p>\n<h2>\u00bfCu\u00e1l es el pa\u00eds que ha prohibido el pl\u00e1stico?<\/h2>\n<p>Teniendo en cuenta que seg\u00fan los datos de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE), solamente es posible reciclar el 9% del pl\u00e1stico fabricado, y que representa el 3,4% de las emisiones totales, el primer pa\u00eds que ha prohibido el pl\u00e1stico ya tiene en vigencia su propia Ley.<\/p>\n<p>A fin de explicitar el alcance de la normativa, mencionaremos que<strong> la reglamentaci\u00f3n proh\u00edbe la importaci\u00f3n, comercializaci\u00f3n, fabricaci\u00f3n y uso de los pl\u00e1sticos de un solo uso<\/strong>, que representan al grupo de los recipientes m\u00e1s pol\u00e9micos a la hora de su tratamiento y reciclaje.<\/p>\n<p>Tomando la responsabilidad correspondiente, la regi\u00f3n de Costa Rica es quien se ha puesto a la cabeza de la competencia contra les emisiones de carbono y como miembro de la OCDE y se ha convertido en el primer pa\u00eds en prohibir el pl\u00e1stico. <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/plastico-prohibido-capsulas-de-cafe\/5499\/\">En este art\u00edculo puedes conocer otras acciones para combatir el pl\u00e1stico<\/a>.<\/p>\n<p><strong>La Ley N\u00b09786 firmada en forma conjunta con el Ministerio de Salud de Costa Rica<\/strong> tiene por objetivo eliminar de circulaci\u00f3n los pl\u00e1sticos de un solo uso en todo el territorio del pa\u00eds, y se encuentra a la espera del Reglamento T\u00e9cnico para publicar el uso.<\/p>\n<h2>\u00bfQu\u00e9 especificaciones tienen la ley que proh\u00edbe el pl\u00e1stico?<\/h2>\n<p>Las cifras a nivel mundial indican que en los \u00faltimos 20 a\u00f1os se ha duplicado la producci\u00f3n anual de pl\u00e1stico y se espera que este valor se triplique en las siguientes d\u00e9cadas alcanzando las 460.000.000 de toneladas.<\/p>\n<p>As\u00ed como se especifica en el decreto 43985-S del Reglamento a la Ley para combatir la contaminaci\u00f3n por Pl\u00e1stico y proteger el ambiente de Costa Rica, su objetivo es <strong>evitar la contaminaci\u00f3n producida por los pl\u00e1sticos de un solo uso, principalmente pajillas, bolsas y botellas<\/strong>.<\/p>\n<p>La normativa del primer pa\u00eds en prohibir en pl\u00e1stico considera que dichos productos son descartados luego del primer uso y luego desechados en terrenos, costas y mares perjudicando a la biodiversidad y el atractivo tur\u00edstico. Sin embargo, es preciso destacar algunas excepciones.<\/p>\n<h2>\u00bfCu\u00e1les son las excepciones que prev\u00e9 el primer pa\u00eds que proh\u00edbe el pl\u00e1stico antes de la aplicaci\u00f3n de la Ley?<\/h2>\n<p>La ley de Costa Rica declara la creaci\u00f3n de un ente controlador a cargo del Ministerio de Salud, que vigile el cumplimiento de las normas y menciona <strong>algunas excepciones con respecto a la venta y entrega gratuita de material pl\u00e1stico<\/strong> de un solo uso.<\/p>\n<p>El primer pa\u00eds en prohibir el pl\u00e1stico considera que, para el caso de las pajillas, deben eliminarse todas aquellas que vienen adheridas al envase, aunque se reserva su uso para productos medicinales, reg\u00edmenes especiales y emergencias de salud p\u00fablica.<\/p>\n<p>En tanto que, para<strong> las botellas<\/strong>, se except\u00faan los envases con contenido necesario para la industria agropecuaria. Asimismo, dispone permisos para la circulaci\u00f3n de ciertos pl\u00e1sticos que cumplan como los valores de proporci\u00f3n reciclable de los envases dispuestos en el reglamento t\u00e9cnico.<\/p>\n<p>En relaci\u00f3n a las bolsas, el primer pa\u00eds que proh\u00edbe el pl\u00e1stico despide de circulaci\u00f3n a aquellas que se entregan para el traslado de mercader\u00eda en comercios y supermercados, aunque sugiere la sustituci\u00f3n por bolsas de pl\u00e1stico reutilizable o de tela.<\/p>\n<p>Sin embargo, <strong>exime de toda responsabilidad a las verduler\u00edas y carnicer\u00edas del uso de bolsas de pl\u00e1stico<\/strong> por su car\u00e1cter ineludible y necesario para el acarreo de las compras, aunque obliga a disponer de contenedores especiales para su eliminaci\u00f3n. Adem\u00e1s, dispone fuertes multas en caso de incumplimiento de las normas. <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/autoconsumo-agua-invento-400-litros\/4739\/\">Aqu\u00ed te ofrecemos m\u00e1s claves para cuidar el planeta<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya se conoce cu\u00e1l es el primer pa\u00eds que ha prohibido el pl\u00e1stico, coloc\u00e1ndose a la vanguardia en materia de &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este es el primer pa\u00eds que ha prohibido el pl\u00e1stico: la medida radical que Espa\u00f1a podr\u00eda seguir pronto\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/plastico-primer-pais-prohibir\/5802\/#more-5802\" aria-label=\"Leer m\u00e1s sobre Este es el primer pa\u00eds que ha prohibido el pl\u00e1stico: la medida radical que Espa\u00f1a podr\u00eda seguir pronto\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":5819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5802"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5819"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}