{"id":5851,"date":"2024-05-02T16:30:02","date_gmt":"2024-05-02T14:30:02","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=5851"},"modified":"2024-05-02T16:30:02","modified_gmt":"2024-05-02T14:30:02","slug":"este-panel-solar-multiplica-por-1000","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/este-panel-solar-multiplica-por-1000\/5851\/","title":{"rendered":"Este panel solar multiplica por 1000 la electricidad: un enigm\u00e1tico cristal est\u00e1 detr\u00e1s del r\u00e9cord"},"content":{"rendered":"<p>La energ\u00eda solar es una gran fuente alternativa de electricidad. La luz del sol es un elemento virtualmente infinito y existe en forma natural. Sin embargo, a d\u00eda de hoy, todav\u00eda resulta muy dif\u00edcil obtener una cantidad de energ\u00eda suficiente para la vida diaria a partir solamente de paneles solares \u00bfPodr\u00edan estos cient\u00edficos haber descubierto<strong> la clave para el primer panel solar eficiente y sustentable<\/strong>?<\/p>\n<h2>El cristal que cambiar\u00eda los paneles solares<\/h2>\n<p>D\u00eda tras d\u00eda se presentan nuevos inventos para conseguir <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/primer-panel-solar-ultra-lowcost\/5591\/\">paneles solares eficientes y baratos<\/a>. Sin embargo, la luz solar depende de tantos factores que la posibilidad de alcanzar la energ\u00eda solar sustentable parece todav\u00eda lejano y difuso. El primer problema es el movimiento de la tierra y la formaci\u00f3n de nubes que hacen impredecible la capacidad de producci\u00f3n diaria.<\/p>\n<p>Por otro lado, los materiales para la fabricaci\u00f3n de estos paneles son costosos y dif\u00edciles de obtener. Y, finalmente, la energ\u00eda solar requiere de mucho espacio f\u00edsico. Los grandes paneles instalados en granjas solares proyectan una extensa sombra sobre las tierras que ocupan. Esto hace que cada gobierno tenga que sopesar las implicaciones de sacrificar hect\u00e1reas de territorio que podr\u00eda usarse para otros fines.<\/p>\n<p>Todo esto podr\u00eda quedar en el pasado gracias al uso de\u00a0<strong>redes de heteroestructuras<\/strong>, un tipo de materiales que se conoce desde principios de la d\u00e9cada de los setenta, aunque es gracias a la tecnolog\u00eda y conocimiento actual, se ha podido llegar a explotar en todo su potencial. A partir de este material, se podr\u00edan producir cristales que reemplazar\u00edan el uso de silicios, que resultan caros y pocos sustentables.<\/p>\n<p>Los cristales de silicio se emplean sobre la superficie de los paneles fotovoltaicos para captar las part\u00edculas fot\u00f3nicas de la luz solar y dirigirla hacia el mecanismo que convierte esta luz en electricidad. Estos cristales ya han sido motivo de largos debates debido a que su extracci\u00f3n est\u00e1 ligada a la explotaci\u00f3n y la contaminaci\u00f3n medioambiental.<\/p>\n<h2>Fabricar paneles solares con basura<\/h2>\n<p>Como mencionamos anteriormente, el elemento clave en este descubrimiento es <strong>el uso de redes de heteroestructuras<\/strong>. Para crear este material, se apilan capaz de diferentes materiales para formar cristales capaces de absorber mucha m\u00e1s luz solar que los silicios. Estas capas tienen un grosor de apenas unos pocos cientos de \u00e1tomos, pero el proceso de fabricaci\u00f3n es incre\u00edblemente preciso.<\/p>\n<p>Los materiales usados para cada una de las capas de estas redes de heteroestructuras se obtienen a partir de elementos comunes de nuestro planeta y que se extraer incluso de desechos de la industria y la construcci\u00f3n. Las pruebas realizadas hasta ahora han mostrado un incremento en la capacidad de conducir las part\u00edculas fot\u00f3nicas que supera 1000 veces a los cristales actuales.<\/p>\n<p>Lo m\u00e1s prometedor de este nuevo material es la durabilidad que han mostrado. El gran obst\u00e1culo de los materiales superconductores es que su vida \u00fatil es extremadamente corta. A diferencia de otros materiales probados como <strong>las\u00a0perovskitas<\/strong>, los paneles en los que se realizaron los experimentos llegaron a funcionar durante seis meses sin perder sus propiedades.<\/p>\n<p>La investigaci\u00f3n en este material est\u00e1 todav\u00eda en sus primeras fases de experimentaci\u00f3n. Los cient\u00edficos todav\u00eda no saben exactamente por qu\u00e9 esta combinaci\u00f3n particular de elementos incrementa de tal manera la conductividad fotoel\u00e9ctrica de los paneles, aunque la evidencia emp\u00edrica es indiscutible.<\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p>Son muchos los recursos que se destinan a descubrir la clave para obtener <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/energias-termica-y-fotovoltaica\/5371\/\">paneles solares eficientes y sustentables<\/a> que nos permitan aprovechar la luz solar sin altos costos econ\u00f3micos y ambientales. El desarrollo de este innovador cristal es una gran noticia, ya que podr\u00eda significar que la era de la energ\u00eda fotovoltaica eficiente est\u00e1 al alcance de nuestras manos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La energ\u00eda solar es una gran fuente alternativa de electricidad. La luz del sol es un elemento virtualmente infinito y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este panel solar multiplica por 1000 la electricidad: un enigm\u00e1tico cristal est\u00e1 detr\u00e1s del r\u00e9cord\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/este-panel-solar-multiplica-por-1000\/5851\/#more-5851\" aria-label=\"Leer m\u00e1s sobre Este panel solar multiplica por 1000 la electricidad: un enigm\u00e1tico cristal est\u00e1 detr\u00e1s del r\u00e9cord\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":5854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=5851"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/5851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/5854"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=5851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=5851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=5851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}