{"id":6038,"date":"2024-05-06T16:30:38","date_gmt":"2024-05-06T14:30:38","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6038"},"modified":"2024-05-06T16:30:38","modified_gmt":"2024-05-06T14:30:38","slug":"construccion-aislante-celulosa","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/construccion-aislante-celulosa\/6038\/","title":{"rendered":"El mejor aislante en construcci\u00f3n es el material que m\u00e1s desechas: solo lo produce una f\u00e1brica"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hormigon-construccion-aislante\/5401\/\">aislamiento de una construcci\u00f3n es uno de los aspectos m\u00e1s complejos<\/a>, ya que los materiales de uso m\u00e1s habitual son altamente contaminantes y hasta peligrosos para la salud. Sin embargo, dos hermanos espa\u00f1oles unieron fuerzas y consiguieron crear el aislante en construcci\u00f3n perfecto y <strong>son los \u00fanicos en toda Espa\u00f1a en producirlo<\/strong>. Te explicamos de qu\u00e9 se trata este innovador material del futuro.<\/p>\n<h2>El mejor aislante en construcci\u00f3n se obtiene de los desechos<\/h2>\n<p>Los hermanos I\u00f1igo y Julen Puncel son los fundadores de la primera y, hasta ahora, \u00fanica f\u00e1brica en Espa\u00f1a de aislante natural y sustentable que aprovecha el material que se desecha d\u00eda a d\u00eda por toneladas en todo el mundo. Pero no es casualidad que sean precisamente ellos quienes hayan llegado a esta soluci\u00f3n tan sencilla y eficiente para dar un salto hacia la construcci\u00f3n sustentable.<\/p>\n<p>Los hermanos llevaban ya m\u00e1s de una d\u00e9cada de experiencia trabajando en materiales de construcci\u00f3n sustentables y accesibles que ofrecieran una buena alternativa a los productos tradicionales que se obtienen en el mercado actual. Todo este conocimiento acumulado les permiti\u00f3, en 2011, fundar <strong>AISLANAT<\/strong>, la \u00fanica f\u00e1brica en Europa de aislante verde y barato para uso en la construcci\u00f3n.<\/p>\n<p>El aislante de AISLANAT aprovecha todas las propiedades que ofrece la celulosa para mantener la temperatura, absorber la humedad del ambiente y climatizar de manera eficiente cada ambiente de una edificaci\u00f3n. Esta celulosa se obtiene nada m\u00e1s ni nada menos que de los peri\u00f3dicos desechados, los cuales son reciclados y transformados en espuma ligera, altamente aislante y f\u00e1cil de aplicar.<\/p>\n<p>Actualmente, AISLANAT es socio fundador de ECIA, una alianza de diferentes fabricantes europeos de aislantes a base de celulosa que est\u00e1n marcando la diferencia en el sector de la construcci\u00f3n hacia\u00a0 un futuro sustentable. Esto ha llevado a que la empresa fundada por loes hermanos espa\u00f1oles sea reconocida en todo el mundo por su trabajo pionero y el compromiso que tienen con su misi\u00f3n de sustentabilidad.<\/p>\n<h2>\u00bfCu\u00e1les son las ventajas del aislante de celulosa?<\/h2>\n<p>Em primer lugar, nos encontramos con un material que se obtiene de bases naturales que no afectan al ambiente como la mayor\u00eda de los aislantes en la construcci\u00f3n. El proceso de transformaci\u00f3n de diarios desechados en espuma aislante es muy sencillo, requiriendo reacciones qu\u00edmicas muy b\u00e1sicas que<strong> no emiten CO2 al ambiente<\/strong>, convirti\u00e9ndolo en una fuerte apuesta de cara al futuro.<\/p>\n<p>Teniendo en cuenta que <strong>cada persona, en promedio, desecha 150 kilogramos de peri\u00f3dicos anualmente<\/strong>, podemos calcular que estar\u00edamos eliminando toneladas de residuos que se convierte en un aislante den la construcci\u00f3n de primer uso. Una verdadera proeza de de sustentabilidad que supone un gran impulso en los esfuerzos para reducir la huella de carbono.<\/p>\n<p>Por otro lado, tambi\u00e9n hay que mencionar que la espuma de aislamiento de AISLANAT es mucho m\u00e1s ligera que los materiales tradicionales, lo que la hace mucho m\u00e1s sencilla de transportar, reduciendo tambi\u00e9n las emisiones de CO2 en el aspecto log\u00edstico. El aislante es de consistencia espumosa y se puede aplicar tanto en paredes como en tuber\u00edas.<\/p>\n<p>La celulosa es transpirable, por lo que permite ventilar eficientemente cada ambiente, pero tambi\u00e9n puede absorber la humedad. Una vez transformados en esta espuma, los peri\u00f3dicos reciclados mantienen burbujas de aire en su interior que evitan con gran efectividad la transferencia de calor, ayudando as\u00ed a reducir la cantidad de energ\u00eda necesaria para climatizar cualquier ambiente.<\/p>\n<p>Espa\u00f1a est\u00e1 invirtiendo una gran cantidad de recursos para ayudar en los esfuerzo globales para reducir la huella de carbono y contribuir a industrias sustentables. Este innovador aislante en la construcci\u00f3n, as\u00ed como la tecnolog\u00eda detr\u00e1s de estas <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/casas-prefabricadas-espana\/5443\/\">casas prefabricadas s\u00faper baratas<\/a> demuestran que esos esfuerzos est\u00e1n dando fruto y estamos m\u00e1s cerca de alcanzar las metas de sostenibilidad planteadas para el 2030.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El aislamiento de una construcci\u00f3n es uno de los aspectos m\u00e1s complejos, ya que los materiales de uso m\u00e1s habitual &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El mejor aislante en construcci\u00f3n es el material que m\u00e1s desechas: solo lo produce una f\u00e1brica\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/construccion-aislante-celulosa\/6038\/#more-6038\" aria-label=\"Leer m\u00e1s sobre El mejor aislante en construcci\u00f3n es el material que m\u00e1s desechas: solo lo produce una f\u00e1brica\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":6040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6038"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6040"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}