{"id":6192,"date":"2024-05-13T14:30:18","date_gmt":"2024-05-13T12:30:18","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6192"},"modified":"2024-05-13T14:30:18","modified_gmt":"2024-05-13T12:30:18","slug":"energia-6000-millones-litros-agua","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/energia-6000-millones-litros-agua\/6192\/","title":{"rendered":"La energ\u00eda que nos va a costar 6000 millones de litros de agua: es renovable, pero preocupa por esto"},"content":{"rendered":"<p>Las teor\u00edas que sustentan las bases y metas para detener el cambio, hoy se encuentran en una estrecha tensi\u00f3n. Una noticia ha tomado estado p\u00fablico en la ciudad de La Robla que publica que una compa\u00f1\u00eda ha solicitado un permiso para<strong> la extracci\u00f3n de 6000 millones de litros de agua<\/strong> de un embalse para la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/aerogenerador-mas-potente\/6032\/\">creaci\u00f3n de energ\u00eda sostenible<\/a> es m\u00e1s que discutible.<\/p>\n<h2>La utilizaci\u00f3n de recursos renovables para generar combustible verde<\/h2>\n<p>Esta es la cuesti\u00f3n, como dir\u00eda <em>Hamlet<\/em> de Shakespeare. \u00bfCu\u00e1nta energ\u00eda renovable se precisa para generar otras tantas y combustibles sostenibles? \u00bfC\u00f3mo se mide el \u00e9xito de una energ\u00eda cuando se abusa del consumo de otra para su creaci\u00f3n? La paradoja sigue abierta.<\/p>\n<p>En el peri\u00f3dico de <em>La Robla de Le\u00f3n<\/em> se public\u00f3 un informe de una solicitud de la compa\u00f1\u00eda Roblum a la Confederaci\u00f3n Hidrogr\u00e1fica del Duero (CHD) para la extracci\u00f3n de 6000 millones de litros al a\u00f1o que servir\u00e1n para<strong> la creaci\u00f3n de dos plantas de generaci\u00f3n de energ\u00eda renovable<\/strong>.<\/p>\n<p>Asimismo, informan m\u00e1s detalles de las nuevas plantas a instalar en el \u00e1rea de El Crisp\u00edn de esa localidad. Una de ellas se ocupar\u00e1 de generar electricidad por biomasa, y la segunda para metanol e hidr\u00f3geno verde que, adem\u00e1s, consumir\u00e1 di\u00f3xido de carbono.<\/p>\n<p>Esta noticia ha impactado fuertemente en la sociedad y<strong> es hoy una discusi\u00f3n obligatoria entre las autoridades<\/strong>, los privados y hasta en las mesas de bares. Y es que todos nos sentimos responsables de cuidar el planeta, y los l\u00edmites del bien y del mal aqu\u00ed est\u00e1n vulnerables.<\/p>\n<h2>Datos cient\u00edficos para aportar a la discusi\u00f3n<\/h2>\n<p>Existen informes y evaluaciones cient\u00edficas que aportan cifras del consumo de agua por sector energ\u00e9tico que respaldan una teor\u00eda, como otras que ponen en jaque el<strong> exceso de consumo de un recurso para la generaci\u00f3n de otro<\/strong> y subrayan la importancia del valor resultante.<\/p>\n<p>Parafraseando a Maquiavelo, casi en la misma \u00e9poca de Hamlet quien afirmaba que el fin justifica los medios, en este caso la frase es por lo menos m\u00e1s que discutible y es materia urgente a resolver por las autoridades competentes.<\/p>\n<p>Seg\u00fan un informe de la Agencia Internacional de la Energ\u00eda (IEA), <strong>el sector energ\u00e9tico gasta 55 000 millones de m3 agua por a\u00f1o<\/strong>. Solo para fuentes de energ\u00eda y no para combustibles, quien ocupa los primeros puestos es la industria basada en combustibles f\u00f3siles con un consumo de 11,200 km\u00b3.<\/p>\n<p>Como era de esperar, la noticia no sorprende. El estudio contin\u00faa postulando en segunda posici\u00f3n a la energ\u00eda nuclear con 4 km\u00b3 y a las energ\u00edas renovables con un 1 Km3. Sin embargo, existen otros reportes en la vereda opuesta que ofrecen datos m\u00e1s detallados.<\/p>\n<p>Este es el caso del estudio realizado por Joint Research Centre (JRC), que nos acerca<strong> la cifra del consumo de agua por unidad de energ\u00eda producida<\/strong>. Aqu\u00ed las represas hidroel\u00e9ctricas lideraban el ranking, pero eran seguidas de cerca por los biocombustibles.<\/p>\n<h2>Datos de consumo de agua en Espa\u00f1a<\/h2>\n<p>Existe un estudio m\u00e1s reciente confeccionado como trabajo final de un master por Karapet Grigoryan, que fue premiado con el Premio C\u00e1tedra Aquae de Econom\u00eda del Agua. Los datos elaborados en este informe han surgido del consumo en Espa\u00f1a.<\/p>\n<p>Seg\u00fan Grigoryan, la huella h\u00eddrica (WF) se modifica dr\u00e1sticamente de acuerdo al tipo de energ\u00eda. En este sentido, la generaci\u00f3n de electricidad a partir de biodiesel es del 2.2%, pero<strong> la huella h\u00eddrica asciende a un 65%<\/strong>.<\/p>\n<p>En el lado opuesto, destaca a la energ\u00eda e\u00f3lica que presenta menos del 1% de WF y que contribuye un 18,7% de electricidad. Con estos datos, es hora de establecer pol\u00edticas claras para que los proyectos de generaci\u00f3n de recurso sostenible.<\/p>\n<p>No dejarse enceguecer con el brillo de sus resultados a costa de producir<strong> escases de un recurso tan vital como el agua<\/strong>. Abogamos por la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/absorber-contaminacion-geotermia\/3545\/\">creaci\u00f3n e innovaci\u00f3n de nuevas tecnolog\u00edas <\/a>de potabilizaci\u00f3n de aguas recicladas para generar energ\u00eda e impedir el consumo de agua dulce fresca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las teor\u00edas que sustentan las bases y metas para detener el cambio, hoy se encuentran en una estrecha tensi\u00f3n. Una &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La energ\u00eda que nos va a costar 6000 millones de litros de agua: es renovable, pero preocupa por esto\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-6000-millones-litros-agua\/6192\/#more-6192\" aria-label=\"Leer m\u00e1s sobre La energ\u00eda que nos va a costar 6000 millones de litros de agua: es renovable, pero preocupa por esto\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":6219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6192"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6219"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}