{"id":6281,"date":"2024-05-12T17:00:45","date_gmt":"2024-05-12T15:00:45","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6281"},"modified":"2024-05-12T17:00:45","modified_gmt":"2024-05-12T15:00:45","slug":"cemento-ecologico-que-limpia-el-aire","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/cemento-ecologico-que-limpia-el-aire\/6281\/","title":{"rendered":"El cemento ecol\u00f3gico que limpia el aire y el agua: utiliza radiaci\u00f3n y la energ\u00eda del sol"},"content":{"rendered":"<p>El concreto es el material m\u00e1s utilizado en la construcci\u00f3n y es, a su vez, uno de los m\u00e1s nocivos para el medio ambiente. Entre las diferentes alternativas que se investigan, como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hormigon-construccion-nuevo-material\/5856\/\">este material que promete reemplazar al hormig\u00f3n<\/a>, encontramos este <strong>cemento ecol\u00f3gico que es capaz de limpiar el aire y purificar el agua<\/strong>, desarrollado por un equipo de universitarios mexicanos.<\/p>\n<h2>El nuevo cemento ecol\u00f3gico que purifica el aire y el agua<\/h2>\n<p>El concreto es un material clave en la construcci\u00f3n, el cual sirve para unir las estructuras y dotarlas de la resistencia y elasticidad necesarias para poder resistir los embates del clima, aislar las construcciones y soportar impactos y movimientos. Sin embargo, <strong>por cada tonelada de concreto que se produce, se emite otra tonelada de CO2 al ambiente<\/strong>.<\/p>\n<p>El concreto es tambi\u00e9n un material aislante e impermeable, algo \u00fatil para un edificio, pero que impide que la tierra absorba el agua y los gases nocivos y que, por consiguiente, incrementa el riesgo de inundaciones y el efecto invernadero. Desde hace tiempo se viene buscando una soluci\u00f3n efectiva para este gran problema sin mucho \u00e9xito hasta ahora.<\/p>\n<p>La respuesta podr\u00eda estar en mano de un equipo de estudiantes de la Facultad de Estudios Superiores (FES) Arag\u00f3n, de la UNAM, que han conseguido desarrollar un concreto ecol\u00f3gico capaz de purificar el aire y el agua gracias a un proceso llamado <strong>fotocat\u00e1lisis<\/strong>. Se trata de dos materiales diferentes aunque desarrollados a partir de la misma base que promete solventar el problema del cemento.<\/p>\n<h2>C\u00f3mo funciona este cemento ecol\u00f3gico<\/h2>\n<p>La clave del cemento ecol\u00f3gico desarrollado por los acad\u00e9micos mexicanos est\u00e1 en la propiedad de la fotocat\u00e1lisis. Se trata de una reacci\u00f3n que convierte la energ\u00eda solar en energ\u00eda qu\u00edmica y ayuda a eliminar el CO2 del ambiente cuando el material recibe el impacto de los rayos UV. El segundo material es permeable, por lo que filtra el agua dej\u00e1ndola llegar al sustrato y limpi\u00e1ndola por medio de fotocat\u00e1lisis.<\/p>\n<p>Las propiedades de este nuevo material son muy prometedoras, ya que puede usarse en edificios, banquetas y jardines. Al permitir el paso del agua hacia el suelo, <strong>previene inundaciones y evita la degradaci\u00f3n de monumentos hist\u00f3ricos<\/strong>, lo que ha sido hasta ahora una fuerte problem\u00e1tica en muchas partes del mundo adem\u00e1s de M\u00e9xico.<\/p>\n<p>El cemento ecol\u00f3gico est\u00e1 fabricado con materiales reciclados como cascajos, neum\u00e1ticos desechados y fibras org\u00e1nicas, por lo que su producci\u00f3n no emite gases de efecto invernadero. Es capaz de limpiar hasta un 30% de los gases contaminantes del aire y es capaz de convertir las sustancias nocivas del agua de lluvia en nitratos que enriquecen el suelo y previenen la contaminaci\u00f3n de las napas.<\/p>\n<h2>El problema del concreto fotocatal\u00edtico<\/h2>\n<p>En general, todas las propiedades de este material son altamente positivas y prometedoras. <strong>Ya se ha probado en construcciones de M\u00e9xico con \u00e9xito<\/strong> y el mismo concreto, al llegar al fin de su vida \u00fatil, se puede recuperar y reciclar para producir nuevo material.<\/p>\n<p>Las dificultades que atraviesan por el momento los creadores de este cemento ecol\u00f3gico vienen principalmente del lado de la rentabilidad. Los universitarios no cuentan con una planta productiva, por lo que se fabrica artesanalmente. Esto eleva su coste a cuatro veces el precio regular del concreto tradicional, por lo que no resulta nada accesible.<\/p>\n<h2>\u00bfHay mercado para el cemento fotocatal\u00edtico?<\/h2>\n<p>Por el momento, <strong>se trata de un material incipiente que todav\u00eda requiere de fuentes de financiaci\u00f3n<\/strong> que permitan su producci\u00f3n a gran escala. No parece que pueda competir con otros desarrollos mejor fundamentados como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/construccion-ladrillo-huevo-3d\/5699\/\">los ladrillos hechos con huevo<\/a>, tambi\u00e9n de origen mexicano, por lo que no se espera que ingrese al mercado en un futuro pr\u00f3ximo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concreto es el material m\u00e1s utilizado en la construcci\u00f3n y es, a su vez, uno de los m\u00e1s nocivos &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El cemento ecol\u00f3gico que limpia el aire y el agua: utiliza radiaci\u00f3n y la energ\u00eda del sol\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/cemento-ecologico-que-limpia-el-aire\/6281\/#more-6281\" aria-label=\"Leer m\u00e1s sobre El cemento ecol\u00f3gico que limpia el aire y el agua: utiliza radiaci\u00f3n y la energ\u00eda del sol\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":6297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6281"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6297"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}