{"id":6404,"date":"2024-05-15T16:30:28","date_gmt":"2024-05-15T14:30:28","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6404"},"modified":"2024-05-15T16:30:28","modified_gmt":"2024-05-15T14:30:28","slug":"aerogenerador-suelo-autoconsumo","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/aerogenerador-suelo-autoconsumo\/6404\/","title":{"rendered":"Este aerogenerador para tu casa funciona incluso en el suelo: no te creer\u00e1s que sea capaz de hacer esto"},"content":{"rendered":"<p>La generaci\u00f3n de <strong>energ\u00eda limpia y renovable en entornos urbanos<\/strong> es una cuesti\u00f3n todav\u00eda pendiente en la agenda de sustentabilidad. Si bien existen innovadores paneles solares para casa, esto no es suficiente como para tener un impacto considerable en el autoconsumo. Con el nuevo aerogenerador para tu casa que ha lanzado esta compa\u00f1\u00eda, podr\u00edamos llegar a generar energ\u00eda e\u00f3lica en ciudades.<\/p>\n<h2>\u00bfUn aerogenerador para tu casa?<\/h2>\n<p>Para producir electricidad mediante energ\u00eda e\u00f3lica, es necesario recoger la fuerza de los vientos implacables que azotan a altas velocidades las enormes aspas de las turbinas puestas a gran altura. <strong>Esto implica que se requieran varias hect\u00e1reas de terreno despejado<\/strong> para poder obtener electricidad mediante energ\u00eda e\u00f3lica. Estas tierras no pueden usarse para nada m\u00e1s.<\/p>\n<p>El m\u00e9todo m\u00e1s com\u00fan para obtener electricidad limpia en ciudades son los paneles solares, pero estos est\u00e1n limitados a las horas diurnas y su eficiencia es muy variable de acuerdo a las condiciones clim\u00e1ticas. As\u00ed es como han pasado los a\u00f1os y todav\u00eda seguimos buscando maneras alternativas de generar electricidad para los hogares sacando el m\u00e1ximo provecho del espacio disponible en las ciudades.<\/p>\n<p>Con el aerogenerador para tu casa que acaba de dise\u00f1ar la empresa <strong>Katrick<\/strong>, con sede en Glasgow, es posible que finalmente hayamos llegado a la soluci\u00f3n que tanto hemos buscado. Se trata de<strong> aerogeneradores hexagonales que pueden instalarse en cualquier lugar<\/strong>, incluso al nivel del suelo, y podr\u00e1n generar electricidad a partir de las corrientes m\u00e1s suaves de aire que soplan a baja altura.<\/p>\n<h2>C\u00f3mo funcionan los aerogeneradores hexagonales<\/h2>\n<p>Para poder generar energ\u00eda e\u00f3lica sin la necesidad de una gigantesca estructura, el equipo de Katrick Technologies introdujeron un dise\u00f1o revolucionario en sus turbinas: en lugar usar el viento para mover el sistema de transmisi\u00f3n de la turbina, se ha dise\u00f1ado un sistema de canales para llevar las corrientes de viento y acelerarlas, obteniendo as\u00ed energ\u00eda cin\u00e9tica que puede convertirse en electricidad.<\/p>\n<p>El aerogenerador para tu casa de Katrick Technologies est\u00e1 dise\u00f1ado con un marco hexagonal y en un formato modular. Esto <strong>permite instalar tantas turbinas como sean necesarias<\/strong> y distribuirlas de la manera m\u00e1s conveniente entre los edificios. Incluso se pueden instalar en lugares con fuertes corrientes de viento como aer\u00f3dromos y aeropuertos o en tejados de casas y edificios.<\/p>\n<h2>Qu\u00e9 tan eficiente es este aerogenerador<\/h2>\n<p>Se han realizado 51 pruebas sometiendo este aerogenerador para tu casa a diferentes tipos de circunstancias para comprobar su capacidad de producci\u00f3n de energ\u00eda durante m\u00e1s de 80 horas de trabajo. Los resultados han incluso superado a las m\u00e1s optimistas de las previsiones hechas por los ingenieros que las dise\u00f1aron, consiguiendo extraer<strong> hasta 41,1MW de vientos de hasta 10,2m\/s<\/strong>.<\/p>\n<p>Esto es gracias a sus palabas flexibles que barren los recept\u00e1culos donde se encuentran atrapando cualquier corriente de aire y llev\u00e1ndola hacia el mecanismo en el centro del aerogenerador. Esta tecnolog\u00eda tambi\u00e9n le permite aprovechar los bruscos cambios de direcci\u00f3n del viento que ocurren constantemente a nivel del suelo.<\/p>\n<p>Todo parece estar listo para que, en los pr\u00f3ximos meses, podamos ver algunos prototipos completamente funcionales destinados a llegar al mercado de la generaci\u00f3n de energ\u00eda limpia para entornos urbanos. Con este incre\u00edble dise\u00f1o de Katrick Technologies, ser\u00eda posible obtener energ\u00eda e\u00f3lica sin tener que ocupar grandes extensiones de tierra, sin amenazar a las aves, y aprovechando al m\u00e1ximo el espacio.<\/p>\n<h2>\u00bfCu\u00e1ndo podr\u00e1s adquirir estos aerogeneradores hexagonales?<\/h2>\n<p>Esta tecnolog\u00eda todav\u00eda est\u00e1 siendo sometida a pruebas por parte de los equipos de desarrollo para obtener el m\u00e1ximo rendimiento posible en la producci\u00f3n de electricidad limpia y renovable. Mientras esperamos a que el <strong>aerogenerador para tu casa<\/strong> empiece a verse en las calles y edificios, puedes descubrir <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/agua-caliente-en-casa-gratis\/6277\/\">este calentador de agua solar casero que puede ofrecerte agua caliente gratis<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La generaci\u00f3n de energ\u00eda limpia y renovable en entornos urbanos es una cuesti\u00f3n todav\u00eda pendiente en la agenda de sustentabilidad. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este aerogenerador para tu casa funciona incluso en el suelo: no te creer\u00e1s que sea capaz de hacer esto\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/aerogenerador-suelo-autoconsumo\/6404\/#more-6404\" aria-label=\"Leer m\u00e1s sobre Este aerogenerador para tu casa funciona incluso en el suelo: no te creer\u00e1s que sea capaz de hacer esto\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":6407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6404"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6407"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}