{"id":6671,"date":"2024-05-27T16:00:08","date_gmt":"2024-05-27T14:00:08","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6671"},"modified":"2024-05-27T16:00:08","modified_gmt":"2024-05-27T14:00:08","slug":"motor-huracan-hidrogeno-electricidad","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/motor-huracan-hidrogeno-electricidad\/6671\/","title":{"rendered":"El motor \u00abhurac\u00e1n\u00bb que destroza al hidr\u00f3geno: fusiona estos dos combustibles y no deber\u00eda existir"},"content":{"rendered":"<p>Lamborghini ha creado su nuevo motor \u00abHurac\u00e1n\u00bb, cuyo lanzamiento est\u00e1 previsto para finales de este a\u00f1o. Ser\u00e1 un modelo <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-hibrido-sin-limite-velocidad\/5912\/\">hibrido<\/a> que fusionar\u00e1 la electricidad con el hidr\u00f3geno, destacando este \u00faltimo como fuente de energ\u00eda. No deber\u00eda existir, pero ahora veremos las caracter\u00edsticas de esta maravilla.<\/p>\n<h2>El nuevo motor en un autom\u00f3vil de Lamborghini: tercer integrante de sus coches h\u00edbridos<\/h2>\n<p>Este coche es conocido por el c\u00f3digo clave de Lamborghini 634. Es el \u00faltimo integrante del <strong>grupo de veh\u00edculos electrificados<\/strong> de este fabricante. Posee un V8 que incluye un sistema h\u00edbrido de \u00faltima generaci\u00f3n impulsado por una combinaci\u00f3n de combustible y electricidad.<\/p>\n<p>Incluye una caja de cambios manual de doble embrague y ocho velocidades, aunque tambi\u00e9n saldr\u00e1 una versi\u00f3n autom\u00e1tica con las mismas caracter\u00edsticas. Este es un caso m\u00e1s que adelanta la marca hacia la completa electrificaci\u00f3n de sus coches, enmarcada en su programa \u00abDirezione Cor Tauri\u00bb.<\/p>\n<h2>Las caracter\u00edsticas del \u201cHurac\u00e1n\u201d: potencia y belleza en una m\u00e1quina de alta gama<\/h2>\n<p>Para empezar, esta m\u00e1quina combina los <strong>atributos de revoluciones altas y versatilidad<\/strong> que caracterizan las m\u00e1quinas de esta marca. Incluye tres motores el\u00e9ctricos que generan una potencia m\u00e1xima de 800 CV con 10,000 rpm, lo que lo hace m\u00e1s r\u00e1pido y fuerte que sus competidores.<\/p>\n<p>Este es un valor usual para motores de carrera y de propulsor turboalimentado, pero no para m\u00e1quinas de producci\u00f3n en serie. Por otra parte, su cilindrada de 4 litros le permite desarrollar una incre\u00edble potencia promedio de 200 CV por cada litro.<\/p>\n<p>Asimismo, <strong>tiene un par m\u00e1ximo de fuerza de 730 Nm<\/strong>. Con estas especificaciones del fabricante, tiene una progresi\u00f3n parecida a la de uno de alta competencia, esto se debe a la integraci\u00f3n de alto rendimiento existente entre el motor de combusti\u00f3n y el componente el\u00e9ctrico.<\/p>\n<p>Otra propiedad destacable, aunque no es de la m\u00e1quina propiamente dicho, pero s\u00ed est\u00e1 relacionada con su alto desempe\u00f1o, consiste en su sistema trasero el\u00e9ctrico que fue dise\u00f1ado y desarrollado especialmente para esta asombrosa m\u00e1quina h\u00edbrida, pues es capaz de soportar esta potencia.<\/p>\n<p>Este sistema se encuentra ubicado entre la <strong>caja de cambios de doble embrague<\/strong> y el motor de combusti\u00f3n. Contiene la unidad el\u00e9ctrica axial y el inversor. Fue construido para tener la capacidad de desarrollar altos rendimientos de potencia y par m\u00e1ximo con esta combinaci\u00f3n de combustible.<\/p>\n<p>Puede desarrollar 110 kW a 3500 rpm y 300 Nm. \u00bfIncre\u00edble, verdad? Lo mejor es que tiene un peso muy ligero y un tama\u00f1o muy compacto. Y es precisamente estas dimensiones y peso lo que permiten al motor alcanzar velocidades de desplazamiento grandes y sostenidas.<\/p>\n<h2>Las otras especificaciones de la m\u00e1quina \u201cHurac\u00e1n\u201d que la hacen singular<\/h2>\n<p>Un elemento medular al momento del dise\u00f1o es la definici\u00f3n del sonido, <strong>para hacer al motor \u00fanico<\/strong>. Aqu\u00ed se intensifica el sonido, que va creciendo a medida que aumentan las revoluciones, alcanzando su m\u00e1ximo cuando las revoluciones tambi\u00e9n llegan a su tope, es decir, a 10,000 rpm.<\/p>\n<p>Esto se refiere tanto a la frecuencia como al volumen. Tambi\u00e9n se armoniz\u00f3 con las vibraciones que env\u00eda el cig\u00fce\u00f1al al chasis del coche, en consonancia con el rugido caracter\u00edstico de los Lamborghini. As\u00ed que tendr\u00e1s una experiencia sin igual en lo que se refiere a sensaci\u00f3n mental y f\u00edsica.<\/p>\n<p>Por otro lado, esta m\u00e1quina tiene una gran belleza est\u00e9tica. Asimismo, resulta f\u00e1cil de reparar por estar hecha de forma modular. Sin embargo, no te enga\u00f1es; lo mejor que puedes hacer en caso de alguna aver\u00eda es llevar a tu beb\u00e9 a los propios talleres de Lamborghini.<\/p>\n<p>En resumen, esta m\u00e1quina h\u00edbrida denominada<strong> \u00abHurac\u00e1n\u00bb por Lamborghini<\/strong> hace honor a su nombre, por la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-hidrogeno-electrico\/4988\/\">potencia<\/a> y el par m\u00e1ximo que puede desarrollar con la combinaci\u00f3n de combustible para la que fue dise\u00f1ada. De tal manera, que solo te queda probar este coche y sentir la emoci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lamborghini ha creado su nuevo motor \u00abHurac\u00e1n\u00bb, cuyo lanzamiento est\u00e1 previsto para finales de este a\u00f1o. Ser\u00e1 un modelo hibrido &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El motor \u00abhurac\u00e1n\u00bb que destroza al hidr\u00f3geno: fusiona estos dos combustibles y no deber\u00eda existir\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-huracan-hidrogeno-electricidad\/6671\/#more-6671\" aria-label=\"Leer m\u00e1s sobre El motor \u00abhurac\u00e1n\u00bb que destroza al hidr\u00f3geno: fusiona estos dos combustibles y no deber\u00eda existir\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":6673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6671"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6673"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}