{"id":6921,"date":"2024-05-28T16:30:41","date_gmt":"2024-05-28T14:30:41","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=6921"},"modified":"2024-05-28T16:30:41","modified_gmt":"2024-05-28T14:30:41","slug":"energia-fracaso-historico-espana","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/energia-fracaso-historico-espana\/6921\/","title":{"rendered":"Fracaso hist\u00f3rico a las puertas de Espa\u00f1a: hemos perdido 2 billones y retrocedido un siglo en energ\u00eda"},"content":{"rendered":"<p>En Espa\u00f1a llevamos un largo camino recorrido en desarrollo e instalaci\u00f3n de paneles solares, ya sea en grandes granjas fotovoltaicas, o en <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/panel-solar-para-autoconsumo\/6126\/\">innovadores modelos de paneles para autoconsumo<\/a>. Ahora podr\u00edamos estar frente a un importante tropiezo en esta v\u00eda debido a un importante proyecto internacional de energ\u00eda fotovoltaica a gran escala que <strong>mantiene congelados m\u00e1s de 2 billones de euros en capital de inversi\u00f3n<\/strong>.<\/p>\n<h2>La gigantesca granja solar de 2 billones de euros<\/h2>\n<p>En 2020 se anunciaba el gigantesco proyecto\u00a0<strong>Noor Midelt<\/strong>, un complejo de paneles solares para generaci\u00f3n de energ\u00eda h\u00edbrida por medio de celdas solares y bater\u00edas . Esta central se instalar\u00eda en Marruecos y ser\u00eda una importante concesi\u00f3n para las empresas energ\u00e9ticas espa\u00f1olas como Iberdrola, Acciona y TSK, siendo esta \u00faltima la que obtuvo la concesi\u00f3n.<\/p>\n<p>La planta costar\u00eda m\u00e1s de 2 billones de euros y se construir\u00eda en dos etapas, con una capacidad de almacenamiento de energ\u00eda para 800Mw en la primera etapa y 800Mw m\u00e1s durante la segunda. Espa\u00f1a ha formado parte de este proyecto desde el principio y ha comprometido un importante capital. Los beneficios, tanto en sustentabilidad como econ\u00f3micos, de este proyecto eran muy prometedores.<\/p>\n<p>Sin embargo, la planta, que ya deber\u00eda estar en proceso de construcci\u00f3n desde 2022, sigue detenida sin que se haya levantado ninguna estructura en el \u00e1rea de m\u00e1s de 650 hect\u00e1reas que fue designada para la instalaci\u00f3n de este ambicioso proyecto. Esto se debe a <strong>disputas entre el Ministerio de Energ\u00eda y el operador de la red ODEE<\/strong>, Masen, con respecto al tipo de tecnolog\u00eda que se emplear\u00e1.<\/p>\n<h2>Una ciudad de paneles solares<\/h2>\n<p>En los papeles, Noor Midelt est\u00e1 dise\u00f1ada como una mega planta de energ\u00eda solar capaz de abastecer a miles de hogares generando energ\u00eda el\u00e9ctrica limpia y renovable a un coste de 0,6\u20ac por megavatio. Producci\u00f3n de energ\u00eda limpia a gran escala a bajo precio, realmente fue un anuncio que promet\u00eda solucionar muchos problemas para la saturada red el\u00e9ctrica europea, pero las cosas no avanzan.<\/p>\n<p>En el centro del conflicto nos encontramos con la tecnolog\u00eda de las celdas solares, que, seg\u00fan estaba dispuesto desde un principio, <strong>combinar\u00eda tecnolog\u00eda fotovoltaica con CSP<\/strong> (Energ\u00eda Solar Concentrada, en su acr\u00f3nimo anglosaj\u00f3n). Sin embargo, tras otorgar la concesi\u00f3n al operador, el Ministerio estableci\u00f3 que s\u00f3lo podr\u00edan empezar a trabajar en la obra si abandonaban la tecnolog\u00eda CSP.<\/p>\n<p>La tecnolog\u00eda fotovoltaica es m\u00e1s barata que la CSP, pero ofrece una menor capacidad de almacenamiento de energ\u00eda que su contraparte. La alternativa que el Ministerio ofreci\u00f3 a Masen, fue que mantuvieran el sistema CSP pero que cambiaran del almacenamiento t\u00e9rmico en sal, a bater\u00edas. Mientras el operador dirime estos detalles con el Ministerio de Energ\u00eda, el proyecto sigue demor\u00e1ndose otro a\u00f1o.<\/p>\n<h2>\u00bfEl fin del proyecto solar de 2 billones de euros?<\/h2>\n<p>Desde las empresas los directivos afirman que el proyecto ya est\u00e1 en la<strong> \u00faltima fase previa a la implementaci\u00f3n y todos los miembros del proyecto estaban comprometidos<\/strong> con su realizaci\u00f3n. Se supone que las cuestiones pendientes son detalles que deber\u00edan poder llegar a un acuerdo en poco tiempo. Es importante que la planta inicie su construcci\u00f3n para poder amortizar el capital.<\/p>\n<p>El Banco Mundial ya ha advertido que, al tiempo que demoren los miembros del proyecto en ponerse de acuerdo con respecto a la tecnolog\u00eda, hay que sumarle una demora de al menos 30 meses desde que inicien las obras hasta que la planta est\u00e9 plenamente operativa. Mientras tanto, 2 billones de euros en capital est\u00e1n detenidos a la espera de una decisi\u00f3n definitiva.<\/p>\n<h2>La importancia de la energ\u00eda solar para Espa\u00f1a<\/h2>\n<p>Despu\u00e9s del trabajo y capital invertido, Espa\u00f1a se preocupa porque este proyecto de 2 billones de euros pueda concretarse, especialmente despu\u00e9s de haber recibido <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hemos-perdido-300-gw-de-energia\/6412\/\">otro golpe en un proyecto renovable<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Espa\u00f1a llevamos un largo camino recorrido en desarrollo e instalaci\u00f3n de paneles solares, ya sea en grandes granjas fotovoltaicas, &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Fracaso hist\u00f3rico a las puertas de Espa\u00f1a: hemos perdido 2 billones y retrocedido un siglo en energ\u00eda\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-fracaso-historico-espana\/6921\/#more-6921\" aria-label=\"Leer m\u00e1s sobre Fracaso hist\u00f3rico a las puertas de Espa\u00f1a: hemos perdido 2 billones y retrocedido un siglo en energ\u00eda\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":6923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=6921"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/6921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/6923"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=6921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=6921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=6921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}