{"id":708,"date":"2024-01-03T10:00:46","date_gmt":"2024-01-03T09:00:46","guid":{"rendered":"https:\/\/ecoticias.com\/hoyeco\/?p=708"},"modified":"2024-01-03T10:00:46","modified_gmt":"2024-01-03T09:00:46","slug":"cabalgata-reyes","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/cabalgata-reyes\/708\/","title":{"rendered":"Adi\u00f3s a la Cabalgata tal y como la conoc\u00edamos: esta empresa lo cambiar\u00e1 todo en la Cabalgata de 2024"},"content":{"rendered":"<p>La\u00a0<strong>cabalgata de 2024<\/strong> va a ser diferente a la de todos los a\u00f1os. No te preocupes, seguir\u00e1s viendo a Melchor, Gaspar y Baltasar desfilando junto a su corte por las calles de la ciudad. Sin embargo, la pol\u00e9mica est\u00e1 en c\u00f3mo lo har\u00e1n o, mejor dicho, sobre qu\u00e9. En medio de esta incertidumbre, una empresa ha decidido renovarlas para siempre y hacerlas mas sostenibles. Descubre un adelanto de lo que ver\u00e1s.<\/p>\n<h2>\u00bfHabr\u00e1 camellos en la cabalgata de 2024? Esto dice la ley de bienestar animal<\/h2>\n<p>Cuando se aprob\u00f3 en 2023 la ley de bienestar animal, una de las medidas que m\u00e1s polvo levant\u00f3 fue la prohibici\u00f3n definitiva de usar animales en espect\u00e1culos p\u00fablicos. Obviamente, fue una demanda reiterada y constante de asociaciones y partidos pol\u00edticos, <strong>como el todav\u00eda existente PACMA<\/strong>.<\/p>\n<p>Sin embargo, el mismo texto cuenta con varias excepciones que han sido criticadas por ser demasiado interpretables. La \u00fanica expl\u00edcita es la que permite seguir realizando la tauromaquia, pese a incumplir uno de los art\u00edculos con mayor peso dentro de la normativa.<\/p>\n<p>La cabalgata de Reyes del a\u00f1o pasado fue denominada como la \u00faltima de la historia en usar camellos, pero todo <strong>apunta a que este a\u00f1o tambi\u00e9n los veremos<\/strong>. Santander, por ejemplo, plantea llevarlos para que Melchor, Gaspar y Baltasar se monten, aunque no ha sido bien recibido.<\/p>\n<p>Desde Izquierda Unida han decidido interponer medidas judiciales para frenar este espect\u00e1culo y sustituir los animales por carrozas, como hacen la mayor\u00eda de municipios de Espa\u00f1a. De cualquier modo, se espera un aluvi\u00f3n de denuncias en los ayuntamientos que mantengan la tradici\u00f3n.<\/p>\n<h2>La cabalgata de 2024 ser\u00e1 la m\u00e1s sostenible: esta empresa lo ha conseguido<\/h2>\n<p>La pr\u00f3xima edici\u00f3n de la <strong>cabalgata de 2024<\/strong> en la ciudad de Madrid, programada para la tarde del 5 de enero, contar\u00e1 con una destacada novedad: la inclusi\u00f3n de una carroza de la empresa Urbaser en su recorrido. Urbaser, en realidad, es la adjudicataria del Servicio de Limpieza Urgente (SELUR) de la ciudad. \u00bfLo sab\u00edas?<\/p>\n<p>Esta empresa no solo se encargar\u00e1 de la limpieza viaria posterior al evento, sino que tambi\u00e9n participar\u00e1 activamente durante el desfile para sensibilizar sobre la importancia de la sostenibilidad. En un enfoque innovador, el Ayuntamiento busca resaltar en esta edici\u00f3n la inocencia de los ni\u00f1os.<\/p>\n<p>La carroza de Urbaser, con un dise\u00f1o futurista, simbolizar\u00e1<strong> uno de los principales pilares de la empresa<\/strong>: la transformaci\u00f3n de residuos en recursos. Un robot central en la carroza ilustrar\u00e1 este proceso, subrayando el compromiso de Urbaser con la sostenibilidad.<\/p>\n<p>La tarde del 5 de enero ser\u00e1 testigo de c\u00f3mo la carroza transmite a los m\u00e1s peque\u00f1os el mensaje de que un futuro sostenible es uno de los mejores regalos. Esta iniciativa se respalda con el uso de materiales reciclados en la cubierta, una iluminaci\u00f3n de bajo consumo y la distribuci\u00f3n de caramelos sin az\u00facar.<\/p>\n<h2>\u00bfQu\u00e9 otras \u00abcabalgatas sostenibles\u00bb se realizar\u00e1n en Espa\u00f1a?<\/h2>\n<p>Las <strong>cabalgatas sostenibles en Espa\u00f1a<\/strong> cuentan con un destacado antecedente, siendo Barcelona pionera en esta iniciativa en 2020. La ciudad emple\u00f3 carrozas y disfraces confeccionados a partir de materiales reciclados, logrando un rotundo \u00e9xito con la participaci\u00f3n de casi un mill\u00f3n de personas.<\/p>\n<p>Madrid y Vic\u00e1lvaro han seguido este ejemplo durante varios a\u00f1os, incorporando pr\u00e1cticas ecoamigables, como el uso de envoltorios de pl\u00e1stico reciclado para los caramelos y la creaci\u00f3n de carrozas a base de cart\u00f3n resistente en lugar de pl\u00e1stico, pintadas con colores ecol\u00f3gicos.<\/p>\n<p>Valencia tambi\u00e9n se sum\u00f3 a esta tendencia con un enfoque similar en 2019, una tem\u00e1tica que planean retomar este a\u00f1o con algunas variaciones. Su propuesta consisti\u00f3 en <strong>integrar la ecolog\u00eda y la sostenibilidad<\/strong> como elementos fundamentales en el desfile.<\/p>\n<p>Cuando veamos la\u00a0<strong>cabalgata de 2024<\/strong>, contemplaremos c\u00f3mo el medioambiente se est\u00e1 abriendo paso en nuestras ciudades, casi de manera literal. Una l\u00ednea futurista y ecologista de carrozas, junto a caramelos sin az\u00facar con envoltorios reciclados, ser\u00e1 una lecci\u00f3n para los m\u00e1s peque\u00f1os. \u00bfQu\u00e9 te parece esta propuesta? Durante los pr\u00f3ximos d\u00edas, veremos c\u00f3mo las redes se llenan de comentarios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0cabalgata de 2024 va a ser diferente a la de todos los a\u00f1os. No te preocupes, seguir\u00e1s viendo a Melchor, &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Adi\u00f3s a la Cabalgata tal y como la conoc\u00edamos: esta empresa lo cambiar\u00e1 todo en la Cabalgata de 2024\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/cabalgata-reyes\/708\/#more-708\" aria-label=\"Leer m\u00e1s sobre Adi\u00f3s a la Cabalgata tal y como la conoc\u00edamos: esta empresa lo cambiar\u00e1 todo en la Cabalgata de 2024\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":771,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=708"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/771"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}