{"id":7220,"date":"2024-06-06T16:30:31","date_gmt":"2024-06-06T14:30:31","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7220"},"modified":"2024-06-06T16:30:31","modified_gmt":"2024-06-06T14:30:31","slug":"fracaso-historico-reciclaje-espana","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/fracaso-historico-reciclaje-espana\/7220\/","title":{"rendered":"Fracaso hist\u00f3rico de Espa\u00f1a con el reciclaje: la UE advierte de lo que acabamos de hacer"},"content":{"rendered":"<p>Desde que se cre\u00f3 el primer pl\u00e1stico a mediados del siglo XIX, este material se ha convertido en la base de nuestra civilizaci\u00f3n. Ahora se ha convertido en un grave problema con consecuencias como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-islas-privadas-venta\/6721\/\">el pol\u00e9mico territorio espa\u00f1ol en el \u00c1rtico<\/a>. A esto se suma un posible caso de corrupci\u00f3n que podr\u00eda <strong>llevar a Espa\u00f1a a un fracaso hist\u00f3rico que preocupa a toda la Uni\u00f3n Europea<\/strong>.<\/p>\n<h2>Espa\u00f1a comete un grave error con el reciclaje<\/h2>\n<p>La Uni\u00f3n Europea ha invertido una gran cantidad de dinero y esfuerzo para impulsar regulaciones y normativas para reducir el uso de pl\u00e1sticos derivados del petr\u00f3leo. Estas pol\u00edticas establecen controles, penalizaciones y prohibiciones para las industrias que emplean estos materiales con el fin de que los fabricantes reutilicen los residuos o los desechen adecuadamente.<\/p>\n<p>Sin embargo, las empresas defienden su rentabilidad, lo que produce una pugna entre los organismos que luchan por reducir la huella de carbono y los directivos inescrupulosos que tratan de esquivar las regulaciones para mejorar sus beneficios. Esto ha escalado hasta el punto de poner a Espa\u00f1a en una situaci\u00f3n delicada frente a la UE, que est\u00e1 investigando una grave infracci\u00f3n.<\/p>\n<p>Seg\u00fan la organizaci\u00f3n Ecoembes, las compa\u00f1\u00edas espa\u00f1olas estaban reutilizando un 71% de los envases desechados para la producci\u00f3n de bebidas embotelladas. Sin embargo, un nuevo estudio realizado por la consultora brit\u00e1nica Eunomia, revel\u00f3 que <strong>este porcentaje en realidad no superaba el 31%<\/strong> de la reutilizaci\u00f3n en sus plantas de producci\u00f3n. Esto puede suponer un fracaso hist\u00f3rico para Espa\u00f1a.<\/p>\n<h2>Un fracaso hist\u00f3rico que debe preocuparnos<\/h2>\n<p>La organizaci\u00f3n <strong>Ecoembes<\/strong> fue creada en 1996 para gestionar el reciclaje y manejo adecuado de desechos pl\u00e1sticos. Forma parte de las regulaciones europeas que establecen que los fabricantes deben financiar el manejo de los residuos derivados de sus productos. Por esta raz\u00f3n, los fondos de esta organizaci\u00f3n provienen del capital privado.<\/p>\n<p>Ecoembes se encarga de la recolecci\u00f3n y manejo de los desechos pl\u00e1sticos y presenta informes peri\u00f3dicos sobre su desempe\u00f1o. Sin embargo, las discrepancias en los datos que ha sido revelada por Greenpeace a ra\u00edz del informe de Eunomia representa para las autoridades internacionales un fracaso hist\u00f3rico que implicar\u00e1 serias sanciones para su reparaci\u00f3n.<\/p>\n<p>Greenpeace present\u00f3 el caso ante las autoridades de la Uni\u00f3n Europea para que sea investigado y se demuestre si hubo un incumplimiento con la\u00a0Ley de Residuos\u00a0que rige en toda la regi\u00f3n. De ser as\u00ed, quedar\u00eda en evidencia la falta de transparencia en los procedimientos de Ecoembes y un <strong>fracaso hist\u00f3rico en la capacidad de Espa\u00f1a de controlar a las empresas<\/strong> para que sigan las normativas de sustentabilidad.<\/p>\n<h2>Se impone la Ley de Residuos<\/h2>\n<p>De ratificarse la infracci\u00f3n, la sanci\u00f3n establecida por la Ley de Residuos, implicar\u00eda un fuerte endurecimiento de las regulaciones para los fabricantes espa\u00f1oles de bebidas envasadas en pl\u00e1stico. Las mismas incluyen implementar inmediatamente un <strong>Sistema de Dep\u00f3sito<\/strong> que obligar\u00eda a las empresas a financiar la instalaci\u00f3n de contenedores para pl\u00e1sticos.<\/p>\n<p>Tambi\u00e9n se impondr\u00eda el uso de materiales 100% reutilizables, en lugar del 70% actual, para los envases de sus bebidas con estrictos procedimientos de control y seguimiento. Todo esto podr\u00eda implicar un fuerte impacto en los beneficios de estas compa\u00f1\u00edas, de quienes se espera que intenten bloquear la implementaci\u00f3n de sanciones empleando todos sus recursos.<\/p>\n<p>Este fracaso hist\u00f3rico refleja la necesidad de <strong>investigar tambi\u00e9n a los Ministerios y organizaciones<\/strong> encargados de controlar las pol\u00edticas corporativas de manejo de desechos, que podr\u00edan ser c\u00f3mplices de estos empresarios que protegen sus beneficios a costa del ambiente.<\/p>\n<h2>Un error que no debe repetirse<\/h2>\n<p>Este fracaso hist\u00f3rico ha demostrado la necesidad de mecanismos m\u00e1s eficientes para medir e informar datos sobre el progreso del manejo sustentable de pl\u00e1sticos, dirigidas tanto a las compa\u00f1\u00edas como a los organismos reguladores. Teniendo en cuenta que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-islas-privadas-venta\/6721\/\">en Espa\u00f1a hay islas privadas que son propiedad de poderos empresarios<\/a>, es evidente que tenemos una larga batalla que librar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que se cre\u00f3 el primer pl\u00e1stico a mediados del siglo XIX, este material se ha convertido en la base &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Fracaso hist\u00f3rico de Espa\u00f1a con el reciclaje: la UE advierte de lo que acabamos de hacer\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/fracaso-historico-reciclaje-espana\/7220\/#more-7220\" aria-label=\"Leer m\u00e1s sobre Fracaso hist\u00f3rico de Espa\u00f1a con el reciclaje: la UE advierte de lo que acabamos de hacer\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":7240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consumo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7220"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7240"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}