{"id":7355,"date":"2024-06-10T17:00:19","date_gmt":"2024-06-10T15:00:19","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7355"},"modified":"2024-06-10T17:00:19","modified_gmt":"2024-06-10T15:00:19","slug":"aislante-perfecto-con-ropa","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/aislante-perfecto-con-ropa\/7355\/","title":{"rendered":"Espa\u00f1a logra crear el aislante perfecto: 90% m\u00e1s de aislamiento y cero climatizaci\u00f3n"},"content":{"rendered":"<p>Expertos de todo el mundo siguen trabajando para reducir las emisiones en industrias que son b\u00e1sicas para satisfacer nuestras necesidades. Una de ellas es el sector de la construcci\u00f3n, donde se desarrollan interesantes innovaciones como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/ladrillos-de-fuego-ecologicos\/7191\/\">los ladrillos de fuego libre de emisiones de CO2<\/a>. En esta direcci\u00f3n apunta un nuevo fibrocemento hecho con tela que parece ser un <strong>aislante perfecto para la construcci\u00f3n.<\/strong><\/p>\n<h2>El aislante perfecto que se hace con ropa<\/h2>\n<p>Es sabido que la industria de los materiales de construcci\u00f3n es una de las principales responsables de las emisiones de CO2 que causan el calentamiento global. Desde los componentes necesarios, a los procesos de fabricaci\u00f3n, hasta su transporte y aplicaci\u00f3n, estos productos generan toneladas de gases de efecto invernadero que aumentan cada a\u00f1o.<\/p>\n<p>Sin embargo, pocos saben que <strong>otra industria altamente contaminante es la textil<\/strong>. Anualmente, esta industria produce alrededor de 90 millones de toneladas de residuos que van a parar a incineradores que producen altas cantidades de contaminaci\u00f3n. Por su parte, la construcci\u00f3n contribuye a un tercio de las emisiones de CO2, de las cuales un 7% corresponden s\u00f3lo a la fabricaci\u00f3n de cemento.<\/p>\n<p>Para contribuir a una soluci\u00f3n que permita fabricar cemento sin comprometer el medio ambiente, un equipo de investigadores de diferentes universidades de Espa\u00f1a han desarrollado un novedoso<strong> fibrocemento que emplea desechos textiles no tejidos<\/strong>. El material ha sido sometido a diferentes pruebas y ha demostrado ser un aislante perfecto que ofrece todas las propiedades del fibrocemento tradicional.<\/p>\n<h2>Una soluci\u00f3n dos por uno<\/h2>\n<p>El equipo de expertos de la <strong>UPC (Universitat Polit\u00e8cnica de Catalunya \u2013 Barcelona Tech)<\/strong> ha conseguido crear un <strong>material de construcci\u00f3n ligero, ign\u00edfugo y vers\u00e1til que funciona adem\u00e1s como un aislante perfecto para evitar la humedad y mejorar la climatizaci\u00f3n<\/strong>. Tambi\u00e9n ofrece una excelente durabilidad y resistencia, pese a ser una estructura muy ligera.<\/p>\n<p>Para lograr este nuevo fibrocemento bajo en emisiones, combinaron el cemento tradicional con desechos de la industria textil no tejidos, es decir, las fibras m\u00e1s utilizadas para la fabricaci\u00f3n de las prendas que usamos a diario. Despu\u00e9s de aplicar un tratamiento para optimizar las propiedades de la tela, se a\u00f1aden a la mezcla minerales que mejoran la resistencia del material.<\/p>\n<p>Durante las pruebas realizadas para estimar sus prestaciones, el equipo ha conseguido fabricar tejas, baldosas ligeras para pavimento y placas delgadas para fachadas entre otros. En todos los casos se comprob\u00f3 que el nuevo fibrocemento ofrece una <strong>climatizaci\u00f3n m\u00e1s eficiente<\/strong>, es altamente resistente al agua y permite un adecuado paso del aire para evitar la humedad y purificar el aire interior.<\/p>\n<h2>Un desecho que se convierte en el aislante perfecto<\/h2>\n<p>Con esta innovadora tecnolog\u00eda, los investigadores han abierto la posibilidad para crear un nuevo mercado a partir de un material que habitualmente termina incinerado o se acumula en monta\u00f1as de basura en vertederos. Ser\u00eda as\u00ed una posible<strong> fuente de beneficios econ\u00f3micos que ayude a reducir las emisiones de CO2<\/strong>, con el a\u00f1adido de ser el primer aislante perfecto para climatizaci\u00f3n eficiente.<\/p>\n<p>El equipo se encuentra en este momento estudiando las posibilidades para llevar su nuevo fibrocemento reciclado a un nivel industrial donde podr\u00eda reducir tanto las emisiones como los costes de producci\u00f3n de un material ampliamente utilizado en la construcci\u00f3n.<\/p>\n<h2>La econom\u00eda circular es posible<\/h2>\n<p>La<strong> econom\u00eda circular<\/strong> se ha erigido como el pilar de la sustentabilidad. Aprovechando los residuos de la industria textil para crear materiales m\u00e1s econ\u00f3micos y eficientes podr\u00eda ser de gran ayuda, igual que <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/aislante-construccion-arroz\/6195\/\">el aislante hecho con desechos agropecuarios<\/a> que fue desarrollado en Panam\u00e1. Sin duda ser\u00eda un gran logro con la firma de Espa\u00f1a, el cual se suma a la ya extensa lista de soluciones sustentables que hemos creado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expertos de todo el mundo siguen trabajando para reducir las emisiones en industrias que son b\u00e1sicas para satisfacer nuestras necesidades. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a logra crear el aislante perfecto: 90% m\u00e1s de aislamiento y cero climatizaci\u00f3n\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/aislante-perfecto-con-ropa\/7355\/#more-7355\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a logra crear el aislante perfecto: 90% m\u00e1s de aislamiento y cero climatizaci\u00f3n\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":7357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7355"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7357"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}